{"id":164708,"date":"2020-03-28T00:03:12","date_gmt":"2020-03-27T23:03:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=164708"},"modified":"2020-03-28T11:09:34","modified_gmt":"2020-03-28T10:09:34","slug":"leccecronache-il-lievito-e-arrivato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/03\/28\/leccecronache-il-lievito-e-arrivato\/","title":{"rendered":"LECCECRONACHE \/ IL LIEVITO? E&#8217; ARRIVATO!"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-164709\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/03\/download-4.jpg\" alt=\"\" width=\"654\" height=\"368\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/03\/download-4.jpg 654w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/03\/download-4-300x169.jpg 300w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/>di <strong>Raffaele Polo<\/strong>______<\/p>\n<p>Siamo qui, ormai \u00e8 diventato un luogo di penitenza e forzata attesa: davanti al supermercato, a fare la fila. Oggi c&#8217;\u00e8, veramente, un assetto circolare dei convenuti, hanno preso tutti il bigliettino e si guardano da dietro le mascherine.<\/p>\n<p>Dopo un po&#8217;, per\u00f2, le donne non resistono pi\u00f9 e intavolano i discorsi di prammatica, in situazioni simili a questa.\u00a0 Comincia una, bassina, con una enorme copertura facciale che, a stenti, lascia intravedere gli occhi. \u201c Quale numero \u00e8 stato chiamato?\u201d, chiede, pur sapendo benissimo che hanno appena gridato \u201cQuaranta!!!\u201d<\/p>\n<p>\u201cSignuria ce numero tieni?\u201d chiede un&#8217;anziana, vestita di nero, la mascherina bianca spicca con &#8216;effetto luce&#8217; su tutto quello scuro,<\/p>\n<p>\u201cSe non si sbrigano, qui arriva mezzogiorno. E ce cucenamu, spaghetti?\u201d interviene un&#8217;agguerrita bionda con gli occhi spiritati, solo quelli si vedono, del resto.<\/p>\n<p>\u201cC&#8217;\u00e8 maleducazione e mancanza di rispetto\u201d interviene una signora dietro di me, con la pelliccia di leopardo e le scarpe da tennis. Con tono severo, aggiunge: \u201c Del resto, siamo italiani, sempre i soliti, ce ne freghiamo degli altri, di chi sta qui fuori al freddo, ad aspettare&#8230;\u00a0 Eh, non cambieremo mai!!\u201d e la sua considerazione viene accettata con assensi dalle presenti, che partono a raffica: \u201c Si, \u00e8 sempre cos\u00ec, e poi ci lamentiamo\u201d prorompe una signora caratterizzata da una mascherina di quelle complicatissime, con bottoni e prese d&#8217;aria. \u201cNon c\u00e8 niente da fare, dobbiamo protestare!\u201d rilancia la signora in nero. E, subito, un coro invoca &#8216;Cosiminaaaa&#8217;, ovvero la cassiera, che si affaccia alla porta e chiede cosa succede. \u201c Dinne cu se sbriga!!!\u201d dicono dal coro. \u201cL&#8217;ho detto, l&#8217;ho detto, che altro debbo fare? M\u00f2 lo dico di nuovo\u201d\u00a0 e subito, dall&#8217;altoparlante, si sente un modulato e perentorio \u201cNel rispetto dell&#8217;utenza, si prega di affrettare gli acquisti!\u201d.<\/p>\n<p>Soddisfazione delle postulanti che cominciano poi ad entrare, una alla volta.\u00a0 Alla cassa, in realt\u00e0, c&#8217;\u00e8 un&#8217;anziana signora che si sta facendo spiegare come si fa il lievito di birra con la birra e la farina.\u00a0 E ha bloccato il transito&#8230;<\/p>\n<p>Si sprecano le occhiatacce verso la serafica interlocutrice, che non se ne avvede neanche. \u201cChe maleducazione!!!\u201d sbotta la pelliccia di leopardo. \u201cNon c&#8217;\u00e8 rispetto!\u201d conferma un anziano appena arrivato, ma nessuno lo prende in considerazione: \u00e8 l&#8217;unico maschio presente e non ha la mascherina&#8230;.<\/p>\n<p>\u201cIl lievito, c&#8217;\u00e8 il lievito\u201d si sente gridare dal bancone.<\/p>\n<p>E tutte si precipitano in quella direzione, come un unico corpo.<\/p>\n<p>Alla cassa resta solo l&#8217;anziana signora che non ha ancora capito come si fa il lievito di birra. Col suo carrello ricolmo, ostruisce il passaggio, ma non se ne accorge.<\/p>\n<p>Forse, \u00e8 ancora l\u00ec.______<\/p>\n<p>LA RICERCA nel nostro articolo del 24 marzo scorso<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"l4KtzNPy6u\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/03\/24\/leccecronache-il-lievito-forse-arriva-domani\/\">LECCECRONACHE \/ IL LIEVITO? FORSE ARRIVA DOMANI<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/03\/24\/leccecronache-il-lievito-forse-arriva-domani\/embed\/#?secret=l4KtzNPy6u\" data-secret=\"l4KtzNPy6u\" width=\"500\" height=\"282\" title=\"&#8220;LECCECRONACHE \/ IL LIEVITO? FORSE ARRIVA DOMANI&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/03\/28\/leccecronache-il-lievito-e-arrivato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/03\/28\/leccecronache-il-lievito-e-arrivato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo______ Siamo qui, ormai \u00e8 diventato un luogo di penitenza e forzata attesa: davanti al supermercato, a fare la fila. Oggi c&#8217;\u00e8, veramente, un assetto circolare dei convenuti, hanno preso tutti il bigliettino e si guardano da dietro le mascherine. Dopo un po&#8217;, per\u00f2, le donne non resistono pi\u00f9 e intavolano i discorsi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":164709,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/164708"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=164708"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/164708\/revisions"}],"predecessor-version":[{"id":164710,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/164708\/revisions\/164710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/164709"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=164708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=164708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=164708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}