{"id":165145,"date":"2020-04-06T18:52:33","date_gmt":"2020-04-06T16:52:33","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=165145"},"modified":"2020-04-06T19:25:50","modified_gmt":"2020-04-06T17:25:50","slug":"emergenza-covid-19-aggiornamento-dalla-sede-della-protezione-civile-e-notizie-importanti-della-giornata","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/06\/emergenza-covid-19-aggiornamento-dalla-sede-della-protezione-civile-e-notizie-importanti-della-giornata\/","title":{"rendered":"EMERGENZA COVID-19, AGGIORNAMENTO DALLA PROTEZIONE CIVILE E ALTRE NOTIZIE IMPORTANTI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-165149\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/IMG_20200406_185014.jpg\" alt=\"\" width=\"1020\" height=\"562\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/IMG_20200406_185014.jpg 1020w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/IMG_20200406_185014-300x165.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/IMG_20200406_185014-768x423.jpg 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/><strong>Mav<\/strong>_______<\/p>\n<p>Oggi in Italia 636 decessi nelle ultime 24 ore. La nota positiva resta la diminuzione dei contagi e il calo dei ricoveri in terapia intensiva. In linea di massima sembrerebbe di essere in una lunga curva del picco. Le linee di contenimento attuate dovrebbero consentire a breve una considerevole discesa.<\/p>\n<p>&nbsp;<\/p>\n<p>Questi i dati ufficiali che ci giungono dalla sede della protezione civile.<\/p>\n<div id=\"column-2\" class=\"portlet-column portlet-column-first span9\">\n<div id=\"p_p_id_101_INSTANCE_default_\" class=\"portlet-boundary portlet-boundary_101_ portlet-static portlet-static-end portlet-borderless portlet-asset-publisher \">\n<div class=\"portlet-borderless-container\">\n<div class=\"portlet-body\">\n<div class=\"asset-full-content no-title\">\n<div id=\"_101_INSTANCE_default_1244298\" class=\"asset-content\">\n<div class=\"journal-content-article\">\n<div class=\"main-content-text\">\n<div class=\"top-content leg-content\">\n<div class=\"top-content-back\">\n<div class=\"top-content-body\">\n<div>\n<p>Presso la sede del Dipartimento della Protezione Civile proseguono i lavori del Comitato Operativo al fine di assicurare il coordinamento degli interventi delle componenti e delle strutture operative del Servizio Nazionale della protezione civile.\u00a0\u00a0Nell\u2019ambito del monitoraggio sanitario relativo alla diffusione del Coronavirus sul territorio nazionale, al momento 93.187 persone risultano positive al virus. Ad oggi, in Italia sono stati 132.547 i casi totali.<\/p>\n<p>Nel dettaglio: i casi attualmente positivi sono 28.469 in Lombardia, 13.051 in Emilia-Romagna, 10.545 in Piemonte, 9.722 in Veneto, 5.301 in Toscana, 3.706 nelle Marche, 3.300 nel Lazio, 3.117 in Liguria, 2.698 in Campania, 2.115 in Puglia, 1.815 in Sicilia, 1.838 nella Provincia autonoma di Trento, 1.396 in Friuli Venezia Giulia, 1.425 in Abruzzo, 1.260 nella Provincia autonoma di Bolzano, 872 in Umbria, 819 in Sardegna, 722 in Calabria, 567 in Valle d\u2019Aosta, 262 in Basilicata e 187 in Molise.<\/p>\n<\/div>\n<p>Sono 22.837 le persone guarite. I deceduti sono 16.523, ma questo numero potr\u00e0 essere confermato solo dopo che l\u2019Istituto Superiore di Sanit\u00e0 avr\u00e0 stabilito la causa effettiva del decesso.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"asset-metadata\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Tornano a salire sopra i cento casi le nuove positivit\u00e0 di contagio da coronavirus in Puglia, oggi per la precisione sono 127 su un totale di tamponi refertati pari a 1.979. I decessi registrati oggi, invece, sono 13: 6 in provincia di Bari, 4 in provincia di Foggia, 2 nella Bat, uno in provincia di Taranto. Complessivamente le vittime in Puglia sono 195. Oggi il maggior numero di casi sono stati rilevati in provincia di Foggia, 41, a seguire Bat, 39. Dall&#8217;inizio dell&#8217;emergenza sono stati effettuati 22.059 test, i positivi sono 2.444, le persone ricoverate sono 722, quelle guarite 134.<br \/>\nIl maggior numero di contagiati \u00e8 in provincia di Bari, 807, segue quella di Foggia, 605.<\/p>\n<p>Infine un aggiornamento dalla casa di riposo per anziani di Soleto, scenario infernale di contagio e disagio.<\/p>\n<p>Sono saliti a 9 gli anziani, positivi al Coronavirus, morti dal 21 marzo nella Rsa La Fontanella di Soleto che fino a pochi giorni fa ospitava 90 persone, ora scese a 33. Di queste 30 sono positive al Covid-19.<br \/>\nGli ospiti negativi sono stati collocati a distanza in stanze singole. Tutti gli altri sono stati trasferiti in questi giorni in altre strutture di lungodegenza, anche private. L&#8217;ultimo decesso si \u00e8 verificato ieri. Complessivamente sono 88 i casi di contagio registrati tra pazienti e sanitari. I dati sono forniti dall&#8217;Asl di Lecce, che da alcuni giorni gestisce la Rsa.<br \/>\nSu quanto accaduto la Procura di Lecce ha aperto un&#8217;inchiesta delegata al Nas. Il sospetto \u00e8 che alcuni degli anziani deceduti, tutti affetti da gravi patologie invalidanti, possano essere morti in seguito all&#8217;allontanamento del personale dipendente dopo i primi casi di positivit\u00e0. All&#8217;attenzione degli investigatori quanto accaduto dal 21 al 26 marzo, prima che l&#8217;Asl subentrasse nella gestione della struttura.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/06\/emergenza-covid-19-aggiornamento-dalla-sede-della-protezione-civile-e-notizie-importanti-della-giornata\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/06\/emergenza-covid-19-aggiornamento-dalla-sede-della-protezione-civile-e-notizie-importanti-della-giornata\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Mav_______ Oggi in Italia 636 decessi nelle ultime 24 ore. La nota positiva resta la diminuzione dei contagi e il calo dei ricoveri in terapia intensiva. In linea di massima sembrerebbe di essere in una lunga curva del picco. Le linee di contenimento attuate dovrebbero consentire a breve una considerevole discesa. &nbsp; Questi i dati [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":165149,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/165145"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=165145"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/165145\/revisions"}],"predecessor-version":[{"id":165156,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/165145\/revisions\/165156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/165149"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=165145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=165145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=165145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}