{"id":16526,"date":"2013-05-21T06:40:47","date_gmt":"2013-05-21T06:40:47","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=16526"},"modified":"2013-05-21T06:40:47","modified_gmt":"2013-05-21T06:40:47","slug":"arrestata-dalle-volanti-dopo-un-controllo-in-albergo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/21\/arrestata-dalle-volanti-dopo-un-controllo-in-albergo\/","title":{"rendered":"ARRESTATA DALLE VOLANTI DOPO UN CONTROLLO IN ALBERGO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/18\/161-anniversario-della-fondazione-della-polizia-di-stato\/polizia1\/\" rel=\"attachment wp-att-16440\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/POLIZIA1-300x191.jpg\" alt=\"\" width=\"300\" height=\"191\" class=\"alignleft size-medium wp-image-16440\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/POLIZIA1-300x191.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/POLIZIA1.jpg 794w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Personale dell\u2019Ufficio Volanti effettuando dei controlli sulle persone alloggiate negli alberghi, traeva in arresto tale Sonia GURGEVIC nata a Treviso il 22.4.73 e residente a Roma, alloggiata presso un Hotel della periferia di Lecce, a carico della quale pendeva un ordine di carcerazione di 2 anni e 4 mesi di reclusione pena divenuta definitiva a marzo del 2013 emessa dal tribunale di Matera.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/21\/arrestata-dalle-volanti-dopo-un-controllo-in-albergo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/21\/arrestata-dalle-volanti-dopo-un-controllo-in-albergo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Personale dell\u2019Ufficio Volanti effettuando dei controlli sulle persone alloggiate negli alberghi, traeva in arresto tale Sonia GURGEVIC nata a Treviso il 22.4.73 e residente a Roma, alloggiata presso un Hotel della periferia di Lecce, a carico della quale pendeva un ordine di carcerazione di 2 anni e 4 mesi di reclusione pena divenuta definitiva a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16526"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=16526"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16526\/revisions"}],"predecessor-version":[{"id":16528,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16526\/revisions\/16528"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=16526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=16526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=16526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}