{"id":165470,"date":"2020-04-11T19:11:47","date_gmt":"2020-04-11T17:11:47","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=165470"},"modified":"2020-04-11T19:43:13","modified_gmt":"2020-04-11T17:43:13","slug":"tutte-pazze-per-giuseppi-photogallery","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/11\/tutte-pazze-per-giuseppi-photogallery\/","title":{"rendered":"TUTTE PAZZE PER GIUSEPPI &#8211; photogallery"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-165476\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/MANZO.jpg\" alt=\"\" width=\"667\" height=\"960\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/MANZO.jpg 667w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/MANZO-208x300.jpg 208w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>(g.p.)______Beh, tutto questo \u00e8 divertente. Esiste un gruppo Facebook che si chiama &#8220;Giuseppe Conte Sex Symbol&#8221;, non sappiamo dire quanto spontaneo, ci fosse anche qua la longa manus di Rocco Casalino? Bah, per quanto in ogni caso non si parli, se non indirettamente, di politica, un&#8217;operazione di costruzione del consenso in ogni caso \u00e8.<\/p>\n<p>E comunque &#8211; certo grazie ai discorsi in diretta e alle innumerevoli &#8216;comparsate&#8217; televisive delle ultime settimane del presidente del Consiglio- \u00e8 arrivato a 65.000 &#8220;cucciole&#8221;, cos\u00ec si chiamano fra di loro.<\/p>\n<p>L&#8217; evasione in rosa, fotoromanzo a puntate vecchio stile, fra le tante suggestioni multimediali presenti nei post del gruppo, compresa:<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-165475\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/foto.jpg\" alt=\"\" width=\"843\" height=\"959\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/foto.jpg 843w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/foto-264x300.jpg 264w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/foto-768x874.jpg 768w\" sizes=\"(max-width: 843px) 100vw, 843px\" \/><\/p>\n<p>Chiss\u00e0 quanto sar\u00e0 contento lui!<\/p>\n<p>Forse con tracce di ansia da prestazione&#8230;Ah, saperlo&#8230;<\/p>\n<p>Magari la sua compagna, la fidanzata ufficiale e, per cos\u00ec dire, legittima, un po&#8217; meno&#8230;Eccoli in una rara immagine in cui appaiono insieme in pubblico, che abbiamo recuperato a parte, cos\u00ec le &#8220;cucciole&#8221; rosicano un po&#8217;&#8230;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-165471\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/olivia-paladino.jpg\" alt=\"\" width=\"300\" height=\"232\" \/><\/p>\n<p>Di sicuro rosica e tanto Alberto Angela, che si \u00e8 visto soppiantare quale &#8220;sex symbol&#8221;, nell&#8217;immaginario sentimental-erotico femminile delle donne italiane, dopo che aveva, a fatica, soppiantato a sua volta il mitico Rocco Siffredi.<\/p>\n<p>Sic transit gloria mundi.<\/p>\n<p>&nbsp;<\/p>\n<p>Nelle ultime ore, in ogni caso le &#8220;cucciole&#8221; hanno dato il meglio di s\u00e9.<\/p>\n<p>Non \u00e8 divertente, \u00e8 divertentissimo, seguirle, in ogni caso.<\/p>\n<p>Ecco come una di loro ha estrapolato e riadattato una frase della &#8216;conferenza stampa&#8217; di ieri sera del loro &#8220;cucciolone&#8221;:<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-165472\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/fu.jpg\" alt=\"\" width=\"960\" height=\"960\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/fu.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/fu-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/fu-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/fu-768x768.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/fu-60x60.jpg 60w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Ed ecco come un&#8217;altra &#8211; non c&#8217;\u00e8 bisogno di spiegare nulla, per fortuna &#8211; ha politicamente seguito la diretta televisiva a reti unificate, con straordinaria partecipazione emotiva:<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-165473\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/gcsexy.jpg\" alt=\"\" width=\"720\" height=\"534\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/gcsexy.jpg 720w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/gcsexy-300x223.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n<p>A quando, a grande richiesta, un canale appositamente dedicato su Pornhub a luci rosa, mica rosse?<\/p>\n<p>Una cucciola &#8211; sempre ieri sera il lampo di genio- ce l&#8217;ha gi\u00e0 in testa, con tanto di tag di riferimento e titoli appropriati&#8230;Una vera &#8211;\u00a0 come dire? &#8211; conoscitrice della materia, insomma:<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-165474\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/pornhub.jpg\" alt=\"\" width=\"720\" height=\"720\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/pornhub.jpg 720w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/pornhub-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/pornhub-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/pornhub-60x60.jpg 60w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/11\/tutte-pazze-per-giuseppi-photogallery\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/11\/tutte-pazze-per-giuseppi-photogallery\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.)______Beh, tutto questo \u00e8 divertente. Esiste un gruppo Facebook che si chiama &#8220;Giuseppe Conte Sex Symbol&#8221;, non sappiamo dire quanto spontaneo, ci fosse anche qua la longa manus di Rocco Casalino? Bah, per quanto in ogni caso non si parli, se non indirettamente, di politica, un&#8217;operazione di costruzione del consenso in ogni caso \u00e8. E [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":165476,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/165470"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=165470"}],"version-history":[{"count":9,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/165470\/revisions"}],"predecessor-version":[{"id":165491,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/165470\/revisions\/165491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/165476"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=165470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=165470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=165470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}