{"id":16550,"date":"2013-05-21T07:09:31","date_gmt":"2013-05-21T07:09:31","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=16550"},"modified":"2013-05-21T07:09:31","modified_gmt":"2013-05-21T07:09:31","slug":"tra-immagini-poesie-e-musica-gli-scatti-e-i-versi-di-sharklover-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/21\/tra-immagini-poesie-e-musica-gli-scatti-e-i-versi-di-sharklover-2\/","title":{"rendered":"Tra immagini poesie e musica. Gli scatti e i versi di Sharklover."},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-16550 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/21\/tra-immagini-poesie-e-musica-gli-scatti-e-i-versi-di-sharklover-2\/andreasharklover\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/andreasharklover-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/21\/tra-immagini-poesie-e-musica-gli-scatti-e-i-versi-di-sharklover-2\/a_sharklover-1\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/a_sharklover-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/21\/tra-immagini-poesie-e-musica-gli-scatti-e-i-versi-di-sharklover-2\/a_sharklover2\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/a_sharklover2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/21\/tra-immagini-poesie-e-musica-gli-scatti-e-i-versi-di-sharklover-2\/a_sharklover3-1\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/a_sharklover3-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Dal 26 al 31\u00a0 maggio nella sede associativa <em>Le Ali di Pandora<\/em> la mostra fotografica di <strong>Andrea Sharklover.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Titolo della personale di fotografia: <\/strong><strong>Il Blu diventi luce, la luce diventi mare, il mare diventi suono. <em>Immagini, poesia, musica<\/em><\/strong><strong> <\/strong><\/p>\n<p><strong>artista:\u00a0 Andrea Sharklover<\/strong><\/p>\n<p><strong>data: 26-31 maggio 2013 <\/strong><\/p>\n<p><strong>vernissage: 26 maggio ore 19:30<\/strong><\/p>\n<p><strong>orario di apertura, tutti i giorni: 9-13 e 17-21<\/strong><\/p>\n<p><strong>luogo: Centro Polifunzionale \u2013 sede associativa Le Ali di Pandora &#8211;\u00a0 Lecce<\/strong><\/p>\n<p><strong>presentazione: Lucy Ghionna<\/strong><\/p>\n<p><strong>catalogo: Il Raggio Verde edizioni<\/strong><\/p>\n<p><strong>Organizzazione: Ass. Le Ali di Pandora e Il Raggio Verde eventi d\u2019arte <\/strong><\/p>\n<p><strong>Patrocini: Comune di Lecce, Lecce Capitale Europea della Cultura 2019, Provincia di Lecce<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Abstract dell\u2019evento: <em>Nel blu dell\u2019immagine che si fa parole e suono. Dagli scatti fotografici che ritraggono i mari del Sud ai luoghi dell\u2019anima che attraversa il suono e il verso in un continuum di sensazioni dove protagonisti sono la luce e il mare\u2026 per riscoprire la bellezza dell\u2019arte<\/em><\/strong><\/p>\n<p><strong>\u201cIl Blu diventi luce, la luce diventi mare, il mare diventi suono. <em>Immagini, poesia, musica\u201d <\/em><\/strong>\u00e8 il titolo dell\u2019evento organizzato dall\u2019associazione Le Ali di Pandora e la casa editrice Il Raggio Verde srl, domenica 26 maggio, ore 19,30, presso la sede dell\u2019associazione sita in Via Pistoia, 9 (Centro Polifunzionale).<\/p>\n<p>Le immagini saranno quelle della mostra fotografica di Andrea Sharklover autore del libro di foto e versi \u201c<strong><em>In cammino verso la bellezza<\/em><\/strong>\u201d, edizioni Il Raggio Verde. Inaugura la mostra Lucy Ghionna (Docente dell\u2019Accademia di Belle Arti di Lecce) che scrive: \u201cQuesto bel giro del mondo dell\u2019artista Andrea Sharklover ci fa sognare. Le sue fotografie ritraggono la dolcezza, la poesia ma anche l\u2019irruenza della natura. Lui come un reporter, documenta le sue avventure in modo sapiente ed elegante trasferendo la sua passione all\u2019osservatore che si ritrova a viaggiare immediatamente. Il mare, il cielo e i grandi spazi, sono i temi trattati nelle sue opere spesso popolate da animali e soprattutto dagli squali che probabilmente sono la sua passione. Questi animali cos\u00ec forti ed aggressivi\u00a0 sfidano la vita in ogni momento del loro incontro. La sua arte \u00e8 un\u2019arte fatta per tutti, semplice da comprendere in nome di una socialit\u00e0 dell\u2019arte. Come un pittore en plein air, l\u2019artista usa la macchina fotografica con spontaneit\u00e0 costruendo una nuova iconografia attraverso l\u2019esperienza diretta con la natura e la \u201cscoperta \u201c della luce. I suoi paesaggi ritraggono vari momenti della giornata soffermandosi nello studiare la luce nella sua intensit\u00e0. Secondo Apollinaire \u201di grandi poeti e i grandi artisti hanno la missione sociale di rinnovare senza posa le sembianze che riveste la natura agli occhi degli uomini\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Il libro <strong><em>In cammino verso la bellezza<\/em><\/strong>, edizioni <strong>Il Raggio Verde<\/strong>. Fotogrammi e versi, felicemente accostati in continuo rimando fra parole e immagini, per costituire un corpo unico in un libro che diventa pretesto per parlare di bellezza: la bellezza dei paesaggi meravigliosi, catturati tra gli angoli pi\u00f9 disparati del nostro pianeta, e quella dei luoghi dell\u2019anima dove sedimentano i pensieri pi\u00f9 autentici, dove la parola diventa paesaggio interiore, riflessione sul senso della vita, quasi racconto di sentimenti e passioni che hanno la potenza delle onde che si infrangono sugli scogli dei mari del mondo. Un itinerario che parte dal Sud del Bel Paese per giungere all\u2019estremo Sud del mondo, doppiando il Capo di Buona Speranza nel Sud Africa, come gli antichi navigatori, e poi ancora viaggiare, riprendere le rotte del mare\u2026.inseguendo le onde dal Porto di Simon\u2019s Town, Sud Africa, a Cape Point, passando per Los Abrigos, Tenerife Sud, nelle splendide isole Canarie, per poi lasciarsi incantare dalle acque cristalline della caleta, costa Adeje, Tenerife Sud, e ritrovare i propri passi sulla sabbia di cayo Santa Maria, Sancti Sp\u00edritus, nella mitica Cuba\u2026 Nato sotto il segno del leone, <strong>Andrea Sharklover<\/strong> ama definirsi uno spirito in continua ricerca, dedica gran parte del suo tempo a studiare materie umanistiche e scientifiche. Il mare e gli squali, sue grandi passioni, gli fanno incontrare, nel 2006, il professore Alessandro De Maddalena, e con lui approfondisce le sue conoscenze in materia di squali, partecipando a svariati corsi sulla biologia degli stessi.<\/p>\n<p>I suoni saranno quelli del\u00a0 Gruppo <strong>\u201c<em>La chiave di Ecate<\/em>\u201d<\/strong> (a partire dalle ore 20.00) che presenter\u00e0 la performance poetico-visiva <strong>\u201cIl Blu diventi luce, la luce diventi mare, il mare diventi suono\u201d<\/strong> che si avvarr\u00e0, scenograficamente, dello straordinario video di <strong>Massimiliano Manier<\/strong>i dal titolo <em>\u201cPlinck\u201d<\/em>. Il gruppo <em>\u201cLa chiave di Ecate\u201d <\/em>\u00e8 composto da quattro elementi, alla tastiera Stefano Caputo, alla voce Grazia Riccardo, al violino Valentina Marra e al flauto traverso Flavio Mele. La musiche composte dal gruppo posseggono sonorit\u00e0 profonde ed intense, che vanno a lambire i confini dell\u2019anima pizzicando le corde pi\u00f9 intime e nascoste della mente e del cuore qui a servizio della poesia, difatti la performance trae spunto dal libro di Andrea Sharklover \u201cIn Cammino verso la bellezza\u201d Il Raggio Verde ed. Il libro di Sharklover \u00e8 un errare poetico e contemplativo che parte dal Salento e viaggia tra il Sud Africa e Cuba. Un\u2019occasione per avvicinare luoghi lontani che Andrea, amante degli squali, fissa nel suo obiettivo. Un alternarsi di immagini e parole di Sharklover \u00e8 un errare poetico e contemplativo che parte dal Salento e viaggia tra il Sud Africa e Cuba. Un\u2019occasione per avvicinare luoghi lontani che Andrea, amante degli squali, fissa nel suo obiettivo. Un alternarsi tra immagini e parole dove non tutto quel che c&#8217;\u00e8 pu\u00f2 essere detto; sentimenti, emozioni e confronti in un universo costruito attraverso le fotografie e le parole, in una trasposizione soggettiva colma di istanti insostituibili dove pienezza, allegria, delusione, drammaticit\u00e0 e abbandono sono raccontati con semplicit\u00e0 in una fusione mistica con il mare e le sue creature. Tra le immagini e la parola c&#8217;\u00e8 la musica che sembra essere il naturale nesso conciliatore. <strong>\u201cLa chiave di Ecate\u201d<\/strong> apre le porte e compone la musica per la poesia di Andrea e riesce a toccare, attraverso la composizione e la tensione vocale, alle sonorit\u00e0 profonde ed intense, le corde pi\u00f9 intime e nascoste della mente e del cuore andando a lambire i confini dell\u2019anima.<\/p>\n<p>La proiezione del video di<strong> Massimiliano Manieri:<\/strong> \u201cPlink (\u2026l\u2019uomo caduto in cattive acque)\u201d contemporaneamente alla performance, \u00e8 una voluta asimmetria che fa dell&#8217;uomo un mistero permanente e impenetrabile. Scrive Luciano Pagano: \u00e8 un uomo caduto dal cielo che viene trafitto da una lancia conficcata nel terreno e con la punta verso il cielo. (&#8230;) Chi \u00e8 e perch\u00e9 \u00e8 caduto sulla terra? \u00c8 venuto per farsi uccidere all\u2019istante? Il pensiero \u00e8 naturale, venire al mondo per farsi trafiggere all\u2019istante, cadere da una realt\u00e0 ovattata e celeste quale pu\u00f2 essere quella dei nove mesi in cui siamo nel ventre materno, vestiti da sub, coccolati, per poi essere proiettati nel mondo ancora con la muta e trafitti.<\/p>\n<p>L&#8217;evento sar\u00e0 un\u2019occasione per dare voce alla poesia con il canto, un&#8217;opportunit\u00e0 per portare l&#8217;arte in periferia, un motivo per animare e vivere un quartiere della citt\u00e0 considerato degradato nella convinzione che attraverso i linguaggi trasversali dell&#8217;arte in un connubio tra musica, arte e visioni si possa creare una naturale aggregazione costruttiva. Nel solco di questo intento si indirizza la collaborazione tra la casa editrice <em>Il Raggio Verde<\/em> e l\u2019associazione socio-artistica-culturale <em>Le Ali di Pandora<\/em> in una sinergia mirata alla tutela e valorizzazione dell\u2019ambiente e della persona attraverso attivit\u00e0 culturali dove emerga la capacit\u00e0 di animare e creare attrattive in spazi alternativi portando il centro nella periferia, immaginando una citt\u00e0 all&#8217;altezza delle sue bellezze culturali e del suo patrimonio di civilt\u00e0.<\/p>\n<p><strong>La manifestazione \u00e8 patrocinata da Comune e Provincia di Lecce e rientra negli eventi di Lecce Capitale Europea della Cultura 2019. Ingresso libero. <\/strong><\/p>\n<p>Si ringraziano per la realizzazione dell\u2019evento presso l\u2019associazione Le Ali di Pandora: Pasta d\u2019elite\u00a0 Via Bari 2, Lecce Alessio Gubello Executive Personal Chef e Owner presso Pasta D\u2019elite; Scuola di cucina il gusto del tacco di Anna Maria Chirone Arn\u00f2 (via Lupiae n.29\u00a0 73100 Lecce); Cantine Amastuola- Massafra (Taranto) bar Kolbe\u00a0 Lecce; Villa Conca Marco Vanze -Lecce. La mostra sar\u00e0 visitabile tutti i giorni fino al 31 maggio 2013.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/21\/tra-immagini-poesie-e-musica-gli-scatti-e-i-versi-di-sharklover-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/21\/tra-immagini-poesie-e-musica-gli-scatti-e-i-versi-di-sharklover-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Dal 26 al 31\u00a0 maggio nella sede associativa Le Ali di Pandora la mostra fotografica di Andrea Sharklover. &nbsp; Titolo della personale di fotografia: Il Blu diventi luce, la luce diventi mare, il mare diventi suono. Immagini, poesia, musica artista:\u00a0 Andrea Sharklover data: 26-31 maggio 2013 vernissage: 26 maggio ore 19:30 orario di apertura, tutti [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16550"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=16550"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16550\/revisions"}],"predecessor-version":[{"id":16557,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16550\/revisions\/16557"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=16550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=16550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=16550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}