{"id":165549,"date":"2020-04-13T18:47:00","date_gmt":"2020-04-13T16:47:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=165549"},"modified":"2020-04-13T19:42:04","modified_gmt":"2020-04-13T17:42:04","slug":"i-dati-di-oggi-in-italia-e-in-puglia-criticita-a-brindisi-in-una-casa-di-riposo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/13\/i-dati-di-oggi-in-italia-e-in-puglia-criticita-a-brindisi-in-una-casa-di-riposo\/","title":{"rendered":"EMERGENZA SANITARIA: I DATI DI OGGI IN ITALIA E IN PUGLIA. CRITICIT\u00c0 A BRINDISI IN UNA CASA DI RIPOSO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-165012\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/imm.jpg\" alt=\"\" width=\"512\" height=\"330\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/imm.jpg 512w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/imm-300x193.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>Mav______I decessi sono nuovamente aumentati rispetto a ieri: 566 in 24 ore.<\/p>\n<p>Crescono nuovamente anche i ricoverati con sintomi, oggi sono 176 in pi\u00f9. Sostanzialmente stabili, pi\u00f9 o meno, gli altri indicatori, come quello dei ricoverati in terapia intensiva, ancora in calo.<\/p>\n<p>Il virus in generale rallenta ovunque ma senza lasciarci tranquilli. Focolai importanti rimangono allarmanti. In Puglia, a Brindisi, una intera casa di riposo, ospiti e operatori. In dettaglio nell&#8217;articolo.<\/p>\n<p>Intanto vediamo i dati ufficiali della protezione civile.<\/p>\n<p>Nell\u2019ambito del monitoraggio sanitario relativo alla diffusione del Coronavirus sul territorio nazionale, al momento 103.616 persone risultano positive al virus. Ad oggi, in Italia sono stati 159.516 i casi totali.<\/p>\n<div class=\"journal-content-article\">\n<div class=\"main-content-text\">\n<div class=\"top-content leg-content\">\n<div class=\"top-content-back\">\n<div class=\"top-content-body\">\n<p>Nel dettaglio: i casi attualmente positivi sono 31.935 in Lombardia, 13.818 in Emilia-Romagna, 12.765 in Piemonte, 10.766 in Veneto, 6.257 in Toscana, 3.365 in Liguria, 3.080 nelle Marche, 3.920 nel Lazio, \u00a03.062 in Campania, 2.080 nella Provincia autonoma di Trento, 2.512 in Puglia, 1.307 in Friuli Venezia Giulia, \u00a02.050 in Sicilia, 1.778 in Abruzzo, 1.537 nella Provincia autonoma di Bolzano, 625 in Umbria, 914 in Sardegna, 791 in Calabria, 582 in Valle d\u2019Aosta, 270 in Basilicata e 202 in Molise.<\/p>\n<p>Sono 35.435 le persone guarite. I deceduti sono 20.465.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Oggi su 949 tamponi effettuati in Puglia ne sono risultati positivi 76. Oltre la met\u00e0 dei nuovi casi di infezione, 41 per la precisione, sono stati rilevati in provincia di Bari. Sono sette, invece, i decessi: uno in provincia di Bari, due in provincia di Foggia, uno in provincia di Brindisi, uno nella Bat, uno in provincia di Lecce e uno nella provincia di Taranto. Complessivamente, i pazienti morti in Puglia sono 267, quelli guariti 286. Cala la pressione negli ospedali, le persone ricoverate sono 671, in continua riduzione da ormai una settimana; aumentano invece i pugliesi in isolamento domiciliare, 1.183. Dall&#8217;inizio dell&#8217;emergenza sono stati effettuati 31.922 test, 3.065 le positivit\u00e0 riscontrate.<\/p>\n<p>&nbsp;<\/p>\n<p>Registriamo inoltre questo focolaio di difficolt\u00e0 nella citt\u00e0 di Brindisi.<\/p>\n<p>Un numero di 102 casi positivi al coronavirus, quasi tutti asintomatici, \u00e8 stato registrato all&#8217;interno di una residenza sanitaria per anziani di Brindisi, &#8220;Il Focolare&#8221;. Si tratta di 59 ospiti della struttura e 43 operatori. Le persone contagiate, che non presentano particolari problemi, sono rimasti\u00a0 all&#8217;interno della struttura, dove vengono assistite con tutte le precauzioni del caso. Nel caso dovessero peggiorare, \u00e8 pronto un piano di evacuazione per il ricovero.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/13\/i-dati-di-oggi-in-italia-e-in-puglia-criticita-a-brindisi-in-una-casa-di-riposo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/13\/i-dati-di-oggi-in-italia-e-in-puglia-criticita-a-brindisi-in-una-casa-di-riposo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Mav______I decessi sono nuovamente aumentati rispetto a ieri: 566 in 24 ore. Crescono nuovamente anche i ricoverati con sintomi, oggi sono 176 in pi\u00f9. Sostanzialmente stabili, pi\u00f9 o meno, gli altri indicatori, come quello dei ricoverati in terapia intensiva, ancora in calo. Il virus in generale rallenta ovunque ma senza lasciarci tranquilli. Focolai importanti rimangono [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":165554,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/165549"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=165549"}],"version-history":[{"count":11,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/165549\/revisions"}],"predecessor-version":[{"id":165561,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/165549\/revisions\/165561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/165554"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=165549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=165549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=165549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}