{"id":166020,"date":"2020-04-25T00:02:19","date_gmt":"2020-04-24T22:02:19","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=166020"},"modified":"2020-04-25T09:22:30","modified_gmt":"2020-04-25T07:22:30","slug":"lappello-di-mattarella-allunita-degli-italiani","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/25\/lappello-di-mattarella-allunita-degli-italiani\/","title":{"rendered":"L&#8217;APPELLO DI MATTARELLA ALL&#8217;UNITA&#8217; DEGLI ITALIANI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-166021 size-medium\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/37637-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/37637-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/04\/37637.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>(g.p.)______Appello all&#8217;unit\u00e0 di tutti gli Italiani, nel giorno della Festa della Liberazione, nel messaggio di oggi del Presidente della Repubblica Sergio Mattarella, occasione &#8220;per\u00a0ribadire i valori di libert\u00e0, giustizia e coesione sociale, sentendoci uniti intorno al Tricolore&#8221;.<\/p>\n<p>Questo perch\u00e9\u00a0 <em>&#8220;nella nostra democrazia la dialettica e il contrasto delle opinioni non hanno mai, nei decenni, incrinato l\u2019esigenza di unit\u00e0 del popolo italiano, divenuta essa stessa prerogativa della nostra identit\u00e0. E dunque avvertiamo la consapevolezza di un comune destino come una riserva etica, di straordinario valore civile e istituzionale. L\u2019abbiamo vista manifestarsi, nel sentirsi responsabili verso la propria comunit\u00e0, ogni volta che eventi dolorosi hanno messo alla prova la capacit\u00e0 e la volont\u00e0 di ripresa dei nostri territori<\/em>&#8220;.<\/p>\n<p>Quindi\u00a0<em>&#8220;la nostra peculiarit\u00e0 nel saper superare le avversit\u00e0 deve accompagnarci anche oggi, nella dura prova di una malattia che ha spezzato tante vite. Per dedicarci al recupero di una piena sicurezza per la salute e a una azione di rilancio e di rinnovata capacit\u00e0 di progettazione economica e sociale. A questa impresa siamo chiamati tutti, istituzioni e cittadini, forze politiche, forze sociali ed economiche, professionisti, intellettuali, operatori di ogni settore&#8221;.<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/25\/lappello-di-mattarella-allunita-degli-italiani\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/04\/25\/lappello-di-mattarella-allunita-degli-italiani\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.)______Appello all&#8217;unit\u00e0 di tutti gli Italiani, nel giorno della Festa della Liberazione, nel messaggio di oggi del Presidente della Repubblica Sergio Mattarella, occasione &#8220;per\u00a0ribadire i valori di libert\u00e0, giustizia e coesione sociale, sentendoci uniti intorno al Tricolore&#8221;. Questo perch\u00e9\u00a0 &#8220;nella nostra democrazia la dialettica e il contrasto delle opinioni non hanno mai, nei decenni, incrinato [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":166021,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/166020"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=166020"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/166020\/revisions"}],"predecessor-version":[{"id":166022,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/166020\/revisions\/166022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/166021"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=166020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=166020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=166020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}