{"id":16737,"date":"2013-05-24T16:10:14","date_gmt":"2013-05-24T16:10:14","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=16737"},"modified":"2013-05-24T16:10:14","modified_gmt":"2013-05-24T16:10:14","slug":"panorama-da-dietro-le-sbarre","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/24\/panorama-da-dietro-le-sbarre\/","title":{"rendered":"PANORAMA&#8230;DA DIETRO LE SBARRE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/24\/panorama-da-dietro-le-sbarre\/francesca-dellera\/\" rel=\"attachment wp-att-16739\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/15-Francesca-Dellera-in-copertina-sulla-rivista-Panorama--196x300.jpg\" alt=\"\" width=\"196\" height=\"300\" class=\"alignleft size-medium wp-image-16739\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/15-Francesca-Dellera-in-copertina-sulla-rivista-Panorama--196x300.jpg 196w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/15-Francesca-Dellera-in-copertina-sulla-rivista-Panorama-.jpg 647w\" sizes=\"(max-width: 196px) 100vw, 196px\" \/><\/a>Colpita ed affondata Panorama nella battaglia navale giocata con(tro) la magistratura. La condanna ad otto mesi di reclusione per il direttore Mul\u00e8 ed un anno per il giornalista Marcenaro, sembra essere un colpo di grosso calibro assestato ai &#8220;filo-berlusconiani&#8221; della carta stampata. Certo,l&#8217;ANM sosterr\u00e0 con sdegno che nessuna correlazione esiste tra la condanna inflitta per aver definito &#8220;politicizzata&#8221; la Procura di Palermo ed il fatto che Panorama sia berlusconiana di ferro. Tesi opinabilissima,visto che di valutazioni pi\u00fa o meno azzardate ed accuse e contraccuse sulla,ed alla, magistratura ne leggiamo e sentiamo ogni giorno tantissime. Senza,almeno per quanto di mia conoscenza,conseguenze penali di sorta per altri personaggi.<br \/>\nBoh..,cose d&#8217;Italia.<br \/>\nMi sento in dovere,per\u00f2,di porre due piccole e modeste domande a Panorama ed alla stampa berlusconiana.<br \/>\nChe effetto fa,pur essendo parte rilevante ed integrante (in qualit\u00e0 di sostenitori di Berlusconi ) del regime partitocratico,ritenersi quasi perseguitati politici ?<br \/>\nOccorrer\u00e0 proprio guardare da dietro le sbarre per rendersi conto in quale tipo di stato viviamo ?<\/p>\n<p>Grazie per l&#8217;attenzione.<br \/>\nVincenzo Mannello<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/24\/panorama-da-dietro-le-sbarre\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/24\/panorama-da-dietro-le-sbarre\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Colpita ed affondata Panorama nella battaglia navale giocata con(tro) la magistratura. La condanna ad otto mesi di reclusione per il direttore Mul\u00e8 ed un anno per il giornalista Marcenaro, sembra essere un colpo di grosso calibro assestato ai &#8220;filo-berlusconiani&#8221; della carta stampata. Certo,l&#8217;ANM sosterr\u00e0 con sdegno che nessuna correlazione esiste tra la condanna inflitta per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16739,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16737"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=16737"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16737\/revisions"}],"predecessor-version":[{"id":16741,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16737\/revisions\/16741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/16739"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=16737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=16737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=16737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}