{"id":16742,"date":"2013-05-24T16:21:49","date_gmt":"2013-05-24T16:21:49","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=16742"},"modified":"2013-05-24T16:21:50","modified_gmt":"2013-05-24T16:21:50","slug":"il-figlio-su-misura","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/24\/il-figlio-su-misura\/","title":{"rendered":"IL FIGLIO SU MISURA"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/24\/il-figlio-su-misura\/capitan-nazi-1155_jpg_220x0_upscale_q85\/\" rel=\"attachment wp-att-16743\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/Capitan-Nazi-1155_jpg_220x0_upscale_q85-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" class=\"alignleft size-medium wp-image-16743\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/Capitan-Nazi-1155_jpg_220x0_upscale_q85-200x300.jpg 200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/Capitan-Nazi-1155_jpg_220x0_upscale_q85.jpg 220w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>Vuoi un maschio o una femmina? A Basilea, i genitori possono scegliere il sesso del loro bambino.<br \/>\n<\/strong>I genitori che soffrono di gravi malattie ereditarie possono ormai scegliere il sesso del loro bambino all&#8217;ospedale universitario di Basilea. E\u2019 l\u2019unica struttura dell&#8217;Europa continentale che propone una simile scelta. Il sesso del bimbo da concepire a deciderlo \u00e8 l&#8217;uomo con il suo cromosoma X o Y. I suoi spermatozoi, infatti, possono essere di due tipi, quelli che contengono un cromosoma sessuale di tipo maschile (tipo Y) e quelli con cromosoma femminile (tipo X); mentre l\u2019ovulo contiene sempre un cromosoma sessuale femminile (X). Quindi, se l\u2019ovulo \u00e8 fecondato da uno spermatozoo X nascer\u00e0 una femminuccia, mentre da uno di tipo Y si avr\u00e0 un maschietto.<\/p>\n<p>Mentre il nuovo metodo selettivo, denominato Microsort che viene dagli Stati Uniti. Esso separa gli spermatozoi che possiedono erditariet\u00e0 femminile da quelli maschili e si basa sul fatto che i cromosomi X femminili contengono pi\u00f9 patrimonio genetico dei cromosomi Y maschili.<\/p>\n<p>Secondo i medici, riporta\u00a0 Giovanni D\u2019Agata presidente e fondatore dello \u201c<a href=\"http:\/\/www.sportellodeidiritti.org\/\">Sportello dei Diritti<\/a>\u201d,<\/p>\n<p>grazie a questo metodo \u00e8 possibile garantire all&#8217;80% che il nascituro sar\u00e0 maschio o femmina, e cos\u00ec prevenire la trasmissione di malattie ereditarie quali la mucoviscidosi o la distrofia muscolare nel b\u00e9b\u00e9. Molte di queste malattie colpiscono un solo sesso. In maggioranza quello maschile.<\/p>\n<p>V\u2019\u00e8 da specificare che la legislazione svizzera autorizza la selezione di spermatozoi, ma unicamente nei casi di gravi malattie ereditarie che provengono da uno dei genitori.<\/p>\n<p>&nbsp;<\/p>\n<p>(ndr)<\/p>\n<p>Speriamo che ci si limiti ad utilizzare certe tecnologie solo per combattere le malattie. Non vorremmo che si passasse dalla razza perfetta di germanica memoria, al figlio perfetto della societ\u00e0 moderna.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em><br \/>\n<\/em><\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/24\/il-figlio-su-misura\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/24\/il-figlio-su-misura\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Vuoi un maschio o una femmina? A Basilea, i genitori possono scegliere il sesso del loro bambino. I genitori che soffrono di gravi malattie ereditarie possono ormai scegliere il sesso del loro bambino all&#8217;ospedale universitario di Basilea. E\u2019 l\u2019unica struttura dell&#8217;Europa continentale che propone una simile scelta. Il sesso del bimbo da concepire a deciderlo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16743,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16742"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=16742"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16742\/revisions"}],"predecessor-version":[{"id":16745,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16742\/revisions\/16745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/16743"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=16742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=16742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=16742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}