{"id":16768,"date":"2013-05-25T06:16:08","date_gmt":"2013-05-25T06:16:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=16768"},"modified":"2013-05-25T06:44:27","modified_gmt":"2013-05-25T06:44:27","slug":"entella-lecce-via-allultima-chiamata","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/entella-lecce-via-allultima-chiamata\/","title":{"rendered":"ENTELLA &#8211; LECCE: VIA ALL\u2019ULTIMA CHIAMATA a cura di Gabriele De Pandis"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/entella-lecce-via-allultima-chiamata\/schermata-2013-05-25-a-08-14-01\/\" rel=\"attachment wp-att-16769\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/Schermata-2013-05-25-a-08.14.01-300x188.png\" alt=\"\" width=\"300\" height=\"188\" class=\"alignleft size-medium wp-image-16769\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/Schermata-2013-05-25-a-08.14.01-300x188.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/Schermata-2013-05-25-a-08.14.01.png 507w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Ultima chiamata per la B e per evitare l\u2019onta personale. Questa \u00e8 la voce che riecheggia nei corridoi del ritiro di Sestri Levante dove il Lecce sta preparando la gara di andata della semifinale dei playoff che vedr\u00e0 opposti i giallorossi alla Virtus Entella.<\/p>\n<p>Il neo mister Gustinetti ha avuto due settimane per conoscere il gruppo e cercare di trarre le sue prime conclusioni sulla formazione da schierare nell\u2019insidioso impegno di Chiavari.<\/p>\n<p>La Virtus Entella, guidata da mister Luca Prina, non \u00e8 di certo stata scoperta ieri. I liguri sono stati la rivelazione del campionato (insieme alla Sudtirol), partiti con ambizioni di salvezza e trovatisi alla fine del campionato al 5\u00b0posto con un balcone che affaccia sulla B, categoria mai calcata dalla squadra di Chiavari.<\/p>\n<p>L\u2019Entella si \u00e8 guadagnata la 5\u00b0 piazza del campionato grazie ad un campionato condotto in maniera costante e criteriata, infatti, i liguri si sono attestati nella zona playoff dalla prima all\u2019ultima giornata. Analizzando i numeri del rendimento dei biancocelesti si capisce subito che la squadra di Prina \u00e8 stata molto pragmatica nel portarsi a casa molti risultati utili consecutivi evitando di strafare, emblematica al riguardo \u00e8 la serie di sette pareggi consecutivi dall\u2019ottava alla quattordicesima giornata.<\/p>\n<p>Come ogni squadra rivelazione, il segreto dell\u2019exploit dell\u2019Entella \u00e8 stato il rendimento al \u201cComunale\u201d di Chiavari, infatti \u00e8 proprio tra le mura amiche che i biancocelesti hanno ottenuto 10 delle 12 vittorie totali del campionato.<\/p>\n<p>Questo rendimento cos\u00ec altalenante potrebbe indurre Gustinetti all\u2019approccio difensivo per poi giocarsi tutto al \u201cVia del Mare\u201d ma lo stesso mister (e la prassi dei playoff degli ultimi anni) ha affermato di voler affrontare l\u2019impegno in Liguria giocando al massimo e puntando alla vittoria che metterebbe subito le cose in chiaro.<\/p>\n<p>Il morale della squadra di Prina \u00e8 di segno opposto rispetto a quello del Lecce infatti i liguri, rivelatisi come sorpresa del campionato, non hanno nulla da perdere e questa tranquillit\u00e0 potr\u00e0 giocare a loro favore in fasi concitate della partita. Si prevede inoltre un ambiente incandescente al Comunale, i biglietti (pochi per la verit\u00e0 a causa della limitata capienza dell\u2019impianto di Chiavari) sono stati polverizzati in pochi giorni.<\/p>\n<p>Gustinetti, dal canto suo, sta cercando di preparare la partita col massimo pragmatismo dato che nei dentro-fuori di questo calibro ogni scelta pu\u00f2 essere la scelta fatata o nello stesso tempo la scelta fatale.<\/p>\n<p>Tra i 20 convocati partiti gioved\u00ec per la Liguria non figurano i difensori Di Maio e Fatic, non aggregati per la trasferta a causa di problemi muscolari. Sar\u00e0 in dubbio fino a poche ore prima della partita Ernesto Chevanton, che in Liguria ha svolto solo lavoro differenziato.<\/p>\n<p>Sar\u00e0 importante approcciarsi alla partita con lo spirito giusto, lo spirito di una squadra che deve riprendersi ci\u00f2 che ha ingiustificatamente buttato per strada, lo spirito di chi ha il dovere di rispondere si all\u2019ultima chiamata per la B.<\/p>\n<p>&nbsp;<\/p>\n<p>Gabriele De Pandis.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/entella-lecce-via-allultima-chiamata\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/entella-lecce-via-allultima-chiamata\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Ultima chiamata per la B e per evitare l\u2019onta personale. Questa \u00e8 la voce che riecheggia nei corridoi del ritiro di Sestri Levante dove il Lecce sta preparando la gara di andata della semifinale dei playoff che vedr\u00e0 opposti i giallorossi alla Virtus Entella. Il neo mister Gustinetti ha avuto due settimane per conoscere il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16769,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16768"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=16768"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16768\/revisions"}],"predecessor-version":[{"id":16772,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16768\/revisions\/16772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/16769"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=16768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=16768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=16768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}