{"id":16819,"date":"2013-05-25T15:41:57","date_gmt":"2013-05-25T15:41:57","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=16819"},"modified":"2013-05-25T15:41:58","modified_gmt":"2013-05-25T15:41:58","slug":"denunciato-imprenditore-salentino-per-fatture-false","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/denunciato-imprenditore-salentino-per-fatture-false\/","title":{"rendered":"DENUNCIATO IMPRENDITORE SALENTINO PER FATTURE FALSE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/denunciato-imprenditore-salentino-per-fatture-false\/fisco_3-400x300\/\" rel=\"attachment wp-att-16820\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/fisco_3-400x300-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" class=\"alignleft size-medium wp-image-16820\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/fisco_3-400x300-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/fisco_3-400x300.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Nei giorni scorsi, i Finanzieri della Tenenza di Maglie hanno concluso una verifica fiscale nei confronti di una ditta individuale di arredamento del Sud Salento che, per gli anni d\u2019imposta 2007 e 2012, non ha dichiarato ricavi per circa 300 mila euro e ha omesso di dichiarare e versare I.V.A. per circa 200 mila euro.<\/p>\n<p>I militari sono pervenuti a tali conclusioni attraverso l\u2019esame della documentazione contabile detenuta dall\u2019azienda ispezionata e dal proprio commercialista e di quella extra contabile acquisita il giorno di inizio della verifica.<br \/>\nInoltre, eseguendo riscontri incrociati, \u00e8 stato appurato che l\u2019impresa aveva utilizzato ben 26 fatture false.<br \/>\nInfine, al legale rappresentante della societ\u00e0, le Fiamme Gialle hanno contestato l\u2019impiego \u201cin nero\u201d di 2 lavoratori.<br \/>\nIl titolare dell\u2019impresa, un trentenne della zona, \u00e8 stato denunciato all\u2019Autorit\u00e0 Giudiziaria per aver esposto nelle dichiarazioni fiscali del 2007 e 2008, sia ai fini delle imposte dirette che dell\u2019I.V.A., costi \u201cfittizi\u201d originati dall\u2019utilizzo delle fatture false.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/denunciato-imprenditore-salentino-per-fatture-false\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/denunciato-imprenditore-salentino-per-fatture-false\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nei giorni scorsi, i Finanzieri della Tenenza di Maglie hanno concluso una verifica fiscale nei confronti di una ditta individuale di arredamento del Sud Salento che, per gli anni d\u2019imposta 2007 e 2012, non ha dichiarato ricavi per circa 300 mila euro e ha omesso di dichiarare e versare I.V.A. per circa 200 mila euro. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16820,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16819"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=16819"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16819\/revisions"}],"predecessor-version":[{"id":16822,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16819\/revisions\/16822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/16820"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=16819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=16819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=16819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}