{"id":16845,"date":"2013-05-25T16:06:18","date_gmt":"2013-05-25T16:06:18","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=16845"},"modified":"2013-05-25T16:06:18","modified_gmt":"2013-05-25T16:06:18","slug":"probabili-formazioni-a-cura-di-gabriele-de-pandis","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/probabili-formazioni-a-cura-di-gabriele-de-pandis\/","title":{"rendered":"PROBABILI FORMAZIONI  a cura di Gabriele De Pandis"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/probabili-formazioni-a-cura-di-gabriele-de-pandis\/schermata-2013-05-25-a-18-05-43\/\" rel=\"attachment wp-att-16846\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/Schermata-2013-05-25-a-18.05.43-300x219.png\" alt=\"\" width=\"300\" height=\"219\" class=\"alignleft size-medium wp-image-16846\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/Schermata-2013-05-25-a-18.05.43-300x219.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/Schermata-2013-05-25-a-18.05.43.png 343w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>VIRTUS ENTELLA: infermeria quasi vuota per mister Luca Prina, in settimana hanno recuperato la punta Sascha Cori ed il terzino destro Zampano (che rimarr\u00e0 in dubbio fino alla fine). Non sarnno della partita il difensore Bianchi e la giovane punta Beretta. La squadra girer\u00e0 come al solito sull\u2019estro dell\u2019ex Empoli Ighli Vannucchi che sar\u00e0 fulcro del gioco del 4-2-3-1 di Prina. Le frecce ai suoi lati probabilmente saranno l\u2019ex Piacenza Guerra e Staiti. A far filtro a centrocampo troveranno posto capitan Volpe ed uno tra Raggio Garibaldi e Di Tacchio.<\/p>\n<p>Ballottaggio anche per il ruolo di punta tra Rosso ed il rientrante Sascha Cori. In seconda battuta e pronti a partire dalla panchina ci saranno Argeri e Marchi.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>LECCE: Gustinetti sembra propenso ad optare per il 4-3-1-2 provato nell\u2019amichevole di domenica scorsa contro il Copertino. Non sono partiti per la Liguria i difensori Di Maio e Fatic.<\/p>\n<p>La coppia centrale difensiva dovrebbe essere composta da Martinez e Ferrario (favorito su Esposito). A sinistra, per sostituire Fatic, ci sono tre uomini per una maglia: Tomi, Diniz (con inserimento di D\u2019Ambrosio a destra) e l\u2019outsider Zappacosta.<\/p>\n<p>A centrocampo trio di quantit\u00e0 e qualit\u00e0 composto dal rientrante De Rose, Giacomazzi e Memushaj. Sar\u00e0 poi Mariano Bogliacino l\u2019ago della bilancia del sistema di gioco di Gustinetti, l\u2019uruguagio \u00e8 chiamato al lavoro sulla trequarti dietro le due punte che dovrebbero essere Falco e Pi\u00e0. Chevanton, allenatosi poco negli ultimi giorni a causa dei soliti guai muscolari, dovrebbe partire dalla panchina insieme a Jeda.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>VIRTUS ENTELLA<\/p>\n<p align=\"center\">Paroni<\/p>\n<p align=\"center\">\n<p align=\"center\">De Col\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Falcier\u00a0\u00a0\u00a0\u00a0\u00a0 Cesar\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Russo<\/p>\n<p align=\"center\">\n<p align=\"center\">Volpe\u00a0\u00a0\u00a0\u00a0\u00a0 Di Tacchio<\/p>\n<p align=\"center\">\n<p align=\"center\">Staiti\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Vannucchi\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Guerra<\/p>\n<p align=\"center\">\n<p align=\"center\">Rosso<\/p>\n<p align=\"center\">\n<p align=\"center\">\n<div>\n<p align=\"center\">\n<\/div>\n<p align=\"center\">\n<p align=\"center\">Falco\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pi\u00e0<\/p>\n<p align=\"center\">\n<p align=\"center\">Bogliacino<\/p>\n<p align=\"center\">\n<p align=\"center\">Memushaj\u00a0\u00a0\u00a0\u00a0\u00a0 Giacomazzi\u00a0\u00a0\u00a0\u00a0\u00a0 De Rose<\/p>\n<p align=\"center\">\n<p align=\"center\">Diniz\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Martinez\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ferrario\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 D\u2019Ambrosio<\/p>\n<p align=\"center\">\n<p align=\"center\">Benassi<\/p>\n<p>LECCE<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/probabili-formazioni-a-cura-di-gabriele-de-pandis\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/25\/probabili-formazioni-a-cura-di-gabriele-de-pandis\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>VIRTUS ENTELLA: infermeria quasi vuota per mister Luca Prina, in settimana hanno recuperato la punta Sascha Cori ed il terzino destro Zampano (che rimarr\u00e0 in dubbio fino alla fine). Non sarnno della partita il difensore Bianchi e la giovane punta Beretta. La squadra girer\u00e0 come al solito sull\u2019estro dell\u2019ex Empoli Ighli Vannucchi che sar\u00e0 fulcro [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16846,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16845"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=16845"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16845\/revisions"}],"predecessor-version":[{"id":16848,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16845\/revisions\/16848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/16846"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=16845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=16845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=16845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}