{"id":16866,"date":"2013-05-26T08:07:36","date_gmt":"2013-05-26T08:07:36","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=16866"},"modified":"2013-05-26T08:07:36","modified_gmt":"2013-05-26T08:07:36","slug":"tra-qualche-anno-non-avremo-acqua-a-sufficienza","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/26\/tra-qualche-anno-non-avremo-acqua-a-sufficienza\/","title":{"rendered":"TRA QUALCHE ANNO NON AVREMO ACQUA A SUFFICIENZA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/26\/tra-qualche-anno-non-avremo-acqua-a-sufficienza\/acqua\/\" rel=\"attachment wp-att-16867\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/acqua-300x202.jpg\" alt=\"\" width=\"300\" height=\"202\" class=\"alignleft size-medium wp-image-16867\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/acqua-300x202.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/acqua.jpg 478w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>I ricercatori sentenziano che l\u2019acqua, tra due generazioni non sar\u00e0 pi\u00f9 sufficiente per tutti. Un appello alle istituzioni per un uso pi\u00f9 razionale dell&#8217;acqua per evitare la crisi.<br \/>\nL\u2019acqua \u00e8 un bene comune prezioso che dev\u2019essere risparmiato e tutelato da leggi pubbliche dello Stato e da convenzioni della comunit\u00e0 internazionale perch\u00e9 non \u00e8 inesauribile e se continuiamo a sfruttarla nei modi che oggi continuiamo a perpetrare arriveremo ad una crisi senza precedenti nella storia.<\/p>\n<p>Non solo i forum dell\u2019acqua che in questi anni si stanno battendo per la difesa dell\u2019acqua pubblica, ma in questi giorni oltre 500 ricercatori di tutto il mondo riuniti a Bonn in una conferenza, hanno lanciato un appello per un uso pi\u00f9 razionale dell&#8217;acqua, nella convinzione che sia possibile evitare la crisi.<\/p>\n<p>Una crisi che assomiglia ad uno scenario apocalittico: dirottiamo o arginiamo i fiumi che arrivano in mare quasi vuoti, inquiniamo le falde, usiamo grandi quantit\u00e0 di acqua dolce per sfruttare l&#8217;energia fossile: se continueremo su questa strada, nell&#8217;arco di due generazioni l&#8217;acqua non sar\u00e0 pi\u00f9 sufficiente per la maggior parte dei 9 miliardi di persone che popoleranno la Terra.<\/p>\n<p>Nell&#8217;appello, chiamato &#8216;Dichiarazione di Bonn&#8217;, i ricercatori hanno rilevato che &#8220;la crisi dell&#8217;acqua \u00e8 del tutto evitabile&#8221; in quanto \u00e8 dovuta &#8220;solo ad una cattiva gestione di questa risorsa essenziale e insostituibile&#8221;.<\/p>\n<p>\u00c8 ovvio ed \u00e8 sotto gli occhi di tutti, quindi, che l&#8217;attivit\u00e0 umana giochi un ruolo centrale nel sistema idrico globale. Innumerevoli azioni errate individuali si sommano e si riflettono su cambiamenti globali. In questo modo, gesto dopo gesto, l&#8217;uomo ha cambiato drasticamente la portata dei fiumi, delle riserve sotterranee d&#8217;acqua, alterato la qualit\u00e0 dell&#8217;acqua e danneggiato gli ecosistemi acquatici.<\/p>\n<p>Con le attuali conoscenze, hanno sottolineato i ricercatori, non \u00e8 possibile prevedere esattamente quando il limite planetario sar\u00e0 superato. Se si arriver\u00e0 a quel punto, secondo gli esperti, &#8220;si potrebbero innescare cambiamenti irreversibili con potenziali, catastrofiche conseguenze&#8221;.<\/p>\n<p>Ma tutto ci\u00f2 pu\u00f2 essere ancora evitato, si legge nella dichiarazione, se si applicano le seguenti 6 raccomandazioni: potenziare la ricerca sul sistema idrico globale; elaborare una sintesi delle attuali conoscenze sul sistema acqua per migliorarne la protezione; formare la prossima generazione di ricercatori specializzati nel settore idrico; intensificare il monitoraggio dell&#8217;acqua; preferire soluzioni basate sulla salvaguardia degli ecosistemi a costosi interventi strutturali; stimolare l&#8217;innovazione nella gestione dell&#8217;acqua.<\/p>\n<p>L&#8217;aumento dell&#8217;approvvigionamento idrico e dei servizi igienico-sanitari hanno dato indubbi benefici per le persone di tutto il mondo, ma ora c&#8217;\u00e8 un altro bisogno pressante: arrivare a una gestione dell&#8217;acqua basata sul rispetto degli ecosistemi.<\/p>\n<p>Ecco perch\u00e9 lo \u201c<a href=\"http:\/\/www.sportellodeidiritti.org\/\">Sportello dei Diritti<\/a>\u201d, nella persona del presidente e fondatore Giovanni D\u2019Agata, rilancia anche in Italia l\u2019appello della &#8216;Dichiarazione di Bonn&#8217; che riteniamo dovr\u00e0 essere un punto fermo per i governanti del mondo se non si vuole arrivare ad una catastrofe. Al contempo, chiediamo che il nostro parlamento la faccia propria per essere da esempio nel resto del pianeta.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/26\/tra-qualche-anno-non-avremo-acqua-a-sufficienza\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/26\/tra-qualche-anno-non-avremo-acqua-a-sufficienza\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I ricercatori sentenziano che l\u2019acqua, tra due generazioni non sar\u00e0 pi\u00f9 sufficiente per tutti. Un appello alle istituzioni per un uso pi\u00f9 razionale dell&#8217;acqua per evitare la crisi. L\u2019acqua \u00e8 un bene comune prezioso che dev\u2019essere risparmiato e tutelato da leggi pubbliche dello Stato e da convenzioni della comunit\u00e0 internazionale perch\u00e9 non \u00e8 inesauribile e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16867,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16866"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=16866"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16866\/revisions"}],"predecessor-version":[{"id":16869,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16866\/revisions\/16869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/16867"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=16866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=16866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=16866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}