{"id":169929,"date":"2025-07-27T00:01:00","date_gmt":"2025-07-26T22:01:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=169929"},"modified":"2025-07-26T11:09:28","modified_gmt":"2025-07-26T09:09:28","slug":"lunedi-27","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/27\/lunedi-27\/","title":{"rendered":"DIARIO DEL GIORNO \/ DOMENICA 27 LUGLIO 2025"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"310\" height=\"200\" class=\"wp-image-202987\" style=\"width: 450px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/310px-Attentato-via-palestro.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/310px-Attentato-via-palestro.jpg 310w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/310px-Attentato-via-palestro-300x194.jpg 300w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/><\/p>\n\n\n\n<p>Buongiorno!<\/p>\n\n\n\n<p>Oggi \u00e8 domenica 27 luglio 2025.<br>San Felice.<br><\/p>\n\n\n\n<p>Alle 23.14 del 27 luglio 1993, in via Palestro a Milano, l&#8217;esplosione di un&#8217;autobomba avente come obiettivo la Galleria d&#8217;arte moderna e il Padiglione di arte contemporanea, provoc\u00f2 la morte di cinque persone: l&#8217;Agente di Polizia Municipale Alessandro Ferrari, i Vigili del Fuoco Carlo La Catena, Sergio Pasotto, Stefano Picerno e l&#8217;immigrato marocchino Moussafir Driss.<br>L&#8217;attentato va ad inserirsi nella scia di altri dai moventi simili avvenuti tra il 1992 e il 1993 che provocarono la morte di ventuno persone e tra cui quella dei giudici Falcone e Borsellino. La strage di via Palestro, ad opera di &#8220;Cosa nostra&#8221;, rientra in quell&#8217;insieme di attentati effettuati come rappresaglia contro la lotta alla mafia, o comunque quali tentativi di condizionamento degli apparati dello Stato, delle Istituzini. Tra i responsabili troviamo nomi noti del crimine organizzato come Francesco Giuliano, Gaspare Spatuzza e Antonino Mangano.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><br>Proverbio salentino:<strong> DOPU CA RUBBARA MISERA LI CANCELLI A SANTA CHIARA.<br><\/strong> La traduzione letterale \u00e8: Dopo che rubarono misero i cancelli a Santa Chiara.<br>Evidentemente in illo tempore vi era stato un furto nella chiesa di Santa Chiara, non sappiamo se si trattasse della chiesa leccese, quella che si trova &nbsp;a pochi passi piazza Sant\u2019Oronzo: sappiamo per\u00f2 che, dopo che ci fu il&nbsp;&nbsp;furto, essa&nbsp;fu dotata di un cancello che la proteggesse dai ladri. Protezione inutile in quanto la chiesa era stata spogliata &nbsp;dei quadri ed i preziosi arredi.<br>Per cui nella tradizione salentina questo proverbio &nbsp;viene utilizzato per sottolineare un\u2019 azione tardiva e&nbsp;inutile, che non produce alcun effetto positivo.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/27\/lunedi-27\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/27\/lunedi-27\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Buongiorno! Oggi \u00e8 domenica 27 luglio 2025.San Felice. Alle 23.14 del 27 luglio 1993, in via Palestro a Milano, l&#8217;esplosione di un&#8217;autobomba avente come obiettivo la Galleria d&#8217;arte moderna e il Padiglione di arte contemporanea, provoc\u00f2 la morte di cinque persone: l&#8217;Agente di Polizia Municipale Alessandro Ferrari, i Vigili del Fuoco Carlo La Catena, Sergio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":202987,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/169929"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=169929"}],"version-history":[{"count":13,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/169929\/revisions"}],"predecessor-version":[{"id":246488,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/169929\/revisions\/246488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/202987"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=169929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=169929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=169929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}