{"id":173231,"date":"2020-10-11T11:23:12","date_gmt":"2020-10-11T09:23:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=173231"},"modified":"2020-10-11T15:43:30","modified_gmt":"2020-10-11T13:43:30","slug":"emozioni-in-concerto-ieri-sera-al-castello-di-copertino-con-la-trilogia-verdiana-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/10\/11\/emozioni-in-concerto-ieri-sera-al-castello-di-copertino-con-la-trilogia-verdiana-2\/","title":{"rendered":"EMOZIONI IN CONCERTO IERI SERA AL CASTELLO DI COPERTINO CON LA &#8220;TRILOGIA VERDIANA&#8221;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large wp-image-173228\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/FB_IMG_1602405070405-1024x682.jpg\" alt=\"\" width=\"1024\" height=\"682\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/FB_IMG_1602405070405-1024x682.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/FB_IMG_1602405070405-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/FB_IMG_1602405070405-768x511.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/FB_IMG_1602405070405.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>di <strong>Maria Antonietta Vacca<\/strong>_______<\/p>\n<p>Serata incantevole ieri sera nella sempre prestigiosa e suggestiva cornice del castello di Copertino: \u201cTrilogia Verdiana\u201d.<\/p>\n<p>Grande serata collaterale del Festival Internazionale delle Arti 2020.<\/p>\n<p>TRILOGIA VERDIANA \u00e8 il primo appuntamento della rassegna destagionalizzata del Festival, interamente dedicato alla figura di Giuseppe Verdi e alle sue tre opere popolari, Rigoletto, Il Trovatore e La Traviata.<\/p>\n<p>Ospite d\u2019eccezione il pianista Roberto Corlian\u00f2 che ha presentato l\u2019esecuzione delle sue celebri parafrasi operistiche, insieme ai solisti dell\u2019Accademia Germogli d\u2019arte, al tenore Salvatore Cordella, direttore artistico del Festival, e al Coro Internazionale delle Arti diretto dal M\u00b0 Emanuela Di Pietro.<\/p>\n<p>A guidare l\u2019ascolto e la narrazione l\u2019attore Paride Napolitano.<\/p>\n<p>La regia \u00e8 di Rosangela Giurgola.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large wp-image-173226\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/FB_IMG_1602375076021-717x1024.jpg\" alt=\"\" width=\"717\" height=\"1024\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/FB_IMG_1602375076021-717x1024.jpg 717w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/FB_IMG_1602375076021-210x300.jpg 210w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/FB_IMG_1602375076021-768x1097.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/FB_IMG_1602375076021-1075x1536.jpg 1075w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/FB_IMG_1602375076021.jpg 1080w\" sizes=\"(max-width: 717px) 100vw, 717px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Un serata riuscita, un successo annunciato, nel pieno rispetto delle norme anti-Covid. Un pubblico attento e partecipato, coinvolto all\u2019inverosimile da un racconto sapientemente portato ad altissimi livelli dalla direzione artistica dell\u2019evento e che ha raggiunto l\u2019apice con le esecuzioni del Mastro Corlian\u00f2 e la performance del Maestro Salvatore Cordella, forti di un corollario di grandi professionisti.<\/p>\n<p>&nbsp;<\/p>\n<p>La serata resa ancora pi\u00f9 significativa da una data importante: ricorreva ieri infatti il 206\u00b0 anniversario dalla nascita del grande compositore.<\/p>\n<p>&nbsp;<\/p>\n<p>Il festival internazionale delle arti vi da appuntamento per il 14 novembre con un altro imperdibile concerto sempre al castello di Copertino.<\/p>\n<p>#festinart2020 #giuseppeverdi #Trilogiaverdiana<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/10\/11\/emozioni-in-concerto-ieri-sera-al-castello-di-copertino-con-la-trilogia-verdiana-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/10\/11\/emozioni-in-concerto-ieri-sera-al-castello-di-copertino-con-la-trilogia-verdiana-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Maria Antonietta Vacca_______ Serata incantevole ieri sera nella sempre prestigiosa e suggestiva cornice del castello di Copertino: \u201cTrilogia Verdiana\u201d. Grande serata collaterale del Festival Internazionale delle Arti 2020. TRILOGIA VERDIANA \u00e8 il primo appuntamento della rassegna destagionalizzata del Festival, interamente dedicato alla figura di Giuseppe Verdi e alle sue tre opere popolari, Rigoletto, Il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":173228,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/173231"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=173231"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/173231\/revisions"}],"predecessor-version":[{"id":173234,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/173231\/revisions\/173234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/173228"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=173231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=173231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=173231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}