{"id":173271,"date":"2020-10-11T16:16:03","date_gmt":"2020-10-11T14:16:03","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=173271"},"modified":"2020-10-11T16:19:51","modified_gmt":"2020-10-11T14:19:51","slug":"tre-operazioni-antidroga-nel-brindisino-sequestri-arresti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/10\/11\/tre-operazioni-antidroga-nel-brindisino-sequestri-arresti\/","title":{"rendered":"OPERAZIONI ANTIDROGA NEL BRINDISINO, CINQUE ARRESTI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-173272\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/br.jpg\" alt=\"\" width=\"512\" height=\"326\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/br.jpg 512w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/10\/br-300x191.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>(e.l.)______Un uomo di 43 anni, Carlo Coviello, di Trepuzzi, e un giovane di 19 anni, Gianpaolo Elia, di Torchiarolo, sono stati arrestati dai Carabinieri del Nucleo Operativo della Compagnia di <strong>Brindisi<\/strong>, alle porte della citt\u00e0, con l&#8217;accusa di detenzione ai fini di spaccio di sostanze stupefacenti.<\/p>\n<p>Fermati per un controllo mentre erano a bordo di un&#8217; auto di grossa cilindrata, sono stati trovati in possesso, il primo di quaranta involucri contenenti cocaina per un totale di dodici grammi e mezzo, un grammo e mezzo di marijuana, 1.690 euro in contanti ritenuti provento di spaccio; il secondo di un grammo di cocaina e tre grammi e mezzo di marijuana.<\/p>\n<p>Il pm di turno presso la Procura della Repubblica di Brindisi (nella foto) ha disposto per loro i domiciliari.<\/p>\n<p>&nbsp;<\/p>\n<p>Arresti domiciliari anche per una coppia di\u00a0<strong>San Michele Salentino<\/strong>, Alberto Fumarola, 27 anni, e Rosella Ciraci, 24 anni, i quali, sempre nelle ultime ore, durante una perquisizione domiciliare, sono stati trovati in possesso di duecentosessanta grammi di marijuana.<\/p>\n<p>&nbsp;<\/p>\n<p>E, infine,\u00a0 arresti domiciliari anche per l&#8217;ultimo degli arrestati in queste ultime ore nel Brindisino dai Carabinieri con l&#8217;accusa di detenzione ai fini di spaccio di sostanze stupefacenti. L&#8217;ultima e distinta operazione a <strong>Mesagne<\/strong>, dove un uomo di 47 anni, Angelo Lucio Milone, \u00e8 stato trovato in possesso nel suo domicilio di quattrocento ottantaquattro grammi di marijuana e sei piante, e nel terreno agricolo da lui coltivato, di altre cento e quattro piante di marijuana e tre chili di sostanza gi\u00e0 essiccata.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/10\/11\/tre-operazioni-antidroga-nel-brindisino-sequestri-arresti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/10\/11\/tre-operazioni-antidroga-nel-brindisino-sequestri-arresti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______Un uomo di 43 anni, Carlo Coviello, di Trepuzzi, e un giovane di 19 anni, Gianpaolo Elia, di Torchiarolo, sono stati arrestati dai Carabinieri del Nucleo Operativo della Compagnia di Brindisi, alle porte della citt\u00e0, con l&#8217;accusa di detenzione ai fini di spaccio di sostanze stupefacenti. Fermati per un controllo mentre erano a bordo di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":173272,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/173271"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=173271"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/173271\/revisions"}],"predecessor-version":[{"id":173274,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/173271\/revisions\/173274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/173272"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=173271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=173271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=173271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}