{"id":174566,"date":"2020-11-11T18:20:37","date_gmt":"2020-11-11T17:20:37","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=174566"},"modified":"2020-11-11T18:26:51","modified_gmt":"2020-11-11T17:26:51","slug":"fotovoltaico-selvaggio-uno-tsunami-sta-per-abbattersi-sul-salento-un-vero-e-proprio-incubo-per-territorio-e-natura-nellindifferenza-ma-si-tratta-solo-di-indifferenza-della-politica-la-dramm","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/11\/11\/fotovoltaico-selvaggio-uno-tsunami-sta-per-abbattersi-sul-salento-un-vero-e-proprio-incubo-per-territorio-e-natura-nellindifferenza-ma-si-tratta-solo-di-indifferenza-della-politica-la-dramm\/","title":{"rendered":"FOTOVOLTAICO SELVAGGIO. UNO TSUNAMI STA PER ABBATTERSI SUL SALENTO, UN VERO E PROPRIO INCUBO PER TERRITORIO E NATURA, NELL&#8217;INDIFFERENZA &#8211; MA SI TRATTA SOLO DI INDIFFERENZA? &#8211; DELLA POLITICA. LA DRAMMATICA DENUNCIA DEL FORUM AMBIENTE SALUTE. L&#8217;APPELLO &#8220;a tutte le Istituzioni a fermare questa follia&#8221;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-174567\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/11\/impianto-fotovoltaico1.jpg\" alt=\"\" width=\"600\" height=\"351\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/11\/impianto-fotovoltaico1.jpg 600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/11\/impianto-fotovoltaico1-300x176.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>(Rdl)______<strong>&#8220;In soli cinque giorni sono stati presentati una valanga di mega-progetti pronti a far scomparire trecento ettari di suolo agricolo sotto una selva di pannelli fotovoltaici&#8221;.<\/strong><\/p>\n<p>Lo ha reso noto questa sera con giustificato allarme IL FORUM AMBIENTE SALUTE, storica e partecipata associazione ambientalista salentina, che chiede urgentemente lo stop al fotovoltaico selvaggio.<\/p>\n<p>Che cosa sta succedendo?<\/p>\n<p><strong><span style=\"color: #ff0000;\"><em>E&#8217; in arrivo una &#8220;valanga&#8221;, che il Forum definisce &#8220;uno tsunami&#8221;, e anzi &#8220;un incubo&#8221;\u00a0 per Territorio e Natura, nel chiedere contestualmente &#8220;a tutte le istituzioni della Repubblica di fermare questa follia&#8221;.<\/em><\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong><em>&#8220;Si tratta di sette\u00a0progetti di mega-fotovoltaico industriale a terra per un consumo di suolo agricolo di ben 200 ettari, oltre ai 100 ettari di impianti presentanti nei mesi precedenti&#8221; &#8211; ha rivelato il FORUM AMBIENTE SALUTE &#8211; &#8220;Questo con una tale urgenza e quantit\u00e0, in piena emergenza Covid, tanto da risultare a tutti i cittadini non solo molto inquietante ma anche terribilmente sospetto&#8221;.<\/em><\/strong><\/span><\/p>\n<p>In particolare, <strong><em>&#8220;in soli cinque giorni, tra il 2 ed il 6 novembre, sono giunti ben sette progetti, anche pi\u00f9 di uno al giorno! <\/em><\/strong><br \/>\n<strong><em>Gi\u00e0 il 2 novembre si registrava la presentazione presso la Provincia di Lecce di un mega impianto di fotovoltaico industriale da cinquantuno ettari nelle campagne del comune di Lecce.<\/em><\/strong><\/p>\n<p><strong><em>A questo, nei giorni successivi, si sono aggiunti altri sei mega impianti di fotovoltaico a terra per un totale di consumo di suolo agricolo e rurale di ben 200 ettari, ettari che si vanno ad aggiungere ai gi\u00e0 altri 100 degli altri progetti di fotovoltaico gi\u00e0 presentati nei mesi scorsi, ed attualmente in Conferenza dei Servizi presso la Provincia di Lecce, per un totale di quasi 300 ettari suolo vergine e naturale salentino da cancellare!&#8221;.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La denuncia del FORUM AMBIENTE SALUTE si fa stringente:<\/p>\n<p><strong><em>&#8220;Solo per capire verso quale nuova catastrofe agricola il Salento sta andando incontro \u00e8 come se da un giorno all&#8217;altro tra le campagne del Salento sorgesse una nuova grande citt\u00e0 per 30.000 abitanti!<\/em><\/strong><\/p>\n<p><strong><em>I comuni interessati da questi ultimi 7 progetti caduti a valanga sono:<\/em><\/strong><\/p>\n<p><strong><em>Lecce &#8211; 2 impianti per un totale di 81 ettari, Galatina \u2013 altri 2 impianti per un totale di 30 ettari, <\/em><\/strong><br \/>\n<strong><em>Surbo \u2013 1 impianto di 56 ettari, Cavallino \u2013 1 impianto da 9 ettari, Galatone un impianto da 18 ettari, per un totale di 194 ettari.<\/em><\/strong><\/p>\n<p><strong><em>Un sacrificio di territorio e di consumo di suolo agricolo e naturale imponente e impattante che il Salento non pu\u00f2 assolutamente permettersi il lusso ancora di subire.<\/em><\/strong><\/p>\n<p><strong><em>Perdita di suolo ancora pi\u00f9 grave e pesante specialmente per i comuni salentini che da anni sono indicati quali maglia nera per consumo di suolo vergine, risultando sempre in testa alle classifiche nazionali che annualmente redige l&#8217;ISPRA sul suolo naturale cementificato in Italia, quindi definitivamente perso. Questa una vera vergogna per tutta la politica che a tutti i livelli amministra il Salento!<\/em><\/strong><\/p>\n<p><strong>La domanda che oggi si pongono cittadini e associazioni \u00e8: dove son finiti tutti i politici che si dicono difensori del Salento? Cosa hanno fatto in questi lunghi dodici anni a tutela del suolo agricolo e naturale?<\/strong><\/p>\n<p><strong>E soprattutto, cosa ha fatto la politica regionale e nazionale a difesa del territorio del Salento per scongiurare il riproporsi di scenari da assalto al territorio e agli incentivi pubblici, un incubo vissuto dal Salento gi\u00e0 dodici anni fa con la prima ondata di rinnovabili selvagge?<\/strong><\/p>\n<p><strong>Dov&#8217;\u00e8 finita la doverosa tutela del paesaggio e territorio promessa dal Piano Paesaggistico Territoriale Regionale (PPTR), speranza per tantissimi cittadini del Salento, e che oggi si dimostra un baluardo di burro?&#8221;.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Infine, le conclusioni:<\/p>\n<p><strong><em>&#8220;Il Salento ha gi\u00e0 pagato e paga un pesante tributo nazionale e internazionale per colpa della malapolitica subendo da anni le rinnovabili selvagge con territori agricoli e naturali vetrificati da pannelli fotovoltaici e paesaggi palificati da enormi pale eoliche per ettari ed ettari, aree naturali e paesaggi che dovrebbero essere oggi bonificati e riportati urgentemente alla natura, e che, invece, rischiano di vedersi nuovamente devastati. <\/em><\/strong><br \/>\n<strong><em>Tutto questo non \u00e8 solamente inaccettabile \u00e8 anche immorale e scabroso!<\/em><\/strong><\/p>\n<p><strong><em>L&#8217;appello dei cittadini attivi e delle associazioni \u00e8 rivolto a tutti gli amministratori locali e politici seri ed onesti che hanno a cuore il Salento naturale affinch\u00e9 si attivino da subito a fermare questa sciagura ponendosi al fianco delle popolazioni e dei territori, chiedendo alla Regione e al Governo nazionale un&#8217;immediata moratoria a questa follia, avviando una seria politica di vera tutela del Salento e della Puglia prodigandosi per varare una legge di Stop al Consumo di Territorio cos\u00ec come chiesto dall&#8217;Europa e dalle Nazioni Unite&#8221;.<\/em><\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/11\/11\/fotovoltaico-selvaggio-uno-tsunami-sta-per-abbattersi-sul-salento-un-vero-e-proprio-incubo-per-territorio-e-natura-nellindifferenza-ma-si-tratta-solo-di-indifferenza-della-politica-la-dramm\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/11\/11\/fotovoltaico-selvaggio-uno-tsunami-sta-per-abbattersi-sul-salento-un-vero-e-proprio-incubo-per-territorio-e-natura-nellindifferenza-ma-si-tratta-solo-di-indifferenza-della-politica-la-dramm\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______&#8220;In soli cinque giorni sono stati presentati una valanga di mega-progetti pronti a far scomparire trecento ettari di suolo agricolo sotto una selva di pannelli fotovoltaici&#8221;. Lo ha reso noto questa sera con giustificato allarme IL FORUM AMBIENTE SALUTE, storica e partecipata associazione ambientalista salentina, che chiede urgentemente lo stop al fotovoltaico selvaggio. Che cosa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":174567,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/174566"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=174566"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/174566\/revisions"}],"predecessor-version":[{"id":174570,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/174566\/revisions\/174570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/174567"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=174566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=174566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=174566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}