{"id":174848,"date":"2020-11-17T10:03:33","date_gmt":"2020-11-17T09:03:33","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=174848"},"modified":"2020-11-17T13:37:38","modified_gmt":"2020-11-17T12:37:38","slug":"i-docenti-laureati-allunisalento-fanno-rete-da-tutta-italia-la-soddisfazione-del-rettore-fabio-pollice-una-vera-e-propria-comunita-della-formazione","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/11\/17\/i-docenti-laureati-allunisalento-fanno-rete-da-tutta-italia-la-soddisfazione-del-rettore-fabio-pollice-una-vera-e-propria-comunita-della-formazione\/","title":{"rendered":"I DOCENTI LAUREATI ALL&#8217;UNISALENTO FANNO RETE DA TUTTA ITALIA. LA SODDISFAZIONE DEL RETTORE FABIO POLLICE: &#8220;una vera e propria comunit\u00e0 della formazione&#8221;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-174849\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/11\/unnamed-15.jpg\" alt=\"\" width=\"400\" height=\"266\" \/>Riceviamo e volentieri pubblichiamo. L&#8217;Universit\u00e0 del Salento ci manda il seguente comunicato______<\/p>\n<p><strong>RETE \u201cALUMNI UNISALENTO\u201d: IL 18 NOVEMBRE 2020 IL PRIMO INCONTRO ONLINE\u00a0<\/strong><strong>CON 300 DOCENTI DI TUTTA L\u2019ITALIA LAUREATI E\/O ABILITATI A UNISALENTO<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Parte con la sezione dedicata agli ex allievi UniSalento che insegnano nelle scuole di ogni ordine e grado in tutta l\u2019Italia il lancio del network\u00a0\u201cAlumni UniSalento\u201d, la rete dei laureati e delle laureate all\u2019Universit\u00e0\u00a0del Salento\u00a0che, gi\u00e0 inseriti nel mondo del lavoro, tornano a far parte della comunit\u00e0 accademica per collaborare al suo sviluppo e a quello del territorio salentino.<\/p>\n<p><strong>Mercoled\u00ec 18 novembre 2020<\/strong>, alle ore <strong>16.30<\/strong>, circa 300 docenti si ritroveranno online sulla piattaforma predisposta dall\u2019Ateneo per parlarne assieme al Rettore\u00a0Fabio Pollice, ai delegati alla Gestione spazi ed eventi\u00a0Luisa Siculella, all\u2019Orientamento\u00a0Amedeo Maizza, alle Tecnologie digitali\u00a0Luigi Patrono\u00a0e all\u2019Offerta formativa\u00a0Attilio Pisan\u00f2, e al professore di Pedagogia sperimentale\u00a0Salvatore Colazzo: l\u2019incontro sar\u00e0 utile per definire le linee strategiche di una collaborazione che promette di avere ricadute positive per l\u2019Ateneo che per i docenti che vi hanno aderito e vi aderiranno in futuro.<\/p>\n<p><strong><em>\u00abSin dal mio insediamento ho promosso l\u2019allargamento della comunit\u00e0 accademica a tutti coloro che, avendo svolto nel nostro Ateneo i propri studi, se ne sentono parte e vogliono contribuire al suo sviluppo e allo sviluppo del Salento\u00bb &#8211;\u00a0<\/em><\/strong>spiega il Rettore\u00a0<strong>Fabio Pollice<\/strong> &#8211; <strong><em>\u00abIn questo senso, i nostri laureati possono avere un ruolo strategico collaborando in prima persona, o attraverso le istituzioni in cui operano, per la realizzazione di iniziative didattiche, di ricerca e di terza missione, e promuovendo l\u2019Ateneo e la sua offerta formativa. <\/em><\/strong><\/p>\n<p><strong><em>Di qui l\u2019idea di invitare tutti coloro che\u00a0oggi\u00a0insegnano nelle scuole a costituire una rete di \u201cAlumni docenti\u201d, con l\u2019obiettivo di creare occasioni per condividere le proprie esperienze e sviluppare assieme ai colleghi universitari iniziative e progetti. <\/em><\/strong><\/p>\n<p><strong><em>Una vera e propria comunit\u00e0 della formazione, finalizzata allo sviluppo delle competenze delle persone che vi fanno parte e alla realizzazione di forme di collaborazione, a beneficio sia della professionalit\u00e0 dei partecipanti sia della qualit\u00e0 del sistema formativo nel suo complesso\u00bb.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Per aderire al network \u201cAlumni UniSalento\u201d basta aver conseguito un qualunque titolo di studio presso l\u2019Universit\u00e0 del Salento (laurea, laurea magistrale, master, corso di specializzazione eccetera); informazioni su<\/p>\n<p><a href=\"http:\/\/www.alumni.unisalento.it\">www.alumni.unisalento.it<\/a><\/p>\n<p>video tutorial su<\/p>\n<p><a href=\"https:\/\/youtu.be\/O6CapQaclZk\">https:\/\/youtu.be\/O6CapQaclZk<\/a><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/11\/17\/i-docenti-laureati-allunisalento-fanno-rete-da-tutta-italia-la-soddisfazione-del-rettore-fabio-pollice-una-vera-e-propria-comunita-della-formazione\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/11\/17\/i-docenti-laureati-allunisalento-fanno-rete-da-tutta-italia-la-soddisfazione-del-rettore-fabio-pollice-una-vera-e-propria-comunita-della-formazione\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. L&#8217;Universit\u00e0 del Salento ci manda il seguente comunicato______ RETE \u201cALUMNI UNISALENTO\u201d: IL 18 NOVEMBRE 2020 IL PRIMO INCONTRO ONLINE\u00a0CON 300 DOCENTI DI TUTTA L\u2019ITALIA LAUREATI E\/O ABILITATI A UNISALENTO &nbsp; Parte con la sezione dedicata agli ex allievi UniSalento che insegnano nelle scuole di ogni ordine e grado in tutta l\u2019Italia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":174849,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,31,75,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/174848"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=174848"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/174848\/revisions"}],"predecessor-version":[{"id":174854,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/174848\/revisions\/174854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/174849"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=174848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=174848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=174848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}