{"id":175520,"date":"2020-12-03T16:44:29","date_gmt":"2020-12-03T15:44:29","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=175520"},"modified":"2020-12-03T18:05:15","modified_gmt":"2020-12-03T17:05:15","slug":"casa-lecce-il-resoconto-dellallenamento-odierno","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/12\/03\/casa-lecce-il-resoconto-dellallenamento-odierno\/","title":{"rendered":"CASA LECCE \/ IL RESOCONTO DELL&#8217;ALLENAMENTO ODIERNO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-175528\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/12\/Foto-Hotel-2-300x212.jpg\" alt=\"\" width=\"400\" height=\"283\" \/>di <strong>Mattia Ala______<\/strong><\/p>\n<p>Seduta di allenamento pomeridiana ad <strong>Acaya<\/strong> (nella foto, il centro sportivo)\u00a0per il <strong>Lecce<\/strong> di mister <strong>Eugenio Corini.<\/strong><\/p>\n<p>Il tecnico di Bagnolo Mella per la gara contro il <strong>Venezia<\/strong> di sabato prossimo al Via del Mare potr\u00e0 praticamente contare su tutta la rosa, ad eccezione di <strong>Mattia Felici<\/strong>, e,\u00a0 anche se siamo ancora nel campo delle ipotesi, <strong>Gabriel<\/strong>.<\/p>\n<p>Il brasiliano, infatti,\u00a0 ha nuovamente svolto un programma di allenamento differenziato a causa della ferita al ginocchio sinistro rimediata nell&#8217;allenamento\u00a0 di marted\u00ec,\u00a0 mentre il classe 2001 Felici \u00e8 stato tenuto a riposo.<\/p>\n<p>Nella mattinata di domani\u00a0 la rifinitura, sempre ad <strong>Acaya<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Intanto per il match contro i lagunari \u00e8 stato designato l&#8217;arbitro <strong>Eugenio Abbattista<\/strong> della sezione di <strong>Molfetta<\/strong>, mentre gli assistenti saranno il <strong>sig<\/strong>.\u00a0<strong>Michele Lombardi di Brescia<\/strong>\u00a0 ed il <strong>sig. Filippo Bercigli di Valdarno<\/strong>.<\/p>\n<p>Come quarto uomo designato, invece, il <strong>sig. Davide Ghersini<\/strong> della sezione di <strong>Genova<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/12\/03\/casa-lecce-il-resoconto-dellallenamento-odierno\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/12\/03\/casa-lecce-il-resoconto-dellallenamento-odierno\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Mattia Ala______ Seduta di allenamento pomeridiana ad Acaya (nella foto, il centro sportivo)\u00a0per il Lecce di mister Eugenio Corini. Il tecnico di Bagnolo Mella per la gara contro il Venezia di sabato prossimo al Via del Mare potr\u00e0 praticamente contare su tutta la rosa, ad eccezione di Mattia Felici, e,\u00a0 anche se siamo ancora [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":175528,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/175520"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=175520"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/175520\/revisions"}],"predecessor-version":[{"id":175529,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/175520\/revisions\/175529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/175528"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=175520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=175520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=175520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}