{"id":176634,"date":"2020-12-28T00:02:38","date_gmt":"2020-12-27T23:02:38","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=176634"},"modified":"2021-01-13T13:47:42","modified_gmt":"2021-01-13T12:47:42","slug":"da-tre-anni-alla-maturita-pronti-per-entrare-nelluniversita-e-nel-mondo-del-lavoro-li-prendiamo-per-mano-a-uno-a-uno-il-percorso-verticale-delle-marcelline-raccontata-con-tutte-le-n","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/12\/28\/da-tre-anni-alla-maturita-pronti-per-entrare-nelluniversita-e-nel-mondo-del-lavoro-li-prendiamo-per-mano-a-uno-a-uno-il-percorso-verticale-delle-marcelline-raccontata-con-tutte-le-n\/","title":{"rendered":"DAI 2 ANNI, AI 18 DELLA MATURITA&#8217;"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/zEDR7KPc3uQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><strong>PRONTI PER ENTRARE IN UNIVERSITA&#8217; E NEL MONDO DEL LAVORO: &#8220;li prendiamo per mano a uno a uno&#8221;. &#8216;IL PERCORSO VERTICALE&#8217; DELLE MARCELLINE, RACCONTATO CON TUTTE LE NOVITA&#8217; DALLA RESPONSABILE, SUOR MONICA CERONI, E DAI PROFESSORI DELLA PRESTIGIOSA SCUOLA LECCESE &#8211; video <\/strong><\/p>\n<p>di\u00a0<strong>Chiara Evangelista<\/strong>______<\/p>\n<p>L\u2019istituto Marcelline si rinnova, adottando un taglio sempre pi\u00f9 internazionale e adattando il percorso curriculare alle inclinazioni di ogni studente. In tal modo la scuola di formazione prende le distanze da un insegnamento passivo e cattedratico ponendo al centro dell\u2019itinere il ragazzo, prima che l\u2019alunno. Questa scelta denota l\u2019influenza del contesto e del respiro internazionale a cui l\u2019ente mira ad adeguare la propria offerta formativa.<\/p>\n<p>Lo slogan della scuola? <strong>La modernit\u00e0 \u00e8 un classico<\/strong>. L\u2019intento che si propone l\u2019istituto \u00e8 proprio quella di sdoganarsi dallo stereotipo di vetust\u00e0 e di porre <strong>la tradizione al passo dei tempi<\/strong>.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-176700\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/12\/133787386_389638778766913_6499280195818049010_n.jpg\" alt=\"\" width=\"1925\" height=\"1125\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/12\/133787386_389638778766913_6499280195818049010_n.jpg 1925w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/12\/133787386_389638778766913_6499280195818049010_n-300x175.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/12\/133787386_389638778766913_6499280195818049010_n-1024x598.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/12\/133787386_389638778766913_6499280195818049010_n-768x449.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/12\/133787386_389638778766913_6499280195818049010_n-1536x898.jpg 1536w\" sizes=\"(max-width: 1925px) 100vw, 1925px\" \/><\/p>\n<p>L\u2019Istituto \u00e8 sul territorio di Lecce dal 1882 tuttavia trova le sue radici in un carisma che nasce nel milanese, dal suo fondatore Don Luigi Biraghi. Comprende la scuola dell\u2019infanzia, la scuola primaria e la scuola secondaria di primo e secondo grado.<\/p>\n<p>L\u2019offerta \u00e8 quella di poter compiere un percorso verticale: i bambini hanno la possibilit\u00e0 di muovere nell\u2019istituto i primi passi per poi essere pronti, dopo la maturit\u00e0, ad affrontare il mondo universitario e lavorativo. La peculiarit\u00e0 della scuola \u00e8 quella di <strong>valorizzare le caratteristiche e il talento di ciascun ragazzo<\/strong>, adattando il percorso curriculare alle inclinazioni dello studente.<\/p>\n<p>&nbsp;<\/p>\n<p>Lo <strong>studio delle lingue straniere<\/strong> \u00e8 la scriminante, la priorit\u00e0 dell\u2019istituto. Fin dall\u2019infanzia infatti c\u2019\u00e8 un\u2019attenzione particolare alla lingua inglese, che viene portata avanti fino alla maturit\u00e0, e ad essa dalla prima media viene affiancato lo studio di una seconda lingua a scelta tra spagnolo e francese. L\u2019istituto adotta dalla prima elementare i <strong>testi Cambridge<\/strong> e ad accompagnare la maestra durante le ore di lezione vi \u00e8 anche una <strong>madre lingua<\/strong>. \u00c8 possibile inoltre poter conseguire le certificazioni valide per dimostrare la conoscenza della lingua inglese.<\/p>\n<p>&nbsp;<\/p>\n<p>Da quest\u2019anno <strong>il liceo ha un taglio internazionale<\/strong> ed \u00e8 articolato in liceo classico e scientifico internazionale. Tale scelta \u00e8 dovuta al fatto di rendere i ragazzi \u201ccittadini del mondo\u201d e, di conseguenza, poter far acquisire loro le competenze necessarie che richiede la globalizzazione che stiamo vivendo nei tempi odierni. Gli studenti sono chiamati a scegliere un\u2019area caratterizzante tra classico e scientifico, sebbene vi siano <strong>materie comuni<\/strong> ad entrambi gli ambiti (italiano, storia, scienze ecc\u2026).<\/p>\n<p>Dal punto di vista didattico il liceo presenta delle <strong>novit\u00e0<\/strong>:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Nel piano curriculare dell\u2019<strong>area umanistica<\/strong>, oltre allo studio caratterizzante del greco, sono stati introdotti <strong>diritto ed economia<\/strong> come materie obbligatorie per rendere completa la formazione.<\/li>\n<li>Nell\u2019<strong>area scientifica <\/strong>invece vi \u00e8 il <strong>potenziamento di matematica e fisica<\/strong> e l\u2019introduzione del <strong>disegno tecnico in autocad<\/strong>: sin dal primo anno i ragazzi iniziano a tracciare le prime linee su un software utilizzato perlopi\u00f9 in ambito accademico.<\/li>\n<li>Sia nell\u2019ambito scientifico sia in quello classico, dal terzo anno <strong>obbligatoriamente<\/strong> \u00e8 prevista per gli studenti <strong>un\u2019ora a settimana di logica<\/strong> in modo tale da poter sviluppare il pensiero critico e poterli preparare in vista dei test universitari.<\/li>\n<li>Sia nell\u2019ambito scientifico sia in quello classico, i ragazzi potranno inserire una tra le seguenti <strong>materie a scelta<\/strong> in base alle proprie inclinazioni: <strong>cinese, francese, cinema e fotografia o robotica<\/strong>. Nel triennio invece cinema e fotografia vengono sostituiti dallo studio della <strong>letteratura mondiale e delle global perspectives<\/strong>.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Le ore di lezione sono da <strong>cinquanta minuti<\/strong> ciascuna ed \u00e8 prevista la <strong>settimana corta<\/strong>. Oltre al progetto intercultura, una chicca della scuola \u00e8 sicuramente la collaborazione con <strong>l\u2019Associazione Diplomatici<\/strong>: grazie a questo partenariato, nel 2019 alcuni studenti hanno potuto effettuare l\u2019alternanza scuola lavoro a New York per il progetto \u201cDemocracy\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019istituto, dunque, mira a formare uomini e donne capaci di vivere la \u201ccitt\u00e0 globale\u201d con un bagaglio adatto di competenze linguistiche-tecnologiche e dotati di pensiero critico, necessario per comprendere un mondo sempre pi\u00f9\u00a0eclettico e complesso al contempo.______<\/p>\n<p>(Chiunque fosse interessato a questa\u00a0 offerta formativa pu\u00f2 contattare il n. 0832-240020)<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/12\/28\/da-tre-anni-alla-maturita-pronti-per-entrare-nelluniversita-e-nel-mondo-del-lavoro-li-prendiamo-per-mano-a-uno-a-uno-il-percorso-verticale-delle-marcelline-raccontata-con-tutte-le-n\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/12\/28\/da-tre-anni-alla-maturita-pronti-per-entrare-nelluniversita-e-nel-mondo-del-lavoro-li-prendiamo-per-mano-a-uno-a-uno-il-percorso-verticale-delle-marcelline-raccontata-con-tutte-le-n\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>PRONTI PER ENTRARE IN UNIVERSITA&#8217; E NEL MONDO DEL LAVORO: &#8220;li prendiamo per mano a uno a uno&#8221;. &#8216;IL PERCORSO VERTICALE&#8217; DELLE MARCELLINE, RACCONTATO CON TUTTE LE NOVITA&#8217; DALLA RESPONSABILE, SUOR MONICA CERONI, E DAI PROFESSORI DELLA PRESTIGIOSA SCUOLA LECCESE &#8211; video di\u00a0Chiara Evangelista______ L\u2019istituto Marcelline si rinnova, adottando un taglio sempre pi\u00f9 internazionale e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":176700,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/176634"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=176634"}],"version-history":[{"count":10,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/176634\/revisions"}],"predecessor-version":[{"id":177213,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/176634\/revisions\/177213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/176700"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=176634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=176634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=176634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}