{"id":177197,"date":"2021-01-06T10:29:44","date_gmt":"2021-01-06T09:29:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=177197"},"modified":"2021-01-06T10:30:37","modified_gmt":"2021-01-06T09:30:37","slug":"177197","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/01\/06\/177197\/","title":{"rendered":"UN NUOVO AVVISTAMENTO DI UNA FOCA MONACA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-177198\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/01\/foca-monaca.jpg\" alt=\"\" width=\"719\" height=\"524\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/01\/foca-monaca.jpg 719w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/01\/foca-monaca-300x219.jpg 300w\" sizes=\"(max-width: 719px) 100vw, 719px\" \/>Riceviamo e volentieri pubblichiamo. Francesco De Pascalis, per conto dell&#8217; Area Marina Protetta di Porto Cesareo, ci manda il seguente comunicato______<\/p>\n<p>&nbsp;<\/p>\n<p>A tu per tu con la Foca Monaca (Monachus monachus). Un pescatore sportivo diportista, avvista e filma nella Zona A della Riserva Nazionale marina il mammifero.<\/p>\n<p>&nbsp;<\/p>\n<p>Eccezionale e spettacolare avvistamento nelle acque dell\u2019Area Marina Protetta Porto Cesareo di un esemplare di foca monaca. A realizzare le immagini \u00e8 stato Omar De Benedittis, pescatore diportista sportivo, che si trovava con suo natante nella Zona A dell\u2019Amp, praticamente il cuore della Riserva, in cui \u00e8 vietata qualunque tipo di attivit\u00e0 ad eccezione della ricerca scientifica. Emozionato ed incredulo, Omar dopo essersi accertato che si trattava proprio di uno splendido esemplare di mammifero, ha immediatamente avvertito ed allertato i biologi della Area Marina, che dopo un primo consulto ed un approfondimento sui comportamenti avuti dall\u2019animale ed altres\u00ec osservando lo stile della sua nuotata, hanno appurato che effettivamente si trattava di uno splendido esemplare di foca monaca, ritornata a solcare le acque dello Jonio cesarino.<\/p>\n<p>Appena appresa l\u2019ufficialit\u00e0 della notizia si \u00e8 detto entusiasta il direttore della Riserva Nazionale marina, il dottor Paolo D\u2019Ambrosio, che ha ringraziato Omar per aver offerto il materiale video e la sua collaborazione. \u201cSiamo di fronte alla documentazione filmata e reale, di un ritorno atteso da anni e di importanza rilevate. La foca monaca, infatti era scomparsa da tempo in diverse zone dal Mediterraneo, l\u2019ultimo avvistamento nelle acque di Porto Cesareo risale addirittura agli anni settanta. Un esemplare pescato in quel periodo e poi imbalsamato, fa mostra di se nel locale museo di Biologia Marina intitolato alla memoria del professor Pietro Parenzan. Poi -continua D\u2019Ambrosio- per tutta una serie di cause che vanno dall\u2019antropizzazione del litorale costiero sino alla minaccia per questa specie rappresentata da predatori senza scrupoli ne ha decretato, l\u2019allontanamento e la quasi estinzione.\u00a0Oggi\u00a0lo storico ritorno -sottolinea il biologo- testimoniato da incredibili immagini che ci riempiono di gioia e qualificano, qualora ve ne fosse ancora bisogno, l\u2019eccellente lavoro che si sta svolgendo da anni nell\u2019Amp Porto Cesareo. L\u2019insieme delle misure di conservazione unite alla fortissima attivit\u00e0 di sensibilizzazione ambientale attuata in diverse forme e modalit\u00e0, ha fatto accrescere in tutte le categorie che utilizzano la Riserva Marina Nazionale, dai pescatori ai residenti, dai diportisti agli imprenditori, dai turisti agli ambientalisti, un forte senso di rispetto oltre ad una presa di coscienza di uno sviluppo che sia soprattutto ecosostenibile. Un esempio per tutti, la sinergia e la cooperazione che ha portato, alla nidificazione prima ed alla nascita protetta poi, di ben 82 esemplari di tartaruga Caretta caretta, evento avvenuto la scorsa estate, in un tratto di costa in cui insite uno stabilimento privato che registra un\u2019altissima presenza di bagnanti. Ed\u00a0oggi\u00a0l\u2019ennesimo grande regalo della natura con il ritorno della foca monaca che torna a coesistere nelle nostre acque, in cui lo ribadisco \u2013 conclude D\u2019Ambrosio &#8211; Marina Protetta e le sue politiche giocano un ruolo davvero importante, utile e fondamentale per la conservazione naturale dei luoghi e delle specie che li popolano\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019importanza scientifica e naturalista dell\u2019avvistamento \u00e8 stata commentata anche dal professor Antonio Terlizzi, docente di zoologia e biologia marina presso l\u2019Universit\u00e0 di Trieste, e per 20 anni docente presso il Disteba di UniSalento oltre che responsabile per conto del Conisma di diversi progetti di gestione e valorizzazione dell\u2019efficacia dell\u2019Amp Porto Cesareo.<\/p>\n<p>\u201cLa foca monaca mediterranea\u00a0(Monachus monachus)\u00a0\u00e8 un mammifero pinnipede, unico rappresentante, in mediterraneo, della famiglia delle foche -spiega il docente-. Pu\u00f2 raggiungere i 300 kg di peso. Un tempo presente in tutto il Mediterraneo, ha visto rarefarsi la sua popolazione come conseguenza della frequentazione turistica delle coste e, soprattutto, della cattura e uccisione da parte dell\u2019uomo. Si nutre di pesci e cefalopodi. Alla fine del Novecento si considerava estinta in Italia. Pi\u00f9 di recente si \u00e8 assistito a segnalazioni nel basso adriatico e lungo le coste ioniche italiane, greche e albanesi. L\u2019ultima segnalazione in Salento \u00e8 di un cucciolo a Frigole che poi \u00e8 morto a Torre San Gennaro\u201d. Poi la raccomandazione importante del prof Terlizzi. \u201cQualora si dovesse avvistarla, non molestarla, non disturbarla, segnalare esclusivamente la presenza\u201d.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-177197-1\" width=\"640\" height=\"352\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/01\/WhatsApp-Video-2021-01-05-at-17.59.06-2.mp4?_=1\" \/><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/01\/WhatsApp-Video-2021-01-05-at-17.59.06-2.mp4\">https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/01\/WhatsApp-Video-2021-01-05-at-17.59.06-2.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p>_______<\/p>\n<p>LA RICERCA nei nostri articoli del 28 e del 30 gennaio 2020<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"Oq0bVJc5gX\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/01\/28\/la-triste-morte-di-apulia-una-cucciola-di-foca-salvata-per-poche-ore-e-gia-polemica-sui-social-abbiamo-ancora-molto-da-imparare-noi-umani-presuntuosi-e-arroganti\/\">LA TRISTE FINE DI &#8216;Apulia&#8217;, UNA CUCCIOLA DI FOCA, &#8220;SALVATA&#8221; SOLO PER POCHE ORE E CHE NON POTRA&#8217; RITORNARE NEL SUO MARE NEPPURE DA MORTA: FINIRA&#8217; IMBALSAMATA IN UN MUSEO. PER ADESSO DIVAMPA GIA&#8217; LA POLEMICA SUI SOCIAL: &#8220;Abbiamo ancora molto da imparare noi umani, presuntuosi e arroganti&#8221;<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/01\/28\/la-triste-morte-di-apulia-una-cucciola-di-foca-salvata-per-poche-ore-e-gia-polemica-sui-social-abbiamo-ancora-molto-da-imparare-noi-umani-presuntuosi-e-arroganti\/embed\/#?secret=Oq0bVJc5gX\" data-secret=\"Oq0bVJc5gX\" width=\"500\" height=\"282\" title=\"&#8220;LA TRISTE FINE DI &#8216;Apulia&#8217;, UNA CUCCIOLA DI FOCA, &#8220;SALVATA&#8221; SOLO PER POCHE ORE E CHE NON POTRA&#8217; RITORNARE NEL SUO MARE NEPPURE DA MORTA: FINIRA&#8217; IMBALSAMATA IN UN MUSEO. PER ADESSO DIVAMPA GIA&#8217; LA POLEMICA SUI SOCIAL: &#8220;Abbiamo ancora molto da imparare noi umani, presuntuosi e arroganti&#8221;&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"p5wWBjisGx\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/01\/30\/162593\/\">LA TRISTE FINE DI &#8220;Apulia&#8221;<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/01\/30\/162593\/embed\/#?secret=p5wWBjisGx\" data-secret=\"p5wWBjisGx\" width=\"500\" height=\"282\" title=\"&#8220;LA TRISTE FINE DI &#8220;Apulia&#8221;&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/01\/06\/177197\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/01\/06\/177197\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Francesco De Pascalis, per conto dell&#8217; Area Marina Protetta di Porto Cesareo, ci manda il seguente comunicato______ &nbsp; A tu per tu con la Foca Monaca (Monachus monachus). Un pescatore sportivo diportista, avvista e filma nella Zona A della Riserva Nazionale marina il mammifero. &nbsp; Eccezionale e spettacolare avvistamento nelle acque [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/177197"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=177197"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/177197\/revisions"}],"predecessor-version":[{"id":177201,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/177197\/revisions\/177201"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=177197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=177197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=177197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}