{"id":179075,"date":"2021-02-16T00:03:59","date_gmt":"2021-02-15T23:03:59","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=179075"},"modified":"2021-02-16T14:37:10","modified_gmt":"2021-02-16T13:37:10","slug":"la-rassegna-filosofica-dellunisalento-attenzione-ai-falsi-intellettuali-da-avorroe-ai-giorni-nostri-la-lezione-della-professoressa-fiorella-retucci","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/02\/16\/la-rassegna-filosofica-dellunisalento-attenzione-ai-falsi-intellettuali-da-avorroe-ai-giorni-nostri-la-lezione-della-professoressa-fiorella-retucci\/","title":{"rendered":"LA RASSEGNA FILOSOFICA DELL&#8217;UNISALENTO \/ Attenzione ai falsi intellettuali! DA AVORROE&#8217; AI GIORNI NOSTRI, LA LEZIONE  DELLA PROFESSORESSA FIORELLA RETUCCI"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-179076\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/02\/imm.-Retucci.jpg\" alt=\"\" width=\"609\" height=\"397\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/02\/imm.-Retucci.jpg 609w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/02\/imm.-Retucci-300x196.jpg 300w\" sizes=\"(max-width: 609px) 100vw, 609px\" \/>di <strong>Mariangela Rosato<\/strong>______<\/p>\n<p>Siamo giunti oramai al penultimo appuntamento, il decimo di quelli previsti nel programma, dell\u2019interessante rassegna on line dal titolo \u201c<em>Filosofica-mente, Riflessioni sul pensare e sull\u2019Agire<\/em>\u201d inerente il tema \u201c<em>Uomo e Civilt\u00e0<\/em>\u201d e organizzata dal Dipartimento di Filosofia dell\u2019Universit\u00e0 del Salento. Una rassegna, la cui positiva natura itinerante ha permesso di seguire ogni evento sormontando le difficolt\u00e0 legate al Covid e, soprattutto, le distanze geografiche.<\/p>\n<p>Ad intervenire nel corso dell\u2019incontro di ieri, \u00e8 stata <strong>Fiorella Retucci<\/strong> (nella foto), professoressa associata di storia della filosofia medioevale e presidente del forum accademico italiano, la quale ha dedicato la sua presentazione al civis nel Medioevo e alla sua dimensione universalistica.<\/p>\n<p>Numerosi sono i quesiti che hanno spinto la professoressa ad interessarsi a tale tematica in particolare quello legato al ruolo dell\u2019essere umano nella sua dimensione individuale e collettiva, nonch\u00e9 alla libert\u00e0 d\u2019azione del soggetto in qualit\u00e0 di cittadino.<\/p>\n<p>Domande queste, che potrebbero sembrare prive di fondamento se si guarda al Medioevo con le linee direttive offerte dai manuali di filosofia secondo le quali il Medioevo sarebbe un lungo periodo di oscurantismo e di involuzione in cui l\u2019individuo non \u00e8 attore della sua vita, bens\u00ec risulta sottomesso al disegno provvidenziale. \u201c<em>Ci si \u00e8 abituati per tali ragioni &#8211;<\/em>\u00a0afferma Retucci &#8211;\u00a0<em>ad immaginare il Medioevo per sottrazione. Numerosi sono, invece, gli autori medioevali che hanno una visione pi\u00f9 attiva dell\u2019individuo primo fra tutti Averro\u00e8 il quale identifica l\u2019essere umano con la sua razionalit\u00e0 e l\u2019intelletto<\/em>\u201d.<\/p>\n<p>La riflessione per Averro\u00e8 non ha un fine esclusivamente teoretico, ma presenta delle profonde ricadute sulla dimensione etica e politica. Per cui, la sapienza filosofica, ci dice Averro\u00e8, conduce l\u2019essere umano sia alla felicit\u00e0 intellettuale, sia al conseguimento della perfezione della vita morale che \u00e8 il presupposto della convivenza civile tra gli uomini. \u201c<em>Averro\u00e8 &#8211;\u00a0<\/em>specifica la professoressa &#8211;\u00a0<em>va ancora pi\u00f9 in l\u00e0 affermando che i falsi amanti della sapienza utilizzano la filosofia senza conoscerne la vera natura e sono da considerarsi come dei veri nemici pubblici<\/em>\u201d. Citando le parole di Averro\u00e8, Retucci continua: \u201c<em>i falsi intellettuali sono pi\u00f9 pericolosi degli uomini ignoranti perch\u00e9 con loro non si possono assolutamente creare dei rapporti di convivenza civile e non si pu\u00f2 fare alcuna forma di contratto in quanto tutte le loro orazioni sono rivolte al loro utile<\/em>\u201d.<\/p>\n<p>Una lettura che d\u00e0 ampio spazio alla razionalit\u00e0 e all\u2019azione individuale la ritroviamo anche in altri autori medioevali come Tommaso di York, il quale, cos\u00ec come Averro\u00e8, democraticizza l\u2019accesso alla razionalit\u00e0 estendendola a tutti gli uomini sia in una dimensione etica che collettiva: \u201c<em>per questi autori quindi\u00a0<\/em><em>non c\u2019\u00e8 bisogno di un\u2019educazione civica per fare dell\u2019uomo un buon cittadino, perch\u00e9 la vera natura dell\u2019uomo \u00e8 gi\u00e0 garanzia ontologica che permette agli uomini di essere pieni cittadini<\/em>.<\/p>\n<p>L\u2019incontro si conclude con una serie di domande , rispondendo alle quali\u00a0 la professoressa ha maggiormente chiarito alcuni aspetti del suo intervento, tra cui l\u2019idea del falso intellettuale: \u201c<em>a volte\u00a0<\/em><em>mi sembra di trovarmelo di fronte il falso intellettuale. Come si fa a riconoscerlo? Forse c\u2019\u00e8 una strada: il vero amante della sapienza non pu\u00f2 essere solo un teoretico, ma deve essere qualcuno che mette anche in pratica dal punto di vista etico e agisce nell\u2019ambito politico, in conformit\u00e0 a quelle che sono le conclusioni teoretiche. Il vero intellettuale, quindi, tiene sempre uniti tutti e tre gli aspetti. Un elemento senza l\u2019altro fa dell\u2019intellettuale un falso intellettuale<\/em>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/02\/16\/la-rassegna-filosofica-dellunisalento-attenzione-ai-falsi-intellettuali-da-avorroe-ai-giorni-nostri-la-lezione-della-professoressa-fiorella-retucci\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/02\/16\/la-rassegna-filosofica-dellunisalento-attenzione-ai-falsi-intellettuali-da-avorroe-ai-giorni-nostri-la-lezione-della-professoressa-fiorella-retucci\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; di Mariangela Rosato______ Siamo giunti oramai al penultimo appuntamento, il decimo di quelli previsti nel programma, dell\u2019interessante rassegna on line dal titolo \u201cFilosofica-mente, Riflessioni sul pensare e sull\u2019Agire\u201d inerente il tema \u201cUomo e Civilt\u00e0\u201d e organizzata dal Dipartimento di Filosofia dell\u2019Universit\u00e0 del Salento. Una rassegna, la cui positiva natura itinerante ha permesso di seguire [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":179076,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/179075"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=179075"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/179075\/revisions"}],"predecessor-version":[{"id":179077,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/179075\/revisions\/179077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/179076"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=179075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=179075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=179075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}