{"id":17927,"date":"2013-06-19T21:18:41","date_gmt":"2013-06-19T21:18:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=17927"},"modified":"2013-06-19T21:18:41","modified_gmt":"2013-06-19T21:18:41","slug":"rifiuti-e-igiene-sulle-spiaggie-il-comune-le-pulira","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/06\/19\/rifiuti-e-igiene-sulle-spiaggie-il-comune-le-pulira\/","title":{"rendered":"RIFIUTI E IGIENE SULLE SPIAGGIE&#8230;IL COMUNE LE PULIR\u00c0?"},"content":{"rendered":"<p>Calendarizzati tutti gli interventi dell\u2019Assessorato alle Politiche Ambientale nelle marine\u00a0Torre Chianca,\u00a0Frigole,\u00a0Spiaggia Bella\u00a0e\u00a0Torre Rinalda.<\/p>\n<p>Spiagge pulite e sanificazione urbana.\u00a0Sono queste le priorit\u00e0 immediate dell\u2019Assessorato alle Politiche Ambientali del Comune per\u00a0l\u2019avvio della stagione estiva. E\u2019 ripreso ieri, infatti, il servizio di pulizia degli arenili del litorale del comune di Lecce mentre \u00e8 previsto per domani l\u2019avvio degli interventi di\u2028disinfestazione anti-larva e anti-alato, derattizzazione, deblattizzazione, antipulci e anti-zecche sia in citt\u00e0 sia nelle marine.<\/p>\n<p>Saranno ben 55 interventi meccanizzati e 6 interventi manuali quelli calendarizzati dal comune per le spiagge leccesi, riguarderanno\u00a0Torre Chianca,\u00a0Frigole,\u00a0Spiaggia Bella\u00a0e\u00a0Torre Rinalda\u00a0e si protrarranno con regolarit\u00e0 fino al 14 settembre prossimo.\u00a0Nelle operazioni di ieri, seguite personalmente dall\u2019assessore\u00a0Andrea Guido, sono stati impegnati gli addetti delle ditte\u00a0Icos\u00a0e\u00a0Bios\u00a0il cui compito \u00e8 stato quello di ripulire le spiagge da rifiuti di vario genere (in buona parte residui delle mareggiate degli ultimi mesi).<\/p>\n<p>\u201cVogliamo che la citt\u00e0, le nostre spiagge e le nostre marine\u00a0&#8211;\u00a0dichiara l\u2019assessore all\u2019Ambiente\u00a0Andrea Guido\u00a0&#8211;\u00a0si presentino salubri e pulite affinch\u00e9 i nostri concittadini ma anche i turisti e i visitatori possano trovare un litorale decoroso e attraente\u00bb,\u00a0, lanciando un appello a\u00a0non sporcare le spiagge e differenziare il pi\u00f9 possibile i rifiuti ma, soprattutto, a dare una mano all\u2019Amministrazione Comunale contribuendo con il proprio comportamento a non vanificare gli sforzi effettuati\u201d.<\/p>\n<p>\u201cSi tratta di fare attenzione ai piccoli gesti quotidiani\u201d \u2013\u00a0continua Guido\u00a0\u2013 \u201cdi non di trascurare piccole cose come la stecchetta di gelato o la cicca di sigaretta che, se insabbiate, ad esempio, con i loro tempi di biodegradabilit\u00e0 naturale, rimarranno nell\u2019ambiente per moltissimi anni avvenire. Dobbiamo comprendere che questi piccoli comportamenti incivili, se moltiplicati per gli innumerevoli cittadini e turisti \u2018distratti\u2019, portano a considerevoli danni di carattere ecologico ambientale\u201d.<\/p>\n<p>\u201cDa domani\u201d \u2013\u00a0prosegue Guido\u00a0\u2013 \u201csar\u00e0 dato il via anche alle disinfestazioni in citt\u00e0 e nelle marine. Gli interventi si protrarranno fino a novembre inoltrato e riguarderanno, oltre la\u00a0derattizzazione, deblattizzazione, antipulci e anti-zecche, anche e soprattutto, le disinfestazione anti-larva e anti-alato. Gi\u00e0 da qualche anno, infatti, la\u00a0presenza delle zanzare, non pi\u00f9 limitata alla sola stagione estiva \u2013continua l\u2019assessore comunale\u00a0&#8211;\u00a0rappresenta un fenomeno in recrudescenza, provocato essenzialmente dal cambiamento delle condizioni climatiche, da quella che gli esperti definiscono tropicalizzazione.\u00a0Debellare la presenza delle zanzare a Lecce, quindi, \u00e8 impossibile. Il problema c\u2019\u00e8 e rimarr\u00e0, si tratta solamente di lavorare d\u2019anticipo per contenerlo il pi\u00f9 possibile. E di seguire alcune semplici regole che ci aiuteranno a prevenirlo adeguatamente\u201d.<\/p>\n<p>\u201cQueste\u00a0le raccomandazioni \u2013\u00a0conclude\u00a0Andrea Guido\u00a0&#8211; che ho il dovere di fare ai leccesi e che, assicuro, possono rappresentare un valido aiuto a sostegno degli interventi a carattere chimico e tecnologico da noi programmati:<\/p>\n<div>\n<div>\u2022<\/div>\n<div>fondamentale, per le aziende private che operano sul territorio comunale e per i cittadini, provvedere ad eliminare tutti i possibili ristagni d\u2019acqua, limitando cos\u00ec la proliferazione di esemplari;<\/div>\n<\/div>\n<div>\n<div>\u2022<\/div>\n<div>fare attenzione a non abbandonare contenitori di qualsiasi forma e dimensione in spazi aperti pubblici e privati, compresi terrazzi e balconi, ed in qualsiasi luogo in cui possa verificarsi raccolta di acqua piovana;<\/div>\n<\/div>\n<div>\n<div>\u2022<\/div>\n<div>mantenere in perfetta efficienza le grondaie o i tombini presenti nei giardini o negli spazi condominiali;<\/div>\n<\/div>\n<div>\n<div>\u2022<\/div>\n<div>pulire bene vasi e sottovasi prima di collocarli all\u2019interno delle abitazioni;<\/div>\n<\/div>\n<div>\n<div>\u2022<\/div>\n<div>convogliare in appositi apparati di scarico la condensa prodotta dagli impianti di climatizzazione<span style=\"font-family: Times\">\u201d.<\/span><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/06\/19\/rifiuti-e-igiene-sulle-spiaggie-il-comune-le-pulira\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/06\/19\/rifiuti-e-igiene-sulle-spiaggie-il-comune-le-pulira\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Calendarizzati tutti gli interventi dell\u2019Assessorato alle Politiche Ambientale nelle marine\u00a0Torre Chianca,\u00a0Frigole,\u00a0Spiaggia Bella\u00a0e\u00a0Torre Rinalda. Spiagge pulite e sanificazione urbana.\u00a0Sono queste le priorit\u00e0 immediate dell\u2019Assessorato alle Politiche Ambientali del Comune per\u00a0l\u2019avvio della stagione estiva. E\u2019 ripreso ieri, infatti, il servizio di pulizia degli arenili del litorale del comune di Lecce mentre \u00e8 previsto per domani l\u2019avvio degli [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/17927"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=17927"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/17927\/revisions"}],"predecessor-version":[{"id":17929,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/17927\/revisions\/17929"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=17927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=17927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=17927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}