{"id":17996,"date":"2013-06-22T07:59:13","date_gmt":"2013-06-22T07:59:13","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=17996"},"modified":"2013-06-22T07:59:13","modified_gmt":"2013-06-22T07:59:13","slug":"otranto-denunciato-professionista","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/06\/22\/otranto-denunciato-professionista\/","title":{"rendered":"OTRANTO: DENUNCIATO PROFESSIONISTA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/guardiafinanza2-400x215.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/guardiafinanza2-400x215-300x161.jpg\" alt=\"\" width=\"300\" height=\"161\" class=\"alignleft size-medium wp-image-15953\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/guardiafinanza2-400x215-300x161.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/guardiafinanza2-400x215.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>I Finanzieri della Compagnia di Otranto hanno eseguito una verifica fiscale nei confronti di un architetto, il quale, nel presentare le dichiarazioni annuali dei redditi, IVA ed IRAP per gli anni dal 2008 al 2012, ha sottratto a tassazione, complessivamente, ricavi per oltre 2 milioni e 300mila euro ed evaso IVA per oltre 250mila euro.<\/p>\n<p>L\u2019attivit\u00e0 operativa ha preso le mosse da una segnalazione dei militari della Sezione Operativa Navale di Otranto, che, nell\u2019ambito del controllo economico del territorio finalizzato all\u2019individuazione di beni indicativi di capacit\u00e0 contributiva, avevano rilevato i dati di un\u2019imbarcazione da diporto, del valore di circa 100.000 euro, ormeggiata nel porto idruntino, intestata al professionista.<\/p>\n<p>I successivi approfondimenti avevano fatto emergere la precedente titolarit\u00e0 di altra analoga imbarcazione del valore di oltre 600.000 euro.<\/p>\n<p>L\u2019analisi degli elementi cos\u00ec acquisiti, ad opera dei militari della Compagnia della Guardia di Finanza di Otranto, evidenziava l\u2019evidente e significativa sproporzione tra la manifestata capacit\u00e0 contributiva e i redditi esposti in dichiarazione dal medesimo professionista.<\/p>\n<p>Infatti, al termine dell\u2019articolata attivit\u00e0 a carattere fiscale, protrattasi per quasi un anno, confortata anche dall\u2019esito di complesse \u201cindagini finanziarie\u201d, le Fiamme Gialle sono riuscite a quantificare quanto nascosto al Fisco.<\/p>\n<p>Inoltre, i Finanzieri hanno denunciato il professionista alla Procura della Repubblica di Lecce per le violazioni alla normativa penale tributaria, con riferimento alle dichiarazioni infedeli e all\u2019occultamento di documenti contabili.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/06\/22\/otranto-denunciato-professionista\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/06\/22\/otranto-denunciato-professionista\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I Finanzieri della Compagnia di Otranto hanno eseguito una verifica fiscale nei confronti di un architetto, il quale, nel presentare le dichiarazioni annuali dei redditi, IVA ed IRAP per gli anni dal 2008 al 2012, ha sottratto a tassazione, complessivamente, ricavi per oltre 2 milioni e 300mila euro ed evaso IVA per oltre 250mila euro. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15953,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/17996"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=17996"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/17996\/revisions"}],"predecessor-version":[{"id":17998,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/17996\/revisions\/17998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/15953"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=17996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=17996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=17996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}