{"id":180857,"date":"2021-03-25T17:47:06","date_gmt":"2021-03-25T16:47:06","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=180857"},"modified":"2021-03-25T17:47:06","modified_gmt":"2021-03-25T16:47:06","slug":"il-travel-influencer-per-la-promozione-del-turismo-post-covid","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/03\/25\/il-travel-influencer-per-la-promozione-del-turismo-post-covid\/","title":{"rendered":"IL TRAVEL INFLUENCER PER LA PROMOZIONE DEL TURISMO POST COVID"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-180858\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/03\/travel-influencer-promozione-turismo.jpg\" alt=\"\" width=\"1280\" height=\"854\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/03\/travel-influencer-promozione-turismo.jpg 1280w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/03\/travel-influencer-promozione-turismo-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/03\/travel-influencer-promozione-turismo-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/03\/travel-influencer-promozione-turismo-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>Non \u00e8 un mistero che i blog siano una realt\u00e0 concreta e un fenomeno che sta facendo sempre pi\u00f9 tendenza. In un mondo che fa maggiormente uso del digitale, anche in seguito all&#8217;emergenza sanitaria causata dal COVID-19, stanno nascendo vere e proprie nuove forme di business: una di queste \u00e8 il <strong>travel blogging<\/strong>. Negli ultimi anni si \u00e8, infatti, diffusa la professione del travel influencer che comunica con il suo pubblico anche attraverso il blog (oltre che ai social): una professione che garantisce una particolare unione tra piacere di viaggiare e guadagno.<\/p>\n<p>Il <strong><em><a href=\"https:\/\/www.milanofinanza.it\/news\/digitale-una-sfida-ad-ostacoli-2459238\">boom dei blog dedicati ai viaggi<\/a><\/em><\/strong> si deve sicuramente al web 2.0, poich\u00e9 gli utenti non si limitano pi\u00f9 ad assumere semplicemente il ruolo passivo di consumatori, ma partecipano attivamente. Infatti, \u00e8 emerso che gli under 35 (in percentuale, il 35%) sono interessati a condividere la propria esperienza di viaggio online e fanno largo uso delle recensioni online per pianificare i propri viaggi (in percentuale, il 74%). Inoltre, una ricerca ha evidenziato che le parole chiave &#8220;<strong>web turismo<\/strong>&#8221; e &#8220;<strong>blog viaggi<\/strong>&#8221; hanno raggiunto negli ultimi anni volumi di ricerca pari a +36% e +29% nell&#8217;arco di un mese.<\/p>\n<p><strong>Come iniziare un progetto professionale come travel blogger<\/strong><\/p>\n<p>Se si \u00e8 interessati a inserirsi in questo settore in maniera professionale, ci sono vari strumenti e conoscenze che \u00e8 importante apprendere affinch\u00e9 il proprio blog di viaggi diventi un vero e proprio lavoro. Non solo si avr\u00e0 bisogno dell&#8217;attrezzatura adeguata (fotocamera e\/o videocamera, treppiedi, trolley professionali, powerbank da viaggio, ecc.), ma anche di programmi professionali (software di editing foto e video) e competenze informatiche e di comunicazione.<\/p>\n<p><strong>Consigli pratici per diventare travel influencer: cosa occorre sapere e avere<\/p>\n<p><\/strong>Per quanto riguarda le <strong>conoscenze di marketing fondamentali<\/strong>, sar\u00e0 importante conoscere:<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/wordpress.com\/it\/create-website\/\">WordPress<\/a><\/strong>, un importante software che consente di creare siti web e blog: \u00e8 disponibile sia gratuitamente che a pagamento (alcuni layout grafici e alcuni plug-in). Bisogner\u00e0 acquistare un <strong>dominio<\/strong> (l&#8217;URL che viene visualizzato nella barra di ricerca dei browser) e l&#8217;<strong>hosting <\/strong>(il server che contiene tutti i contenuti di un sito web). Con WordPress si pu\u00f2 personalizzare il blog in modo abbastanza semplice: baster\u00e0 scegliere e personalizzare con colori e immagini il tema pi\u00f9 adatto. I diversi layout si possono visualizzare e scaricare direttamente dentro il software.<\/li>\n<li>La <strong>SEO<\/strong>, ovvero l&#8217;ottimizzazione dei contenuti finalizzata a migliorare il <strong>posizionamento<\/strong> nei risultati organici dei motori di ricerca come Google (SERP). Questa disciplina afferente al digital marketing, ha come base la scelta di una o pi\u00f9 <strong>parole chiave<\/strong> da inserire opportunamente nel testo di ogni articolo di blog (ma anche sui social e su alcune sezioni del sito). Dopo aver scelto delle <strong><em>keywords<\/em><\/strong> accattivanti, che abbiano un <strong>volume di ricerca<\/strong> abbastanza elevato e abbiano una <strong>bassa concorrenza<\/strong> (per iniziare \u00e8 importante scegliere delle parole chiave a coda lunga, ovvero composte da pi\u00f9 parole, e non scontate, affinch\u00e9 il sito non debba confrontarsi con dei <em>competitor<\/em> gi\u00e0 affermati), l&#8217;articolo andr\u00e0 <strong>suddiviso in paragrafi<\/strong>, i quali dovranno avere dei <strong>sottotitoli<\/strong>. Ogni titolo, sia quello principale che i sottotitoli, dovranno contenere la parola chiave principale. Trattandosi di un blog di viaggi \u00e8 importante inserire anche delle <strong>immagini ottimizzate<\/strong> con la parola chiave, ovvero il <strong>tag alt<\/strong> (il testo alternativo) dovr\u00e0 contenere la <em>keyword<\/em>. Non bisogna dimenticare di inserire anche una <strong>meta description<\/strong> interessante che spinga l&#8217;utente ad aprire l&#8217;articolo: dovr\u00e0 essere breve, per evitare che Google tagli le parole, ovvero comprendere tra i 160 e i 320 caratteri massimo. A questo proposito, WordPress mette a disposizione un plug-in, <strong>Yoast SEO<\/strong>, che consente di monitorare l&#8217;andamento della propria SEO basica e fornisce una lista dettagliata di cosa migliorare negli articoli. Per progetti molto avanzati, che sono diventati veri e propri business competitivi, il salto di qualit\u00e0 si ottiene rivolgendosi a un consulente SEO, per strategie pi\u00f9 tecniche e avanzate.<\/li>\n<li><strong>Promozione del blog<\/strong>: la promozione \u00e8 mirata a farsi leggere e ad <strong>aumentare il traffico<\/strong> sul sito, affinch\u00e9 gli utenti possano conoscere e apprezzare il progetto di travel blogging. Oltre all&#8217;ottimizzazione SEO che cresce in maniera organica, ci sono tantissimi strumenti a pagamento in grado di far ottenere a un sito un posizionamento migliore nelle SERP. Notissimi sono i <strong>banner pubblicitari<\/strong> o le sponsorizzazioni su Google e sui social dei singoli articoli; interessanti anche le tecniche di email marketing, come l&#8217;invio di newsletter periodiche. Ovviamente, chiunque voglia avviare un&#8217;attivit\u00e0 di successo deve considerare di creare delle <strong>pagine social<\/strong>, per esempio su Instagram o su Facebook, dove il visual marketing tipico di foto, vlog e video di viaggi ha maggiore impatto e target in linea.<\/li>\n<\/ul>\n<p>Gli <strong>strumenti professionali <\/strong>per avviare una carriera da travel blogger di cui si avr\u00e0 bisogno sono:<\/p>\n<ul>\n<li>Una <strong>fotocamera <\/strong>di qualit\u00e0 o un <strong>cellulare con fotocamera potente<\/strong>: la parte foto e video \u00e8 estremamente importante per chi voglia diventare travel influencer. Per questo motivo \u00e8 fondamentale avere a disposizione dei dispositivi adeguati. Le scelte, per quanto riguarda la fotocamera, possono ricadere su una <strong>Reflex<\/strong>, capace di generare scatti di alta qualit\u00e0, o una <strong>Mirrorless<\/strong>, pi\u00f9 compatta e maneggevole, o ancora una <strong>Action cam<\/strong>, adatta alle riprese in movimento. Da non sottovalutare anche i cellulari che stanno diventando sempre pi\u00f9 sofisticati: bisogner\u00e0 optare per smartphone che registrino in <strong>4K<\/strong> e che possano scattare foto a partire da <strong>12MP<\/strong>.<\/li>\n<li>Un <strong>software di editing foto e video<\/strong>: strumento estremamente importante per fare di un blog una vera e propria professione. Saper <strong>montare video<\/strong> \u00e8 un requisito fondamentale per un travel influencer ed \u00e8 altrettanto basilare avere a disposizione un <strong>programma<\/strong> affidabile e di qualit\u00e0 (qui consigli specifici sui <strong>migliori video editor<\/strong>: <a href=\"http:\/\/www.movavi.com\/it\/learning-portal\/migliori-video-editor-gratuiti.html\">www.movavi.com\/it\/learning-portal\/migliori-video-editor-gratuiti.html<\/a>).<\/li>\n<li>Un <strong>powerbank da viaggio: <\/strong>per non rimanere mai con la batteria a zero e non perdere nemmeno un attimo o non trovarsi privi di mappe online, servizi di emergenza e dati memorizzati 8anche di pagamento). Si consiglia l&#8217;acquisto di un powerbank che abbia una capacit\u00e0 di almeno <strong>30.000 mAh<\/strong>, altrimenti sar\u00e0 bene avere sempre con s\u00e9 almeno due powerbank da <strong>15.000 mAh<\/strong>.<\/li>\n<li>Tante <strong>schedine di memoria<\/strong>: le <strong>schede SD<\/strong> sono un bene essenziale per un travel influencer, poich\u00e9 \u00e8 probabile che durante i propri viaggi e le proprie esperienze si abbia necessit\u00e0 di registrare o fotografare numerose volte. Dunque, si consiglia di avere sempre almeno 3 o 4 <strong>schede SD<\/strong> da almeno <strong>128 GB<\/strong>, per contenere adeguatamente i file di alta qualit\u00e0 degli strumenti posseduti.<\/li>\n<li>Un <strong>treppiede<\/strong> e uno <strong>stabilizzatore<\/strong>: questi due accessori sono essenziali per registrare immagini di qualit\u00e0. Il <strong>treppiede<\/strong>, che sia per fotocamera o per smartphone, \u00e8 la base per ciascun travel influencer. Lo <strong>stabilizzatore<\/strong> si rende uno strumento necessario, poich\u00e9 consente di registrare video di alto livello anche mentre si cammina.<\/li>\n<\/ul>\n<p>Per <a href=\"https:\/\/www.vanityfair.it\/viaggi-traveller\/notizie-viaggio\/2017\/11\/15\/professione-travel-influencer\">iniziare un progetto professionale come <strong>travel influencer<\/strong><\/a> occorre essere ben attrezzati e studiare un po&#8217; di tecniche di comunicazione digitale che possano far conoscere il proprio blog e far aumentare il traffico.<\/p>\n<p>\u00c8 poi importante <strong>creare un<\/strong> <strong>proprio stile<\/strong>, sia di scrittura che grafico, e impegnarsi per farlo diventare familiare agli utenti del web. L&#8217;unicit\u00e0 \u00e8 la chiave per il successo, poich\u00e9 la concorrenza \u00e8 alta e l&#8217;utenza si aspetta contenuti sempre nuovi e aggiornati. Non bisogna dimenticare che la promozione di un blog non avviene solo tramite servizi a pagamento, ma anche a livello organico, quindi sar\u00e0 importante curare sempre nei minimi dettagli gli articoli da pubblicare, facendo attenzione al lessico e a comprendere ci\u00f2\u00a0che il target di riferimento si aspetta e desidera leggere.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/03\/25\/il-travel-influencer-per-la-promozione-del-turismo-post-covid\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/03\/25\/il-travel-influencer-per-la-promozione-del-turismo-post-covid\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Non \u00e8 un mistero che i blog siano una realt\u00e0 concreta e un fenomeno che sta facendo sempre pi\u00f9 tendenza. In un mondo che fa maggiormente uso del digitale, anche in seguito all&#8217;emergenza sanitaria causata dal COVID-19, stanno nascendo vere e proprie nuove forme di business: una di queste \u00e8 il travel blogging. Negli ultimi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":180858,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/180857"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=180857"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/180857\/revisions"}],"predecessor-version":[{"id":180859,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/180857\/revisions\/180859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/180858"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=180857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=180857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=180857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}