{"id":18180,"date":"2013-06-26T10:18:26","date_gmt":"2013-06-26T10:18:26","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=18180"},"modified":"2013-06-26T10:18:26","modified_gmt":"2013-06-26T10:18:26","slug":"day-off-music-festival-al-parco-gondar","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/06\/26\/day-off-music-festival-al-parco-gondar\/","title":{"rendered":"DAY OFF MUSIC FESTIVAL AL PARCO GONDAR"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/06\/Skunk-Anansie.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/06\/Skunk-Anansie-300x196.jpg\" alt=\"\" width=\"300\" height=\"196\" class=\"alignleft size-medium wp-image-18181\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/06\/Skunk-Anansie-300x196.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/06\/Skunk-Anansie.jpg 591w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Il \u201cDAY OFF FESTIVAL 2013\u201d, il mega evento di Ferragosto del PARCO GONDAR con headliner gli SKUNK ANANSIE, per la prima volta live in Puglia e unica data del sud Italia, si completa con un cast di grandi nomi della scena internazionale: Crookers, Pendulum dj set, Miss Kittin dj set e Andro i.d.!<\/p>\n<p>Un evento unico nel suo genere, che presenter\u00e0 4 festival in contemporanea sui 4 palchi tematici, sviluppati nella splendida cornice del PARCO GONDAR: il Main Stage, il D&amp;B Stage, l\u2019Electro Stage e il Techno Stage.<\/p>\n<p>Ad aprire e chiudere gli show delle star internazionali, il top della scena pugliese con i concerti live dei The Monkey Weater, I Misteri del Sonno, Grace e i dj set con Dj Skizzo, Nerve, Ballarock DjSet, 2DNoize, Dj Mike, Hubdy Pole.<\/p>\n<p>Dal tardo pomeriggio fino alla mattina del giorno successivo, 10 ore di grande spettacolo, tra musica e coreografiche performance, saranno la caratteristica dell\u2019appuntamento pi\u00f9 atteso del ferragosto italiano.<\/p>\n<p>\u00c8 gi\u00e0 possibile acquistare i biglietti presso i circuiti ParcoGondar, Bookingshow, Salentoconcerti e TicketOne al costo di soli 27 \u20ac + d.p.. La cifra si conferma come il biglietto pi\u00f9 basso tra le date italiane del &#8220;Black Traffic Tour 2013&#8221; di Skin e soci: soli 27\u20ac per un\u2019esperienza unica, comprensiva di tutti gli spettacoli della serata, sia per il main stage che per le altre aree del parco.<\/p>\n<p>Ancora una volta PARCO GONDAR continua a sposare la politica dei grandi eventi ai prezzi pi\u00f9 bassi, con i migliori artisti internazionali per un pubblico sempre pi\u00f9 vasto.<\/p>\n<p>L&#8217;evento \u00e8 presentato da Parco Gondar, Day Off Agency, Public Group e Musica&amp;Parole.<\/p>\n<p>CENNI BIOGRAFICI line up<\/p>\n<p>Gli Skunk Anansie, guidati dalla carismatica Skin, rappresentano una delle massime espressioni della scena rock mondiale, autori di pezzi storici come Hedonism, Charlie Big Potato, Secretely, solo per citarne alcuni. Lo scorso 25 settembre ha pubblicato &#8220;Black Traffic&#8221;, quinto album di inediti della loro discografia &#8211; e il secondo dopo la reunion del 2009 \u2013 accolto come sempre da grande clamore, si \u00e8 classificato da subito ai primi posti delle classifiche internazionali, soprattutto in Italia, che si conferma uno dei paesi in cui la band ha maggiore appeal, dove ha raggiunto il secondo posto in classifica.<\/p>\n<p>Crookers rappresenta la punta di diamante di quella nuova scena che fonde suoni elettronici e house influenzati dalla cultura hip hop. Originariamente composto da due membri, \u00e8 noto in tutto il mondo per aver sviluppato negli anni uno stile personale, fatto di sample, casse tonanti e bassi giga. Il talento di Crookers, alias Francesco &#8220;Phra&#8221; Barbaglia, attuale e unico componente del progetto, \u00e8 quello di aver caratterizzato, con le sue produzioni e i suoi remix, alcune tra le tracce pi\u00f9 famose ed influenti degli ultimi tempi, collaborando con artisti del calibro di Timbaland, Armand Van Helden, Britney Spears, The Chemical Brothers e molti altri, inclusa la hit mondiale: il remix di &#8220;Day N Nite&#8221; di Kid Cudi.<\/p>\n<p>I Pendulum sono la fusione tra rock elettronico e drum\u2019n\u2019bass, che partiti dall\u2019Australia hanno conquistato il mondo dando fama e notoriet\u00e0 al drumm\u2019n\u2019bass spaziando al contempo tra trance, breakbeat e dub. Hanno calcato i palchi di tutto il mondo, sia che si tratti di live o di djset, trasmettono nei loro show tutta la loro carica ed energia, coinvolgendo il pubblico in un set scatenato e imperdibile.<\/p>\n<p>Miss Kittin , cantante, musicista, deejay elettronica francese (vero nome Caroline Herv\u00e9) \u00e8 tra gli esponenti di maggior successo dell\u2019elettroclash. Il suo nuovo album, Calling From The Stars, pubblicato lo scorso 19 aprile, contiene, tra le altre tracce, una sorprendente cover di Everybody Hurts dei R.E.M. Miss Kittin passa dalle collaborazioni con Sven Vath, Felix Da Housecat, The Hacker o T. Raumschmiere ai passaggi quasi punk di I Com, dalle pi\u00f9 recenti collaborazioni con Kris Menace alle serate come deejay.<\/p>\n<p>Andro i.d. racchiude l\u2019identit\u00e0 dance ed elettronica di Andrea Mariano, gi\u00e0 tastierista dei Negramaro, la rock band pi\u00f9 importante nel panorama italiano. Molti i warm up ai concerti di artisti come The Prodigy, Chemical Brothers, Jeff Mills, Dj Hell, occasioni in cui Andro. i.d. si esibisce in un mix carico e coinvolgente di musica elettronica dalle forti atmosfere techno, house, tribal e funk.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/06\/26\/day-off-music-festival-al-parco-gondar\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/06\/26\/day-off-music-festival-al-parco-gondar\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il \u201cDAY OFF FESTIVAL 2013\u201d, il mega evento di Ferragosto del PARCO GONDAR con headliner gli SKUNK ANANSIE, per la prima volta live in Puglia e unica data del sud Italia, si completa con un cast di grandi nomi della scena internazionale: Crookers, Pendulum dj set, Miss Kittin dj set e Andro i.d.! Un evento [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18181,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18180"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=18180"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18180\/revisions"}],"predecessor-version":[{"id":18183,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18180\/revisions\/18183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/18181"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=18180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=18180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=18180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}