{"id":182683,"date":"2021-05-05T00:17:22","date_gmt":"2021-05-04T22:17:22","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=182683"},"modified":"2021-05-05T09:38:29","modified_gmt":"2021-05-05T07:38:29","slug":"il-discorso-di-fedez-smontato-pezzo-per-pezzo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/05\/il-discorso-di-fedez-smontato-pezzo-per-pezzo\/","title":{"rendered":"IL DISCORSO DI FEDEZ SMONTATO PEZZO PER PEZZO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-182690\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/fedez-amodeo.jpg\" alt=\"\" width=\"1358\" height=\"712\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/fedez-amodeo.jpg 1358w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/fedez-amodeo-300x157.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/fedez-amodeo-1024x537.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/fedez-amodeo-768x403.jpg 768w\" sizes=\"(max-width: 1358px) 100vw, 1358px\" \/>https:\/\/www.radioradio.it\/2021\/05\/discorso-fedez-messaggio-subdolo-nascosto-amodeo\/<\/p>\n<p>gm______Francesco Amedeo, autore del Libro la Matrix Europea \u00e8 uno degli scrittori pi\u00f9 interessanti che abbiamo in Italia, perch\u00e9 \u00e8 un giornalista controcorrente ma sopratutto perch\u00e9 con le sue inchieste e i suoi libri ha denunciato quelle che sono le manovre ai danni dell&#8217;Italia da parte di Multinazionali, Burocrazia Europea e Alta Finanza.<\/p>\n<p>Questa volta interviene sul comizio di Fedez, che in un contesto diverso nessuno avrebbe preso in considerazione. Egli ha per\u00f2 utilizzato uno spazio unico come quello che la Rai gli ha messo a disposizione, ossia il Palco del Concertone del Primo Maggio, manifestazione pagata dalla RAI con i soldi dei cittadini(600.000 euro), per fare un comizio politico senza contraddittorio.<\/p>\n<p>Come minimo una risposta va data anche se non abbiamo a disposizione quella platea mediatica.<\/p>\n<p>Alla Festa del Primo Maggio ci si aspetterebbe che si parlasse di lavoro e delle problematiche ad esso connesse.<\/p>\n<p>Per esempio ci saremmo aspettato che si parlasse dell&#8217;ILVA di Taranto, dove il padrone, licenzia degli operai, solo perch\u00e9 mandano un messaggino ad un collega invitandolo a vedere un film che parla dell&#8217;acciaieria, azienda, ricordiamolo, adesso partecipata dallo Stato italiano.<\/p>\n<p>Fedez, durante la Festa del Primo Maggio invece di parlare di lavoro, ci parla delle sue simpatie e antipatie politiche, parla di una legge che se dovesse passare limiterebbe la libert\u00e0 di espressione di tutti noi.<\/p>\n<p>Ora al di l\u00e0 della pochezza e della scorrettezza del personaggio, che non solo prende una barca di soldi dalle varie televisioni, ma fa pure finta di essere stato censurato da questa: insomma questo signore, come dicono i napoletani con una frase colorita ma che bene esprime il modo di fare del personaggio, &#8220;chiagne e fotte&#8221;.<\/p>\n<p>Questo concetto di democrazia secondo cui i giullari del pensiero unico dominante possono parlare senza che i cittadini possano ascoltare l&#8217;altra campana, non va pi\u00f9 bene.<\/p>\n<p>Qualcuno dovrebbe ricordare a Fedez e al segretario del PD che lo difende, o a coloro che il servizio pubblico riempie di soldi, come i compagni Lucia Annunziata o Fabio Fazio &#8211; solo quest&#8217;ultimo si becca dalla RAI oltre 10 milioni di euro l&#8217;anno &#8211; che gli artisti discriminati sono quelli che non sono disposti a fare i giullari del mainstream. Sono personaggi come Giuseppe Povia la cui bravura \u00e8 incontestabile, ma che ogni anno gli viene negata la possibilit\u00e0 di cantare a San Remo, cos\u00ec come non trova spazio nei programmi di mamma Rai.<\/p>\n<p>Torniamo a coloro chela democrazia la intendono come esercito dove loro possono parlare mentre agli atri tale possibilit\u00e0 viene negata.<br \/>\nEcco la stessa censura che ha subito Fedez dalla Rai vorremmo fosse applicata a tutti quegli artisti che vengono tenuti fuori dalla emittente di Stato, credo che sarebbero ben contenti di essere riempiti di soldi e di avere tutto lo spazio di cui Fedez gode in Rai, facendo finta pure di essere limitato nelle sue esternazioni.<br \/>\nMa ascoltiamo cosa ci dice Francesco Amedeo, ancora una volata con un suo intervento preciso e puntuale smonta pezzo per pezzo la propaganda di Fedez.<\/p>\n<p>Amodeo ci racconta che:<\/p>\n<p>&#8220;<em>Le tecniche di manipolazione delle masse usate nel discorso di <strong>Fedez <\/strong>del primo maggio potrebbero sfuggire ai pi\u00f9 distratti, non certo agli addetti ai lavori. Cerchiamo di ricostruire quanto \u00e8 accaduto. Cominciamo a capire quali fossero i suoi obiettivi e poi come sono stati raggiunti.<\/em><\/p>\n<p><em>Il primo era quello di trasformare l\u2019apertura di un concerto in un<strong> comizio politico<\/strong> per propagandare un pensiero unico senza contraddittorio per creare nella percezione degli italiani il mostro contro cui opporsi, che doveva essere personificato negli oppositori della <strong>legge Zan<\/strong>.<\/em><\/p>\n<div class=\"td-a-rec td-a-rec-id-content_inline tdi_2_aca td_block_template_1\"><em>\u00a0Il secondo era quello di rafforzare questo sentimento di <strong>ostilit\u00e0 <\/strong>nei confronti del nuovo mostro facendo credere che ci fosse stato un tentativo di censura da parte dei <strong>vertici Rai<\/strong>.<\/em><br \/>\n<em>La prima \u00e8 che chi si oppone alla legge Zan \u00e8 un <strong>leghista<\/strong>, mentre sappiamo che nel Paese c\u2019\u00e8 un\u2019opposizione trasversale che riguarda tutta la societ\u00e0 civile. La seconda, che prova ad alterare la percezione del pubblico citando frasi vergognose di qualche <strong>estremista <\/strong>di turno. Il terzo punto, il pi\u00f9 subdolo, \u00e8 che per associazione \u00e8 riuscito a far credere che tutti gli oppositori alla legge Zan siano allineati a quel pensiero. Sintetizzando questo concetto: o sostieni la legge Zan, o la pensi come loro.<\/em><\/div>\n<p><em>Operazione riuscita magistralmente&#8221;.<\/em><\/p>\n<p>Per ascoltare tutto l&#8217;articolato intervento di Francesco Amedeo cliccate sul sito che abbiamo messo all&#8217;inizio di questa pagina.<a href=\"https:\/\/www.radioradio.it\/2021\/05\/discorso-fedez-messaggio-subdolo-nascosto-amodeo\/\">\u00a0<\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/05\/il-discorso-di-fedez-smontato-pezzo-per-pezzo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/05\/il-discorso-di-fedez-smontato-pezzo-per-pezzo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.radioradio.it\/2021\/05\/discorso-fedez-messaggio-subdolo-nascosto-amodeo\/ gm______Francesco Amedeo, autore del Libro la Matrix Europea \u00e8 uno degli scrittori pi\u00f9 interessanti che abbiamo in Italia, perch\u00e9 \u00e8 un giornalista controcorrente ma sopratutto perch\u00e9 con le sue inchieste e i suoi libri ha denunciato quelle che sono le manovre ai danni dell&#8217;Italia da parte di Multinazionali, Burocrazia Europea e Alta Finanza. Questa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/182683"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=182683"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/182683\/revisions"}],"predecessor-version":[{"id":182697,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/182683\/revisions\/182697"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=182683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=182683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=182683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}