{"id":183270,"date":"2021-05-15T13:58:45","date_gmt":"2021-05-15T11:58:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=183270"},"modified":"2021-05-15T14:00:11","modified_gmt":"2021-05-15T12:00:11","slug":"sanzionato-parcheggiatore-abusivo-vicino-la-questura","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/15\/sanzionato-parcheggiatore-abusivo-vicino-la-questura\/","title":{"rendered":"PARCHEGGIATORE ABUSIVO VICINO LA QUESTURA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-183271\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/questura-01.jpg\" alt=\"\" width=\"530\" height=\"245\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/questura-01.jpg 530w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/questura-01-300x139.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/questura-01-315x145.jpg 315w\" sizes=\"(max-width: 530px) 100vw, 530px\" \/>(e.l.)______Ieri pomeriggio gli agenti in servizio presso la Sezione Volanti della Questura di Lecce hanno denunciato a piede libero un uomo di 43 anni di San Cesario di Lecce, per il reato di \u201cRifiuto d\u2019indicazione sulla propria identit\u00e0\u201d, e lo hanno multato per attivit\u00e0 di parcheggiatore abusivo.<\/p>\n<p>L&#8217;intervento, dopo che erano arrivate\u00a0telefonate da parte di automobilisti che segnalavano in via Marconi un parcheggiatore abusivo alquanto petulante e con atteggiamento minaccioso.<\/p>\n<p>Giunti sul posto, lo hanno visto all&#8217;opera.<\/p>\n<p>Gli agenti procedevano allora al controllo dell\u2019uomo, che per\u00f2 si mostrava insofferente e, nonostante ripetuti inviti e ammonimenti,\u00a0 si rifiutava di fornire le generalit\u00e0 o di esibire un documento valido ai fini dell\u2019identificazione.<\/p>\n<p>Pertanto, \u00e8 stato portato negli uffici della vicina Questura, dove \u00e8 stato identificato, e, come detto, \u00e8 stato sia denunciato, sia multato.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/15\/sanzionato-parcheggiatore-abusivo-vicino-la-questura\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/15\/sanzionato-parcheggiatore-abusivo-vicino-la-questura\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______Ieri pomeriggio gli agenti in servizio presso la Sezione Volanti della Questura di Lecce hanno denunciato a piede libero un uomo di 43 anni di San Cesario di Lecce, per il reato di \u201cRifiuto d\u2019indicazione sulla propria identit\u00e0\u201d, e lo hanno multato per attivit\u00e0 di parcheggiatore abusivo. L&#8217;intervento, dopo che erano arrivate\u00a0telefonate da parte di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":183271,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/183270"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=183270"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/183270\/revisions"}],"predecessor-version":[{"id":183273,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/183270\/revisions\/183273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/183271"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=183270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=183270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=183270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}