{"id":183294,"date":"2021-05-15T18:59:21","date_gmt":"2021-05-15T16:59:21","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=183294"},"modified":"2021-05-15T20:02:53","modified_gmt":"2021-05-15T18:02:53","slug":"183294","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/15\/183294\/","title":{"rendered":"AGGUATO NELLA NOTTE, FREDDATO EX CARABINIERE \/ QUESTO POMERIGGIO A COPERTINO L&#8217;ULTIMO SALUTO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-183295\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/139C2D65-F313-4D96-A682-44E92D1A02F8.jpeg\" alt=\"\" width=\"2084\" height=\"2627\" \/><\/p>\n<p>di <strong>Alisia Mariano<\/strong>______<\/p>\n<p>Sguardi persi, silenzio, volti rigati da lacrime di dolore. Si \u00e8 celebrato questo pomeriggio alle 16.30, presso la chiesa di San Gerardo Maiella,<span class=\"Apple-converted-space\">\u00a0 <\/span>il funerale di Silvano Nestola, l\u2019ex carabiniere quarantaseienne ucciso lo scorso 3 maggio sotto gli occhi del piccolo figlio.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Ha lasciato un vuoto incolmabile la sua morte.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>La chiesa era gremita di gente: amici e parenti vicini al dolore della famiglia, straziata dalla perdita.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Una commovente celebrazione. Presente al funerale per dare l\u2019ultimo saluto, a nome di tutta la citt\u00e0 di Copertino, la sindaca Sandrina Schito che ha ricordato Silvano come cittadino, come uomo, come valente membro dell\u2019arma dei carabinieri e come padre.<\/p>\n<p>Un lungo applauso all\u2019uscita dalla chiesa del feretro, accompagnato dai parenti pi\u00f9 prossimi: i genitori e i fratelli.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Sul sagrato della chiesa, in fila, i piccoli amici e compagni di classe del figlio di Silvano, con in mano una rosa bianca, pronti ad accogliere e ad abbracciare il loro amico.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Oggi un bambino ha dato il suo ultimo saluto al padre. Mano nella mano con la madre \u00e8 uscito per ultimo dalla chiesa,<span class=\"Apple-converted-space\">\u00a0 <\/span>con gli occhi gonfi, ma indossando fiero e orgoglioso la lucerna del padre.______<\/p>\n<p>LA RICERCA nel nostro articolo del 12 maggio scorso<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"BFTA21Wu5a\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/12\/agguato-nella-notte-freddato-ex-carabiniere-iscritti-due-nomi-nel-registro-degli-indagati\/\">AGGUATO NELLA NOTTE, FREDDATO EX CARABINIERE\/ ISCRITTI DUE NOMI NEL REGISTRO DEGLI INDAGATI<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/12\/agguato-nella-notte-freddato-ex-carabiniere-iscritti-due-nomi-nel-registro-degli-indagati\/embed\/#?secret=BFTA21Wu5a\" data-secret=\"BFTA21Wu5a\" width=\"500\" height=\"282\" title=\"&#8220;AGGUATO NELLA NOTTE, FREDDATO EX CARABINIERE\/ ISCRITTI DUE NOMI NEL REGISTRO DEGLI INDAGATI&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/15\/183294\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/15\/183294\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Alisia Mariano______ Sguardi persi, silenzio, volti rigati da lacrime di dolore. Si \u00e8 celebrato questo pomeriggio alle 16.30, presso la chiesa di San Gerardo Maiella,\u00a0 il funerale di Silvano Nestola, l\u2019ex carabiniere quarantaseienne ucciso lo scorso 3 maggio sotto gli occhi del piccolo figlio.\u00a0 Ha lasciato un vuoto incolmabile la sua morte.\u00a0 La chiesa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":183295,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/183294"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=183294"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/183294\/revisions"}],"predecessor-version":[{"id":183310,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/183294\/revisions\/183310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/183295"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=183294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=183294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=183294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}