{"id":183651,"date":"2021-05-24T00:03:32","date_gmt":"2021-05-23T22:03:32","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=183651"},"modified":"2021-05-22T19:54:57","modified_gmt":"2021-05-22T17:54:57","slug":"moda-mode-il-diario-bastian-contraria","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/24\/moda-mode-il-diario-bastian-contraria\/","title":{"rendered":"MODA \/ MODE &#8211; IL DIARIO DI BASTIAN CONTRARIA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-183652\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/183939444_217020709877983_1849770679092847503_n.jpg\" alt=\"\" width=\"753\" height=\"525\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/183939444_217020709877983_1849770679092847503_n.jpg 753w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/05\/183939444_217020709877983_1849770679092847503_n-300x209.jpg 300w\" sizes=\"(max-width: 753px) 100vw, 753px\" \/>di <strong>Elena Vada<\/strong>______<\/p>\n<p>L&#8217;argomento principe di questo periodo, \u00e8 il &#8220;politicamente corretto&#8221;.Ne sentiamo di ogni, in merito e, quindi, parliamo, discutiamo, (cercando di capire) con cognizione di causa o meno.<br \/>\n\u00c8 la nuova psicosi. La fobia dei giorni nostri.<\/p>\n<p>Siamo arrivati, infatti, a paradossi ed assurdi, incredibili. Ad esempio, criticare, addirittura, il Principe Azzurro delle favole, per il famoso bacio&#8230; &#8220;Desiderato, dall&#8217;interessata???&#8221;, chiedono i moderni censori. La Bella Addormentata e Biancaneve, non erano consenzienti, in quel momento. Pazzesco&#8230; caso da &#8220;Forum&#8221;.<\/p>\n<p>Seguendo i dettami, di questa socio-filosofia, quanti film, capolavori della cinematografia, allora, non si potranno pi\u00f9 vedere, cos\u00ec come monumenti e pitture. Oppure, quali canzoni saranno ascoltabili, sempre per la su citata questione?<\/p>\n<p>Ieri canticchiavo, con il mio nipotino, il motivetto &#8220;Tucul&#8221; (rimembranza dei tempi delle gite parrocchiali) dove c&#8217;\u00e8 una\u00a0negretta\u00a0che\u00a0aspetta nella capanna (il Tucul, appunto!). Scorretto?<br \/>\nMa, chi se ne frega! Questa esclamazione ricorda il ventennio fascista:\u00a0 di nuovo &#8220;politicamente scorretto&#8221;, quindi?!<br \/>\nE, chi se ne frega!!! Esclamo, un po&#8217; inquieta e stizzita.<\/p>\n<p>Dopo gli anni in cui siamo diventati tutti &#8220;NON qualcosa&#8221;\u00a0 (vedenti, udenti, pensanti, eccetera), \u00e8 arrivata, successivamente, anche l&#8217;era del &#8220;DIVERSAMENTE&#8230;&#8221;, fino all&#8217;estremo, ridicolo, abbinamento a &#8220;giovane&#8221;, ovvero, una come me, sarebbe &#8220;Diversamente Giovane&#8221;, in pratica, correttamente:\u00a0\u00a0anziana.<\/p>\n<p>Oggi, invece, parliamo&#8230; di Political Correct, enfatizzando, con questo fastidioso inglese, l&#8217;internalizzazione dell&#8217;intento: opinioni senza alcun pregiudizio di sorta.<br \/>\nNon posso dire &#8220;fastidioso inglese&#8221;???<br \/>\nScorretto? UFFA!<br \/>\nGi\u00e0, vedo il nostro Direttore che &#8220;storce il naso&#8221;, leggendomi. Dottor Puppo, lei mi conosce, sono politicamente scorretta, dalla nascita.<br \/>\nA dir il vero, in famiglia, mi chiamavano &#8220;Bastian Cuntrari&#8221;, che non \u00e8 proprio la stessa cosa, ma quasi.<br \/>\nComunque, la sensazione di dover controllare ogni parola, dichiarazione,\u00a0 discorso, in virt\u00f9 di questa moda (e legge) del &#8220;corretto o scorretto&#8221; mi sembra una grave limitazione della libert\u00e0 d&#8217;espressione, se mal interpretata. Basterebbero: educazione, buon senso, sensibilit\u00e0. \u00c8 una cazzata!<br \/>\nA gi\u00e0,\u00a0\u00a0&#8220;cazzata&#8221;,\u00a0\u00e8 termine scorretto.<br \/>\nInfatti, perch\u00e9 menzionare il pene (parte anatomica maschile) per indicare una cosa negativa e, al contrario, dire\u00a0Figata, (citando la corrispondente parte anatomica femminile) per indicarne una molto positiva?<br \/>\nPotremmo continuare a citare infiniti esempi, come questo, riguardanti sostantivi, aggettivi, avverbi. Tutto pu\u00f2 diventare o renderci: &#8220;Politically incorrect&#8221;.<\/p>\n<p>Che mal di testa. Sar\u00e0 che sto ascoltando, (televisione accesa) il nostro Premier, Draghi, che spiega la sua &#8220;cura per Italia&#8221;, con la studiata Manovra Economica che sta, sapientemente, mettendo in pratica.<br \/>\nRisponde ai giornalisti in modo deciso e conciso. Quasi lapidario.<br \/>\nC&#8217;\u00e8 lo invidiano tutti, sar\u00e0 bravissimo a fare i conti, ma non mi \u00e8 simpatico, con quella saccente arroganza, da primo della classe.<br \/>\nOpinione personale, senza pregiudizi, di alcun genere.<br \/>\nSono di nuovo, scorretta?<br \/>\nVabb\u00e8, allora ditelo che ce l&#8217;avete con me! Mi faccio un caff\u00e8, per consolarmi.<br \/>\nCorretto o macchiato?<br \/>\nQuesto \u00e8 il problema!<br \/>\nMa, &#8220;Francamente, me ne infischio!&#8221; come disse Rhett Butler (Clark Gable) in &#8220;Via col vento&#8221; (1939, diretto da Victor Fleming) film ambientato durante la guerra di Secessione americana (1861) e cancellato dalla piattaforma in streaming HBO Max (servizio on-demand, statunitense), perch\u00e9 rappresenta l&#8217;America con pregiudizi etnico-razziali.<br \/>\nIl film vinse, all&#8217;epoca (1940) otto Oscar, di cui uno all&#8217;attrice non protagonista, Hattie McDaniel (foto), di origine afroamericana, con il personaggio &#8221; Mamie&#8221; balia di Rossella O&#8217;Hara, (Vivien Leight) protagonista (Oscar) della pellicola.<br \/>\nIl film \u00e8, ancora\u00a0oggi, campione mondiale d&#8217;incassi, se adattato a cambio ed inflazione monetaria.<br \/>\nMa \u00e8 &#8220;politicamente scorretto&#8221;. Allora stasera lo riguardo (registrato). Sono solo quattro ore di spettacolo d&#8217; intramontabile bellezza, intensit\u00e0 e coinvolgimento. &#8220;Dopotutto,\u00a0domani\u00a0\u00e8 un altro giorno&#8221; (frase di Rosella O&#8217;Hara, nel film) e, chiss\u00e0 che inventeranno?!______<\/p>\n<p>L&#8217;APPROFONDIMENTO nei nostri articoli del 3 e del 6 maggio scorsi<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"qkyZGbrj6H\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/06\/il-bacio-del-principe-azzurro-a-biancaneve-politicamente-scorretto-ma-in-italia-per-fortuna-ci-ha-salvati-lironia-la-nostra-classifica-antologica-delle-migliori-meme-apparse-sul-web\/\">&#8220;Il bacio del Principe Azzurro a Biancaneve? Politicamente scorretto&#8230;&#8221;. MA IN ITALIA PER FORTUNA CI HA SALVATI L&#8217;IRONIA. LA NOSTRA CLASSIFICA ANTOLOGICA COMMENTATA DELLE MIGLIORI MEME APPARSE SUL WEB<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/06\/il-bacio-del-principe-azzurro-a-biancaneve-politicamente-scorretto-ma-in-italia-per-fortuna-ci-ha-salvati-lironia-la-nostra-classifica-antologica-delle-migliori-meme-apparse-sul-web\/embed\/#?secret=qkyZGbrj6H\" data-secret=\"qkyZGbrj6H\" width=\"500\" height=\"282\" title=\"&#8220;&#8220;Il bacio del Principe Azzurro a Biancaneve? Politicamente scorretto&#8230;&#8221;. MA IN ITALIA PER FORTUNA CI HA SALVATI L&#8217;IRONIA. LA NOSTRA CLASSIFICA ANTOLOGICA COMMENTATA DELLE MIGLIORI MEME APPARSE SUL WEB&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"jqPHdcFpuP\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/03\/pio-e-amedeo\/\">LA #FelicissimaSera DI PIO E AMEDEO CHE CON IL SUCCESSO DEL LORO PROGRAMMA TELEVISIVO SU CANALE 5 HANNO SDOGANATO LA SATIRA &#8216;SCORRETTA&#8217;<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/03\/pio-e-amedeo\/embed\/#?secret=jqPHdcFpuP\" data-secret=\"jqPHdcFpuP\" width=\"500\" height=\"282\" title=\"&#8220;LA #FelicissimaSera DI PIO E AMEDEO CHE CON IL SUCCESSO DEL LORO PROGRAMMA TELEVISIVO SU CANALE 5 HANNO SDOGANATO LA SATIRA &#8216;SCORRETTA&#8217;&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/24\/moda-mode-il-diario-bastian-contraria\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/05\/24\/moda-mode-il-diario-bastian-contraria\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Elena Vada______ L&#8217;argomento principe di questo periodo, \u00e8 il &#8220;politicamente corretto&#8221;.Ne sentiamo di ogni, in merito e, quindi, parliamo, discutiamo, (cercando di capire) con cognizione di causa o meno. \u00c8 la nuova psicosi. La fobia dei giorni nostri. Siamo arrivati, infatti, a paradossi ed assurdi, incredibili. Ad esempio, criticare, addirittura, il Principe Azzurro delle [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":183652,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/183651"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=183651"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/183651\/revisions"}],"predecessor-version":[{"id":183654,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/183651\/revisions\/183654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/183652"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=183651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=183651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=183651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}