{"id":18377,"date":"2013-07-04T17:26:41","date_gmt":"2013-07-04T17:26:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=18377"},"modified":"2013-07-04T17:26:41","modified_gmt":"2013-07-04T17:26:41","slug":"beach-volley-finale-under-20-femminile","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/04\/beach-volley-finale-under-20-femminile\/","title":{"rendered":"BEACH VOLLEY : FINALE UNDER 20 FEMMINILE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/foto-bianchin-enzo.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/foto-bianchin-enzo-300x224.jpg\" alt=\"\" width=\"300\" height=\"224\" class=\"alignleft size-medium wp-image-18378\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/foto-bianchin-enzo-300x224.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/foto-bianchin-enzo.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Secondo posto per Langellotti-Lestini, terzo per la coppia salentina Guido-Leone e, in quarta posizione, Zuccarelli-Concetti<\/p>\n<p>La coppia veneta formata da Margherita Bianchin e Irene Enzo conquista la finale del Campionato italiano Master Under 20 femminile di beach volley \u201cSalento d\u2019amare cup\u201d, che si \u00e8 svolta a San Cataldo, presso il Lido York, sotto l\u2019egida della Federazione italiana pallavolo (Fipav).<\/p>\n<p>Le due gare semifinali hanno visto in campo Bianchin-Enzo contro le marchigiane Concetti-Zuccarelli (21-18, 21-11) e Lodovica Langellotti-Monica Lestini contro la coppia formata dalla galatinese Camilla Guido (che ha vinto la B-2 con la Betitaly Maglie) e la tarantina Emi Leone (21-11, 21-12).<\/p>\n<p>La finale per il terzo e quarto posto ha visto poi Guido-Leone aggiudicarsi la vittoria al tie-break contro Concetti-Zuccarelli (21-16, 19-21, 15-10).<\/p>\n<p>La finalissima si \u00e8 conclusa a favore di Bianchin-Enzo che ha battutto, non senza difficolt\u00e0, la coppia Lestini-Langellotti (25-23, 21-19).<\/p>\n<p>Domani 5 luglio, al Lido York, prender\u00e0 il via il Campionato Italiano Master femminile. A sfidarsi saranno le migliori giocatrici del ranking italiano. Sono 34 le coppie iscritte alla tappa \u201crosa\u201d leccese \u2013 e 18 quelle in qualifica: testa di serie numero uno del tabellone principale, la coppia siculo-romana Graziella Lo Re-Giulia Toti, che si \u00e8 formata quest\u2019anno, seguita da Nelli Mazzulla-Francesca Giogoli, coppia siculo-emiliana; e ancora, per la prima volta insieme, Vittoria Orsi Toth e Natalia Vigan\u00f2, quest\u2019ultima atleta di A1. Da menzionare, la coppia emergente formata da Silvia Costantini ed Eleonora Gili, che ha vinto la prima tappa \u201crosa\u201d del Master che si \u00e8 svolta a Bibione. Unica coppia salentina in maindraw \u00e8 quella composta da Mara Di Martile e Valeria Cristofaro. In tutto sono ben sei le coppie locali iscritte al Master femminile anche questo un record per la tappa leccese del campionato italiano.<\/p>\n<p>La tappa salentina del campionato italiano di beach volley proseguir\u00e0 al lido York il 12,13 e 14 luglio con le sfide del Master maschile.<\/p>\n<p>Il campionato italiano Master di beach volley \u00e8 organizzato dalla Federazione italiana Pallavolo (Fipav). La tappa leccese \u00e8 organizzata da Beach Talents Asd e Lido York, in collaborazione con Eventi Marketing &amp; Communication e con il sostegno di Provincia (Assessorato Turismo e Marketing territoriale) e Comune di Lecce.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/04\/beach-volley-finale-under-20-femminile\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/04\/beach-volley-finale-under-20-femminile\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Secondo posto per Langellotti-Lestini, terzo per la coppia salentina Guido-Leone e, in quarta posizione, Zuccarelli-Concetti La coppia veneta formata da Margherita Bianchin e Irene Enzo conquista la finale del Campionato italiano Master Under 20 femminile di beach volley \u201cSalento d\u2019amare cup\u201d, che si \u00e8 svolta a San Cataldo, presso il Lido York, sotto l\u2019egida della [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18378,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18377"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=18377"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18377\/revisions"}],"predecessor-version":[{"id":18380,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18377\/revisions\/18380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/18378"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=18377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=18377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=18377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}