{"id":18438,"date":"2013-07-08T07:38:06","date_gmt":"2013-07-08T07:38:06","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=18438"},"modified":"2013-07-08T07:38:06","modified_gmt":"2013-07-08T07:38:06","slug":"i-love-san-cataldo-un-contest-fotografico-per-rilanciare-la-marina-leccese","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/08\/i-love-san-cataldo-un-contest-fotografico-per-rilanciare-la-marina-leccese\/","title":{"rendered":"&#8220;I LOVE SAN CATALDO&#8221;, UN CONTEST FOTOGRAFICO PER RILANCIARE LA MARINA LECCESE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/DSC_0182.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/DSC_0182-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" class=\"alignleft size-medium wp-image-18439\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/DSC_0182-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/DSC_0182.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>E\u2019 stata scattata proprio a San Cataldo una delle foto pi\u00f9 famose del mondo. L\u2019immagine rappresenta un bacio tra due innamorati sotto il famoso faro e fa parte di uno dei cataloghi di Magnum, una delle pi\u00f9 blasonate agenzie del pianeta. Per questo l\u2019Assessorato all\u2019Ambiente del Comune e l\u2019attivissima associazione culturale Menti Calde lanciano il primo contest fotografico dedicato al tema dell\u2019amore e dell\u2019ambiente insieme. Cittadini e turisti in visita nella nostra ridente penisola sono invitati ad inviare il loro scatto per rappresentare un gesto romantico e uno scorcio di San Cataldo e\/o del Parco Naturale Regionale di Rauccio. Proprio per questo \u201cI love San Cataldo\u201d \u00e8 il nome del concorso. Ricchi premi in attrezzature per la fotografia e la possibilit\u00e0 di esporre gli scatti pi\u00f9 belli presso il Lido Turrisi nel corso dell\u2019estate, proprio vicino il famoso faro.<\/p>\n<p>Per partecipare occorre postare le foto in privato sulla pagina facebook del concorso, www.facebook.com\/ILOVESANCATALDO, per votarle con il semplice \u201cmi piace\u201d ci sar\u00e0 tempo fino al prossimo 10 agosto a mezzanotte, a decretare i 10 finalisti sar\u00e0 il popolo di internet mentre una giuria di esperti selezioner\u00e0 i primi 3. Vincer\u00e0 la foto che meglio di tutte sapr\u00e0 esprimere il sentimento dell\u2019amore incorniciandolo in uno scenario capace di rendere le peculiarit\u00e0 pi\u00f9 positive dell\u2019ambiente urbano e della natura della marina di San Cataldo o del Parco di Rauccio. Premiazione prevista il 22 agosto alle 21,00 presso il Lido Turrisi.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/08\/i-love-san-cataldo-un-contest-fotografico-per-rilanciare-la-marina-leccese\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/08\/i-love-san-cataldo-un-contest-fotografico-per-rilanciare-la-marina-leccese\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>E\u2019 stata scattata proprio a San Cataldo una delle foto pi\u00f9 famose del mondo. L\u2019immagine rappresenta un bacio tra due innamorati sotto il famoso faro e fa parte di uno dei cataloghi di Magnum, una delle pi\u00f9 blasonate agenzie del pianeta. Per questo l\u2019Assessorato all\u2019Ambiente del Comune e l\u2019attivissima associazione culturale Menti Calde lanciano il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18439,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18438"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=18438"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18438\/revisions"}],"predecessor-version":[{"id":18441,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18438\/revisions\/18441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/18439"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=18438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=18438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=18438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}