{"id":184861,"date":"2021-06-22T12:13:53","date_gmt":"2021-06-22T10:13:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=184861"},"modified":"2021-06-22T12:15:19","modified_gmt":"2021-06-22T10:15:19","slug":"provvedimento-della-magistratura-contro-giovane-violento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/06\/22\/provvedimento-della-magistratura-contro-giovane-violento\/","title":{"rendered":"PROVVEDIMENTO DELLA MAGISTRATURA PER STALKING"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-184862\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/06\/download-1.jpg\" alt=\"\" width=\"400\" height=\"257\" \/>(e.l.)______Un giovane di 38 anni di Presicce non potr\u00e0 avvicinarsi ai luoghi frequentati dalla ex compagna e non potr\u00e0 comunicare in alcun modo con lei. Questo il provvedimento emesso dal gip del Tribunale di Lecce, notificato ieri al destinatario dagli agenti della Polizia di Stato del Commissariato di Taurisano (nella foto).<\/p>\n<p>Dopo mesi di atti persecutori subiti in silenzio, alla fine la vittima aveva presentato denuncia il mese scorso.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/06\/22\/provvedimento-della-magistratura-contro-giovane-violento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/06\/22\/provvedimento-della-magistratura-contro-giovane-violento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______Un giovane di 38 anni di Presicce non potr\u00e0 avvicinarsi ai luoghi frequentati dalla ex compagna e non potr\u00e0 comunicare in alcun modo con lei. Questo il provvedimento emesso dal gip del Tribunale di Lecce, notificato ieri al destinatario dagli agenti della Polizia di Stato del Commissariato di Taurisano (nella foto). Dopo mesi di atti [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":184862,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/184861"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=184861"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/184861\/revisions"}],"predecessor-version":[{"id":184865,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/184861\/revisions\/184865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/184862"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=184861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=184861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=184861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}