{"id":18535,"date":"2013-07-10T07:17:00","date_gmt":"2013-07-10T07:17:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=18535"},"modified":"2013-07-10T07:17:00","modified_gmt":"2013-07-10T07:17:00","slug":"premio-san-leonardo-2013","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/10\/premio-san-leonardo-2013\/","title":{"rendered":"PREMIO SAN LEONARDO 2013"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/PREMIO-SAN-LEONARDO-Locandina.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/PREMIO-SAN-LEONARDO-Locandina-300x142.jpg\" alt=\"\" width=\"300\" height=\"142\" class=\"alignleft size-medium wp-image-18536\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/PREMIO-SAN-LEONARDO-Locandina-300x142.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/PREMIO-SAN-LEONARDO-Locandina.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u201cLa speranza ha due bellissime figlie: lo sdegno e il coraggio&#8230;lo sdegno per la realt\u00e0 delle cose; il coraggio per cambiarle\u201d. Pablo Neruda<\/p>\n<p>Prender\u00e0 il via il prossimo 12 luglio la quarta edizione del \u201cPremio San Leonardo\u201d, a cura dell\u2019Associazione \u201cGruppo San Leonardo\u201d, con il patrocinio di Regione Puglia, Provincia di Lecce e Comune di Castrignano dei Greci. La manifestazione si svolger\u00e0 nella magica location di Masseria Pozzelle a Castrignano dei Greci (Le).<\/p>\n<p>Il premio \u00e8 un riconoscimento che viene assegnato ogni anno a coloro che si sono distinti per la promozione e la tutela dei valori della legalit\u00e0 e della non violenza. Una testimonianza che resti impressa e raggiunga il cuore dei giovani, cittadini del domani che costruiranno le basi di una societ\u00e0 che sia civile ed umana sotto tutti i punti di vista. L\u2019evento \u201cPremio San Leonardo\u201d non sar\u00e0 solo legalit\u00e0 ma anche intrattenimento, sport, solidariet\u00e0, moda e musica, perch\u00e9 attraverso il coinvolgimento di tutti, un territorio cresce e si sviluppa.<\/p>\n<p>Questo il programma della tre giorni.<\/p>\n<p>&#8211; Venerd\u00ec 12 luglio, ore 21,00: \u201cFashioNight \u2013 Moda, voci, tendenze\u201dsfilata di moda ,organizzata da Alberto Persano. In passerella Aldo Colombo, Il Monello, Fadagi\u00f2, De Matteis Gioielli, P. Luzio, La Sellerie, Ottica Costantini, Hairdo Style, Il Sogno nel Cassetto.<\/p>\n<p>&#8211; Sabato 13 luglio, ore 21,00: concerto e musica dal vivo con Zimbaria e Toromeccanica (ingresso Libero).<\/p>\n<p>&#8211; Domenica 14 luglio, ore 21,00: cerimonia di consegna del \u201cPremio San Leonardo 2013\u201d. Il comitato scientifico del \u201cPremio San Leonardo\u201d &#8211; presieduto dal prof. Domenico Lenzi dell\u2019Universit\u00e0 di Lecce, dal prof. Francesco Chielli dell\u2019Universit\u00e0 di Ancona e dal prof. Cosimo Lor\u00e8 dell\u2019Universit\u00e0 di Siena \u2013 quest\u2019anno ha inteso conferire il premio a: Paul Badde (confidente di Benedetto XVI), Assunta Tornesello (Primario di Onco-ematologia Pediatrica, Ospedale \u201cVito Fazzi\u201d di Lecce) e Prof. Ing. Domenico Laforgia, rettore dell&#8217;Universit\u00e0 del Salento. Un riconoscimento speciale sar\u00e0 conferito a Giuliana Perrotta (Prefetto di Lecce) e Nandu Popu (Sud Sound System). Saranno inoltre consegnate delle menzioni speciali a due Castrignanesi doc: Alessia Agros\u00ec, giovane attrice salentina (Un Medico in famiglia RAI) e Giuseppina Vergine, musicista d\u2019arpa di grande talento.<\/p>\n<p>Largo Pozzelle sar\u00e0 adornata con luci soffuse e giochi d\u2019acqua, luminarie e gli \u201cChalet del Gusto\u201d, stand gastronomici con prodotti tipici locali, nel pieno rispetto della genuinit\u00e0 e della tradizione e con un\u2019attenzione particolare all\u2019igiene nella distribuzione degli alimenti e al rispetto dell\u2019ambiente nella gestione dei rifiuti.<\/p>\n<p>Durante la due giorni, inoltre, sar\u00e0 allestito il mercatino della solidariet\u00e0 di Agor\u00e0 Lab, con i lavoretti realizzati dai bambini che frequentano il centro polivalente. Il ricavato dalla vendita dei prodotti sar\u00e0 devoluto all&#8217;Associazione Genitori Onco-Ematologia Pediatrica \u201cPer un sorriso in pi\u00f9 \u2013 Onlus\u201d di Lecce.<\/p>\n<p>SCHEDA<\/p>\n<p>Associazione \u201cGruppo San Leonardo\u201d<\/p>\n<p>Il &#8220;Gruppo San Leonardo\u201d \u00e8 una associazione che nasce nel 2006 con lo scopo di favorire la diffusione della cultura in tutte le et\u00e0 e sensibilizzare le giovani generazioni alla cultura della non violenza.<\/p>\n<p>Nell\u2019ambito delle iniziative finalizzate a diffondere tra i pi\u00f9 giovani i valori dell\u2019etica sociale e in particolar modo della legalit\u00e0, l\u2019associazione, ha istituito nel 2010 il \u201cPremio San Leonardo\u201d. Si tratta di un riconoscimento rivolto a coloro i quali hanno contribuito attivamente all\u2019affermazione di tutti i principi legati alla legalit\u00e0 e alla non violenza; il premio inoltre \u00e8 dedicato a chi, nel corso della propria quotidianit\u00e0, si \u00e8 impegnato a promuovere sentimenti di solidariet\u00e0 e fratellanza attraverso l&#8217;arte, la musica, la letteratura, l&#8217;editoria, la stampa. Il Premio San Leonardo, vuole sottolineare anche in questa edizione, il merito di chi lavora con passione, con professionalit\u00e0 e impegno nel pieno rispetto della dimensione umana, culturale e spirituale della persona.<\/p>\n<p>Nelle scorse edizioni il comitato scientifico del \u201cPremio San Leonardo\u201d, ha scelto di conferire il Premio San Leonardo a : Salvatore Borsellino, al magistrato Antonio Ingroia, a Sergio Ortelli, sindaco del comune Isola del Giglio, a don Luigi Ciotti, presidente dell\u2019ass.\u201dLibera\u201d, a Pantaleo Corvino dirigente della Fiorentina Calcio. L\u2019attivit\u00e0 dei volontari si contraddistingue anche per l\u2019evento \u201cUn goal nell\u2019oratorio\u201d, durante il quale sono stati raccolti dei fondi per la costruzione di un pozzo, adiacente alla Chiesa di San Leonardo. Fra le loro tante attivit\u00e0 vi \u00e8, inoltre, nel 2008 l\u2019istituzione di una scuola di calcio a pochi km da Salvador de Bahia. Questo fruttuoso progetto \u00e8 nato dalla collaborazione tra il gruppo di volontari castrignanesi e Carlo Giliberti, un imprenditore milanese, proprietario di un eco-resort in Brasile: \u201cFazenda Agua da Prata,Linea Verde\u201d.I volontari del gruppo, con il contributo economico raccolto nelle tante manifestazioni di cui si fanno promotori, hanno costruito un campetto di calcio e ai bambini brasiliani periodicamente inviano beni di prima necessit\u00e0. Hanno sterrato il terreno, installato le reti e le porte, acquistato tutto il materiale necessario per poter farli giocare a calcio ed allontanarli dai mille pericoli della strada.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/10\/premio-san-leonardo-2013\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/10\/premio-san-leonardo-2013\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u201cLa speranza ha due bellissime figlie: lo sdegno e il coraggio&#8230;lo sdegno per la realt\u00e0 delle cose; il coraggio per cambiarle\u201d. Pablo Neruda Prender\u00e0 il via il prossimo 12 luglio la quarta edizione del \u201cPremio San Leonardo\u201d, a cura dell\u2019Associazione \u201cGruppo San Leonardo\u201d, con il patrocinio di Regione Puglia, Provincia di Lecce e Comune di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18536,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18535"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=18535"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18535\/revisions"}],"predecessor-version":[{"id":18538,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18535\/revisions\/18538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/18536"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=18535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=18535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=18535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}