{"id":185611,"date":"2021-07-08T19:29:58","date_gmt":"2021-07-08T17:29:58","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=185611"},"modified":"2021-07-08T19:29:58","modified_gmt":"2021-07-08T17:29:58","slug":"perseguita-la-sua-ex-e-finisce-in-carcere-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/08\/perseguita-la-sua-ex-e-finisce-in-carcere-2\/","title":{"rendered":"PERSEGUITA LA SUA EX E FINISCE IN CARCERE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-185612\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/07\/download-6.jpg\" alt=\"\" width=\"400\" height=\"218\" \/>(e.l.)______Sequestro di persona, violenza sessuale e atti persecutori. Sono pesanti le accuse con cui i Carabinieri del Comando Stazione di Racale (nella foto) hanno arrestato in flagranza di reato un giovane di Melissano di 38 anni, per il quale il pm di turno ha disposto che fosse rinchiuso nel carcere di Borgo San Nicola.<\/p>\n<p>Il provvedimento in seguito alle indagini dopo la denuncia della vittima, la ex convivente, che ha raccontato di essere stato segregata in casa dell&#8217;uomo e sottoposta a violenze e abusi per alcuni giorni, prima di riuscire ad avvertire di quanto stava accadendo un parente, il quale a sua volta ha chiamato subito i Carabinieri.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/08\/perseguita-la-sua-ex-e-finisce-in-carcere-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/08\/perseguita-la-sua-ex-e-finisce-in-carcere-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______Sequestro di persona, violenza sessuale e atti persecutori. Sono pesanti le accuse con cui i Carabinieri del Comando Stazione di Racale (nella foto) hanno arrestato in flagranza di reato un giovane di Melissano di 38 anni, per il quale il pm di turno ha disposto che fosse rinchiuso nel carcere di Borgo San Nicola. Il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":185612,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/185611"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=185611"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/185611\/revisions"}],"predecessor-version":[{"id":185613,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/185611\/revisions\/185613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/185612"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=185611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=185611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=185611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}