{"id":185861,"date":"2021-07-15T10:20:59","date_gmt":"2021-07-15T08:20:59","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=185861"},"modified":"2021-07-15T10:20:59","modified_gmt":"2021-07-15T08:20:59","slug":"libri-e-semi-camminano-insieme-a-taviano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/15\/libri-e-semi-camminano-insieme-a-taviano\/","title":{"rendered":"&#8220;Libri e semi camminano insieme a Taviano&#8221;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-185862\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/07\/IMG-20210713-WA0080.jpg\" alt=\"\" width=\"630\" height=\"284\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/07\/IMG-20210713-WA0080.jpg 630w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/07\/IMG-20210713-WA0080-300x135.jpg 300w\" sizes=\"(max-width: 630px) 100vw, 630px\" \/>Riceviamo e volentieri pubblichiamo. Tiziana Colluto ci manda il seguente comunicato______<\/p>\n<p>IN MARCIA TRA PAESAGGI E VARIET\u00c0 ANTICHE<\/p>\n<p>Libri e semi camminano insieme a Taviano: il connubio inedito<\/p>\n<p>protagonista della passeggiata ecologica nell\u2019ambito di \u201cLeggere tra due mari\u201d, il progetto che valorizza le biblioteche pubbliche del Salento<\/p>\n<p>VENERD\u00cc 16 LUGLIO, h 18.30, LIDO PIZZO-MARINA DI MANCAVERSA<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019idea \u00e8 quella di dare ai libri le gambe su cui camminare, per raggiungere le persone pi\u00f9 distratte e meno avvezze alla lettura e legare tra loro i temi e le realt\u00e0 pi\u00f9 impensate: \u201cIn marcia tra paesaggi e variet\u00e0 antiche\u201d \u00e8 molto di pi\u00f9 di una semplice passeggiata ecologica e unisce musica, letture, dialoghi, scambi di semi, mostra pomologica. L\u2019appuntamento \u00e8 per venerd\u00ec 16 luglio, alle ore 18.30, tra localit\u00e0 Lido Pizzo e la Marina di Mancaversa, a Taviano.<\/p>\n<p>L&#8217;evento \u00e8 a cura di Comune di Taviano, Biblioteca comunale Abatelillo, associazione BiblioIdee di Lettura e Consulta Giovani e rientra nel cartellone estivo di &#8220;Leggere tra due mari&#8221;, il progetto di valorizzazione delle biblioteche salentine ideato da Libera Compagnia di Aradeo e Associazione Amici della Biblioteca di Tuglie, con il sostegno di Fondazione CON IL SUD e Centro per il libro e la lettura e il coinvolgimento di un ampio partenariato territoriale. Il progetto gode del patrocinio dell\u2019Associazione Italiana Biblioteche e del Polo bibliomuseale leccese.<\/p>\n<p>&nbsp;<\/p>\n<p>COME SI SVOLGER\u00c0 L\u2019EVENTO. Il ritrovo \u00e8 alle 18.30 di venerd\u00ec 16 luglio in localit\u00e0 Lido Pizzo, a sud di Gallipoli. Dal lido Cotriero prender\u00e0 il via la marcia che per due chilometri attraverser\u00e0, a piedi o in bicicletta, un paesaggio prettamente costiero, per giungere alle 19.30 sul lungomare di Mancaversa, dinanzi alla spiaggia del Mare dei Cavalli. L\u00ec, dopo un intermezzo musicale umoristico a cura di P40, si terr\u00e0 la presentazione di \u201cGiacimenti di biodiversit\u00e0-Guida tra paesaggi e variet\u00e0 antiche nei parchi leccesi\u201d con gli autori Francesco Minonne e Francesca Casaluci. Per l\u2019occasione sar\u00e0 allestita una mostra pomologica e si terr\u00e0 uno scambio di semi.<\/p>\n<p>&nbsp;<\/p>\n<p>IN MARCIA PER LA BIODIVERSIT\u00c0 SALENTINA. La \u201cfatica\u201d della marcia \u00e8 legata al senso di attraversamento di un paesaggio che non \u00e8 solo quello geografico, da Punta Pizzo a Marina di Mancaversa, ma \u00e8 anche quello botanico e agrario, per unire le terre che vanno dai \u201cpummidori a Pappacocu\u201d al cappero di Racale, dal fico d\u2019india Sulfarina al fico borsamele, dall\u2019arancia Piattello di Alezio ai caprifichi di Ugento, dal pisello riccio di Sannicola al sedano di Torrepaduli. La camminata, cos\u00ec, diventa il pretesto per esplorare e imparare a conoscere la biodiversit\u00e0 dell\u2019arco ionico e per metterla in relazione con quella della sponda di levante: non a caso i semi donati da contadini e famiglie del posto e scambiati con i libri saranno consegnati, durante la decima edizione della Notte Verde di Castiglione d\u2019Otranto (27-31 agosto), alla \u201cbiblioteca dei semi\u201d allestita nel \u201cVivaio dell\u2019Inclusione Luigi Russo\u201d dall\u2019associazione Casa delle Agriculture Tullia e Gino, altro partner di \u201cLeggere tra due mari\u201d.<\/p>\n<p>LO SCAMBIO SEMI-LIBRI. In questi giorni, la Consulta Giovani di Taviano ha gi\u00e0 avviato una raccolta di semi, piccoli frutti antichi e ortaggi di stagione tra le famiglie a cui sono stati consegnati i libri prenotati in biblioteca. Inoltre, venerd\u00ec pomeriggio i giovani distribuiranno gratuitamente la guida \u201cGiacimenti di Biodiversit\u00e0\u201d a chi ne far\u00e0 richiesta e la dislocheranno in punti nevralgici (bar, edicole, etc.) in cui potr\u00e0 essere liberamente consultata. In questo modo, \u00e8 stata arricchita di nuovo significato \u201cC\u2019\u00e8 posta per te\u201d, l\u2019azione del progetto \u201cLeggere tra due mari\u201d che ha introdotto il servizio di green delibery, cio\u00e8 di consegna a domicilio dei libri chiesti in prestito. Da dieci mesi, in vari comuni, tra cui Taviano, questo nuovo modo di fruire del patrimonio culturale, inizialmente pensato per anziani e persone con disabilit\u00e0, \u00e8 stato ampliato a tutti i cittadini, per far fronte alle nuove necessit\u00e0 sorte durante la pandemia. \u00ab\u201cLeggere tra due mari\u201d \u2013 spiega Sofia Ungaro, responsabile della biblioteca di Taviano \u2013 considera la promozione della lettura uno strumento per ridurre le diseguaglianze sociali, attraverso iniziative innovative ed inclusive. In questo modo, i cittadini non sono solo fruitori dell\u2019offerta culturale ma protagonisti attivi e indispensabili di un processo di innovazione culturale e sociale\u00bb.<\/p>\n<p>LA GUIDA \u201cGIACIMENTI DI BIODIVERSIT\u00c0\u201d. \u201cGiacimenti di Biodiversit\u00e0-Guida tra paesaggi e variet\u00e0 antiche nei parchi leccesi\u201d \u00e8 prodotta dal Parco Costa Otranto &#8211; S.Maria di Leuca e Bosco di Tricase e nasce nell&#8217;ambito del Progetto &#8220;Biodiversit\u00e0 in rete&#8221; finanziato dal MIUR, per valorizzare l&#8217;agro-biodiversit\u00e0 custodita nelle aree protette e nei territori limitrofi della provincia di Lecce. Pi\u00f9 che un atlante delle variet\u00e0 locali, la guida offre spunti conoscitivi per ulteriori approfondimenti in tema di conservazione della biodiversit\u00e0 agraria. Per ogni area protetta sono state scelte variet\u00e0 orticole e fruttifere che possono essere rappresentative sia di entit\u00e0 comuni che di rarit\u00e0 eccezionali di quella zona. Le aree indagate sono: Parco naturale regionale \u201cBosco e Paludi di Rauccio\u201d; Riserva naturale statale \u201cLe Cesine\u201d e dintorni; Parco naturale regionale \u201cCosta Otranto Santa Maria di Leuca e Bosco di Tricase\u201d; Parco Naturale regionale \u201cLitorale di Ugento\u201d; Parco \u201cIsola di Sant\u2019Andrea e Litorale di Punta Pizzo\u201d; Parco Porto Selvaggio e Palude del Capitano; Riserva naturale orientata regionale \u201cPalude del Conte e duna costiera-Porto Cesareo\u201d. Di grande interesse \u00e8 anche l\u2019approfondimento sui \u201cPaesaggi rurali relitti\u201d, giacimenti di biodiversit\u00e0 autentici, come masserie, terrazzamenti costieri, percorsi dei pascoli, \u201cmantagnate\u201d (luoghi riparati dal vento), il \u201cbenificatu\u201d (terreni sassosi concessi ai contadini per la bonifica e in cui si piantava soprattutto il fico), i \u201ccurtali\u201d o \u201cncurtaturi\u201d (piccoli fortini con muri alti, soprattutto nelle aree periurbane).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/15\/libri-e-semi-camminano-insieme-a-taviano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/15\/libri-e-semi-camminano-insieme-a-taviano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Tiziana Colluto ci manda il seguente comunicato______ IN MARCIA TRA PAESAGGI E VARIET\u00c0 ANTICHE Libri e semi camminano insieme a Taviano: il connubio inedito protagonista della passeggiata ecologica nell\u2019ambito di \u201cLeggere tra due mari\u201d, il progetto che valorizza le biblioteche pubbliche del Salento VENERD\u00cc 16 LUGLIO, h 18.30, LIDO PIZZO-MARINA DI [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":185862,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/185861"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=185861"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/185861\/revisions"}],"predecessor-version":[{"id":185863,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/185861\/revisions\/185863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/185862"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=185861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=185861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=185861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}