{"id":186261,"date":"2021-07-25T13:08:17","date_gmt":"2021-07-25T11:08:17","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=186261"},"modified":"2021-07-25T13:10:05","modified_gmt":"2021-07-25T11:10:05","slug":"tenta-di-uccidere-la-moglie-poi-si-butta-dal-balcone","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/25\/tenta-di-uccidere-la-moglie-poi-si-butta-dal-balcone\/","title":{"rendered":"TENTA DI UCCIDERE LA MOGLIE, POI SI BUTTA DAL BALCONE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-186262\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/07\/unnamed-24.jpg\" alt=\"\" width=\"512\" height=\"255\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/07\/unnamed-24.jpg 512w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/07\/unnamed-24-300x149.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>(e.l.)______A solo due giorni di distanza dall&#8217;ultimo episodio del genere, nuovo dramma della follia a Taranto. Questa notte un uomo di 40 anni ha tentato di uccidere la moglie, poi si \u00e8 buttato nel vuoto dal balcone della sua casa dal quarto piano di un palazzo del centro.<\/p>\n<p>La donna \u00e8 riuscita a divincolarsi e a schivare i colpi di forbice pi\u00f9 pericolosi con cui era stata aggredita, ha preso i due figli pi\u00f9 piccoli presenti ed \u00e8 scappata per le scale, mettendosi cos\u00ec in salvo, insieme ai\u00a0 bambini.<\/p>\n<p>Ora si trova ricoverata all&#8217;ospedale Santissima Annunziata (nella foto), ma le sue condizioni non sono gravi, ha riportato solo ferite leggere.<\/p>\n<p>L&#8217;uomo \u00e8 morto sul colpo, quando sono arrivati i sanitari del 118 non c&#8217;era pi\u00f9 niente da fare.<\/p>\n<p>Indagini della Polizia di Stato in corso.<\/p>\n<p>______<\/p>\n<p>LA RICERCA nel nostro articolo del 23 luglio scorso<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"Y7myksfuOF\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/23\/uccide-la-moglie-a-coltellate-e-tenta-il-suicidio\/\">UCCIDE LA MOGLIE A COLTELLATE, E TENTA IL SUICIDIO<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/23\/uccide-la-moglie-a-coltellate-e-tenta-il-suicidio\/embed\/#?secret=Y7myksfuOF\" data-secret=\"Y7myksfuOF\" width=\"500\" height=\"282\" title=\"&#8220;UCCIDE LA MOGLIE A COLTELLATE, E TENTA IL SUICIDIO&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/25\/tenta-di-uccidere-la-moglie-poi-si-butta-dal-balcone\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/25\/tenta-di-uccidere-la-moglie-poi-si-butta-dal-balcone\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______A solo due giorni di distanza dall&#8217;ultimo episodio del genere, nuovo dramma della follia a Taranto. Questa notte un uomo di 40 anni ha tentato di uccidere la moglie, poi si \u00e8 buttato nel vuoto dal balcone della sua casa dal quarto piano di un palazzo del centro. La donna \u00e8 riuscita a divincolarsi e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":186262,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/186261"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=186261"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/186261\/revisions"}],"predecessor-version":[{"id":186265,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/186261\/revisions\/186265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/186262"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=186261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=186261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=186261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}