{"id":186380,"date":"2021-07-27T13:12:20","date_gmt":"2021-07-27T11:12:20","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=186380"},"modified":"2021-07-27T16:16:22","modified_gmt":"2021-07-27T14:16:22","slug":"arrestato-figlio-violento-che-maltratta-il-padre","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/27\/arrestato-figlio-violento-che-maltratta-il-padre\/","title":{"rendered":"ARRESTATO FIGLIO VIOLENTO CHE MALTRATTA IL PADRE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-186381\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/07\/unnamed-27.jpg\" alt=\"\" width=\"408\" height=\"306\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/07\/unnamed-27.jpg 408w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/07\/unnamed-27-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/07\/unnamed-27-400x300.jpg 400w\" sizes=\"(max-width: 408px) 100vw, 408px\" \/>(e.l.)______I Carabinieri del Comando Stazione di Racale hanno arrestato ieri in flagranza di reato un uomo accusato di maltrattamenti in famiglia e di estorsione continuata nei confronti del padre convivente. Il pm di turno presso la Procura della Repubblica di Lecce (nella foto) ha disposto che fosse rinchiuso nel carcere di Borgo San Nicola.<\/p>\n<p>I militari sono intervenuti in quella casa\u00a0 dopo che era stata segnalata una lite, in cui il giovane aveva minacciato l&#8217;anziano con una cesoia e poi aveva dato in escandescenze, perch\u00e9 non aveva avuto i soldi che aveva chiesto.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/27\/arrestato-figlio-violento-che-maltratta-il-padre\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/07\/27\/arrestato-figlio-violento-che-maltratta-il-padre\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______I Carabinieri del Comando Stazione di Racale hanno arrestato ieri in flagranza di reato un uomo accusato di maltrattamenti in famiglia e di estorsione continuata nei confronti del padre convivente. Il pm di turno presso la Procura della Repubblica di Lecce (nella foto) ha disposto che fosse rinchiuso nel carcere di Borgo San Nicola. I [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":186381,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/186380"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=186380"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/186380\/revisions"}],"predecessor-version":[{"id":186382,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/186380\/revisions\/186382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/186381"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=186380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=186380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=186380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}