{"id":18642,"date":"2013-07-12T10:16:35","date_gmt":"2013-07-12T10:16:35","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=18642"},"modified":"2013-07-12T10:16:36","modified_gmt":"2013-07-12T10:16:36","slug":"mare-in-bus-potenziate-le-marine-di-melendugno","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/12\/mare-in-bus-potenziate-le-marine-di-melendugno\/","title":{"rendered":"&#8220;MARE IN BUS&#8221;, POTENZIATE LE MARINE DI MELENDUGNO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Unknown10.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Unknown10.jpeg\" alt=\"\" width=\"240\" height=\"177\" class=\"alignleft size-full wp-image-18643\" \/><\/a>Auto in garage. Questa estate nelle cinque marine di Melendugno si va in bus. Il nuovo servizio di trasporto pubblico, tra l\u2019altro ecologico, \u00e8 stato presentato oggi a Palazzo Adorno a Lecce, dall\u2019assessore provinciale ai Trasporti e alla Mobilit\u00e0 Bruno Ciccarese, dal sindaco del Comune di Melendugno Marco Pot\u00ec e dall\u2019assessore comunale al Turismo Anna Elisa Prete.<\/p>\n<p>l progetto \u201cMare in bus\u201d promosso dal Comune di Melendugno, ed autorizzato dalla Provincia di Lecce che ha la competenza in materia, partir\u00e0 in questo fine settimana nelle marine di Torre Specchia, San Foca, Roca, Torre Dell\u2019Orso, Torre Saracena, Torre Sant\u2019Andrea.<\/p>\n<p>L\u2019iniziativa del tutto sperimentale \u00e8 la prima del genere nel Salento ed integrer\u00e0 il sistema di trasporto pubblico gi\u00e0 garantito dalla Provincia di Lecce attraverso le linee di Salentoinbus.<\/p>\n<p>I mini bus elettrici in dotazione effettueranno il servizio di trasporto per otto ore giornaliere con una sosta di due ore tra la mattina e il pomeriggio per permettere ai mezzi di ricaricarsi. In tutto circoleranno tre navette composte da 14 posti ciascuna. In particolare, la Linea A collegher\u00e0 Torre Specchia a San Foca, la linea B San Foca a Torre dell\u2019Orso e la Linea C Torre dell\u2019Orso a Sant\u2019Andrea.<\/p>\n<p>Le corse con frequenza ogni 20 minuti sono state studiate tenendo conto del tempo di autonomia del mezzo e della sicurezza delle fermate, collegate con i parcheggi posti nell\u2019entroterra, con le spiagge e il sito archeologico di Roca Vecchia. Sui flyers che saranno distribuiti su tutto il territorio saranno indicate i percorsi dei tre mini bus e le tariffe. Per tutte le informazioni ci si pu\u00f2 rivolgere all\u2019Ufficio informazioni e accoglienza turistica di Torre dell\u2019Orso (Portici) al numero 0832.841070.<\/p>\n<p>Le tariffe dei biglietti sono minime: 1 euro per la corsa semplice, 2 euro per l\u2019intera giornata senza limiti di utilizzo. L\u2019abbonamento settimanale coster\u00e0 7 euro; mensile 20 euro.<\/p>\n<p>Il servizio di trasporto sar\u00e0 completamente gratuito per i possessori della Melendugno card, una carta di servizi concessa a tutti i clienti di alberghi e strutture ricettive che pagano l\u2019imposta di soggiorno .<\/p>\n<p>Il progetto \u201cMare in bus\u201d coster\u00e0 circa 40 mila euro, di cui 33 mila finanziati con i proventi della tassa di soggiorno, mentre la restante parte sar\u00e0 a carico del gestore.<\/p>\n<p>Soddisfatto per l\u2019iniziativa l\u2019assessore provinciale ai Trasporti e alla Mobilit\u00e0 Bruno Ciccarese ha dichiarato: \u201cQuesto progetto sperimentale non ha eguali nel Salento ed \u00e8 stato pensato e progettato in maniera tale da risultare integrativo al sistema di trasporto di Salentoinbus che la Provincia di Lecce garantisce ormai da alcuni anni su tutto il territorio provinciale, con grandi sforzi ripagati da ottimi risultati. L\u2019augurio \u00e8 che anche altri Comuni salentini seguano l\u2019esempio virtuoso del Comune di Melendugno\u201d.<\/p>\n<p>Il sindaco del Comune di Melendugno Marco Pot\u00ec ha spiegato il senso dell\u2019iniziativa: \u201cMare in bus rappresenta per il nostro Comune un fatto epocale in quanto \u00e8 da tempo che si parla della necessit\u00e0 di istituire un servizio di trasporto pubblico nelle Marine. Questo progetto rappresenta un esempio di mobilit\u00e0 sostenibile e di riqualificazione dell\u2019offerta turistica con la finalit\u00e0 di limitare l\u2019uso dei mezzi meccanici riducendo cos\u00ec il traffico veicolare e l\u2019inquinamento acustico e ambientale\u201d.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/12\/mare-in-bus-potenziate-le-marine-di-melendugno\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/12\/mare-in-bus-potenziate-le-marine-di-melendugno\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Auto in garage. Questa estate nelle cinque marine di Melendugno si va in bus. Il nuovo servizio di trasporto pubblico, tra l\u2019altro ecologico, \u00e8 stato presentato oggi a Palazzo Adorno a Lecce, dall\u2019assessore provinciale ai Trasporti e alla Mobilit\u00e0 Bruno Ciccarese, dal sindaco del Comune di Melendugno Marco Pot\u00ec e dall\u2019assessore comunale al Turismo Anna [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18643,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18642"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=18642"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18642\/revisions"}],"predecessor-version":[{"id":18645,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18642\/revisions\/18645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/18643"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=18642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=18642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=18642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}