{"id":18696,"date":"2013-07-15T09:18:36","date_gmt":"2013-07-15T09:18:36","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=18696"},"modified":"2013-07-15T09:18:36","modified_gmt":"2013-07-15T09:18:36","slug":"salentown-reggae-festival","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/15\/salentown-reggae-festival\/","title":{"rendered":"SALENTOWN REGGAE FESTIVAL"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/BodyPart4.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/BodyPart4-300x199.png\" alt=\"\" width=\"300\" height=\"199\" class=\"alignleft size-medium wp-image-18697\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/BodyPart4-300x199.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/BodyPart4.png 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Sabato 3 agosto (ore 21.00 &#8211; ingresso 5 euro) il Campo Sportivo di Neviano, in provincia di Lecce ospita Salentown Reggae Festival con alcune delle migliori realt\u00e0 del panorama reggae italiano e alcuni ospiti internazionali.<\/p>\n<p>Nel corso della serata si alterneranno Boom Boom Vibration che, dopo il successo internazionale di &#8220;Rumors&#8221;, &#8220;Dem Know&#8221; e &#8220;Vibra unica&#8221; sono pronti per presentare il loro nuovissimo singolo seguito dal videoclip, &#8220;Ciao Ciao Italia&#8221; prodotto da Alborosie presso gli Shengen Studios di Kingston in Jamaica; Jah Sun, artista californiano di fama internazionale che si \u00e8 aggiudicato dagli utenti del web il titolo di &#8220;Best International Reggae Album 2012&#8221; dal Positive Vibration Reggae Awards con il suo &#8220;2 Battle the Dragon e che proporr\u00e0 i brani del suo nuovo cd &#8220;Rise as One&#8221;; Lion D, fresco di featuring internazionale con Skarramucci, big della reggae music, \u00e8 carico per infiammare la yard. &#8220;Nuh Ramp&#8221; \u00e8 il suo ultimo successo prodotto dalla prolifica Bizzarri Familia; El-V &amp; The GardenHouse, per la prima volta in salento. La storica band bolognese capitanata da Marco Vecchi far\u00e0 ballare la massive a suon di reggae Latino-Emiliano. &#8220;Desde la Calle&#8221; \u00e8 il loro successo pi\u00f9 fresco; Nico Royale ovvero il Singa di Sasso Marconi, anche lui, per la prima volta in salento con la sua crew &#8220;Montagna di Suono&#8221; riempie di positive vibez le colline bolognesi. il suo singolo pi\u00f9 ascoltato sul web \u00e8 &#8220;L&#8217;erba della montagna&#8221;; Cico &amp; Mamafrika, progetto della calda voce, gi\u00e0 spalla di Roy Paci nel tormentone &#8220;Toda joia toda beleza&#8221;, ospite dei Negrita ne &#8220;Un giorno di ordinaria Magia&#8221;, attualmente in tour con i salentini Bundamove, vibrer\u00e0 con tutta la sua storica band. I Mamafrika si esibiranno, infatti, per la prima volta in salento; Lu Tony, giovanissimo mc salentino &#8220;emigrato al nord&#8221; che canta con talento. il suo singolo pi\u00f9 famoso \u00e8 &#8220;Defriscu te ddiu&#8221; con il quale si \u00e8 classificato al secondo posto del talent show &#8220;Em\u00e8rgenti&#8221;. Le selezioni sono affidate a Koolomeeto, Rubio &amp; Rocky, Paparina Silecta, Labo Sound.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/15\/salentown-reggae-festival\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/15\/salentown-reggae-festival\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Sabato 3 agosto (ore 21.00 &#8211; ingresso 5 euro) il Campo Sportivo di Neviano, in provincia di Lecce ospita Salentown Reggae Festival con alcune delle migliori realt\u00e0 del panorama reggae italiano e alcuni ospiti internazionali. Nel corso della serata si alterneranno Boom Boom Vibration che, dopo il successo internazionale di &#8220;Rumors&#8221;, &#8220;Dem Know&#8221; e &#8220;Vibra [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18697,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18696"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=18696"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18696\/revisions"}],"predecessor-version":[{"id":18698,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18696\/revisions\/18698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/18697"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=18696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=18696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=18696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}