{"id":18735,"date":"2013-07-16T14:30:11","date_gmt":"2013-07-16T14:30:11","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=18735"},"modified":"2013-07-16T14:34:08","modified_gmt":"2013-07-16T14:34:08","slug":"la-cittadinanza-onoraria-di-campi-salentina-a-saba-anglana","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/16\/la-cittadinanza-onoraria-di-campi-salentina-a-saba-anglana\/","title":{"rendered":"FINETERRA A CAMPI SALENTINA, TRA MUSICA E SAPORI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/saba-anglana-41.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/saba-anglana-41-272x300.jpg\" alt=\"\" width=\"272\" height=\"300\" class=\"alignleft size-medium wp-image-18736\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/saba-anglana-41-272x300.jpg 272w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/saba-anglana-41-929x1024.jpg 929w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/saba-anglana-41.jpg 1002w\" sizes=\"(max-width: 272px) 100vw, 272px\" \/><\/a>FINETERRA fa tappa a Campi Salentina per uno degli appuntamenti pi\u00f9 significativi dell\u2019edizione 2013 della Rassegna. Nella ricorrenza dei 50 anni dalla Fondazione dell\u2019Unione Africana, La Provincia di Lecce, con l\u2019Istituto di Culture Mediterranee e il Comune di Campi hanno voluto celebrare questa importante ricorrenza con un gesto carico di significati politici, umanitari ed affettivi Insieme.<\/p>\n<p>Il 18 luglio alle ore 20 presso la sala consiliare del Comune di Campi si terr\u00e0 la cerimonia ufficiale di conferimento alla cantante Italo- Somala Saba Anglana della cittadinanza onoraria.<\/p>\n<p>Forse pochi lo sanno ma le radici della bravissima artista sono Salentine. Il padre di Saba Anglana, come denuncia il cognome, era proprio di Campi Salentina.<\/p>\n<p>Ma la scelta dell\u2019Amministrazione di Campi non \u00e8 dettata soltanto da motivi campanilistici, essa vuole essere anche un riconoscimento al talento artistico della cantante e alla sue battaglie per l\u2019accesso all\u2019acqua per le popolazioni africane in favore delle campagne umanitarie di AMREF nell\u2019Africa Orientale.<\/p>\n<p>Testimone di Saba Anglana nella cerimonia ufficiale di conferimento della cittadinanza onoraria sar\u00e0 la giornalista RAI e direttore di RAINEWS 24, Monica Maggioni.<\/p>\n<p>Alla cerimonia prenderanno parte anche il presidente della Provincia di Lecce Antonio Gabellone, la Vpresidente Simona Manca e l\u2019Assessore Massimo Como.<\/p>\n<p>Alle 22, in Piazza libert\u00e0 si terr\u00e0 l\u2019atteso concerto di Saba Anglana.\u00a0I concerti di Saba Anglana sono eventi travolgenti, ricchi di significati, di culture musicali, di ibridazione, di Africa e Italia, di futuro della societ\u00e0 italiana.<\/p>\n<p>Nella band Saba, voce,Tat\u00e8 Nsongan, chitarra, Cheikh Fall, djembe, drum e kora, Martino Roberts al basso<\/p>\n<p>L&#8217;Africa dell&#8217;Est \u00e8 il nodo vitale di diverse culture in cui Saba \u00e8 nata.<\/p>\n<p>Questa geografia fisica ed emozionale fa da sfondo attivo al concerto che si fa racconto.<\/p>\n<p>Diventa dialogo polifonico tra i personaggi e i luoghi che evoca l&#8217;artista dalla sua galleria privata: memorie, visi, corpi, canti, profumi, sapori, immagini, episodi descritti e concertati per risuonare insieme. A nutrire il percorso in musica, non solo l&#8217;Africa dei natali e dell&#8217;albero genealogico, ma soprattutto la recente esperienza in Kenya attraverso i villaggi e le comunit\u00e0 assistite da Amref, di cui Saba \u00e8 Testimonial.<\/p>\n<p>Le storie che ne derivano sono state raccolte nel territorio comune dell&#8217;incontro, senza nessuna ossessione per le tradizioni: in terra d&#8217;Africa come sul palco, la musica ha l&#8217;ambizione di offrire ponti immediati di comunicazione. Nuovi territori dove ci si racconta senza necessit\u00e0 di difendere la propria identit\u00e0 culturale dall&#8217;esperienza di un cambiamento. L&#8217;immaginazione trasforma cos\u00ec il pubblico da audience a vero e proprio compagno di viaggio.<\/p>\n<p>E questo viaggio \u00e8 la chiave di una visione pi\u00f9 ampia, dal particolare del proprio vissuto all&#8217;universale condivisibile in cui vibrano, a tempo di musica, diversi livelli di coscienza.<\/p>\n<p>Saba presenta il suo concerto con Cheikh Fall alla kora, e Tat\u00e8 Nsongan alla chitarra che tessono con lei il tessuto di note e parole, suoni e voci, lingue e linguaggi: dal somalo all&#8217;amarico, dallo swahili all&#8217;inglese.<\/p>\n<p>&#8220;La vita ci mescola&#8221;, in swahili &#8220;Life changanysha&#8221;, appunto, come cita il titolo del suo ultimo album.<\/p>\n<p>Gusto autentico all&#8217;insegna della contaminazione creativa tra culture e nazioni nel secondo appuntamento targato Coldiretti, nell&#8217;ambito del festival &#8220;Fineterra&#8221;. Si\u00a0 chiama &#8220;Il Salento incontra nel piatto di Campagna Amica i sapori dell&#8217;Africa&#8221; la degustazione che avr\u00e0 luogo <span style=\"text-decoration: underline\">gioved<\/span><span style=\"text-decoration: underline\">\u00ec<\/span><span style=\"text-decoration: underline\"> 18 luglio, alle ore 21, nella sala comunale del<\/span> <span style=\"text-decoration: underline\">Municipio di Campi Salentina<\/span>. Coldiretti offrir\u00e0 un aperitivo ispirato ad una ricetta afro-mediterranea, scelta ad hoc per la serata dalla congolese <strong>Victoire Bouna Gouloubi<\/strong>, chef- executive del ristorante l\u2019Incoronata (corso Garibaldi) a Milano.<\/p>\n<p>La professionista, cresciuta nelle cucine di chef stellati del calibro di Claudio Sadler, Marc Farellacci e Fabrizio Ferrari, ha voluto donare al Salento una ricetta che mescola sapientemente e in modo assolutamente inedito\u00a0 prodotti a &#8220;chilometro zero&#8221; e antiche tradizioni culinarie del Continente Nero. Un momento dal forte impatto simbolico che seguir\u00e0 all&#8217;assegnazione della cittadinanza onoraria tribuita all&#8217;artista italo-somala Saba Anglana.<\/p>\n<p>L&#8217;arte culinaria, con il suo linguaggio universale e unificante, diventa cos\u00ec occasione privilegiata di contaminazioni tra gusti e culture, in un Salento che \u00e8 da sempre crocevia di storia e popoli, luogo di rara fascinazione dove tutto ha avuto inizio.<\/p>\n<p>&#8220;Ma proprio dai cultori dell&#8217;arte culinaria &#8211; dice il direttore di Coldiretti Lecce, <strong>Benedetto De Serio<\/strong> &#8211; deve nascere il convincimento che non \u00e8 pi\u00f9 possibile globalizzare tutto senza globalizzare anche le regole. Diversamente non si tiene sufficientemente conto delle esigenze delle persone. Nel mondo vi \u00e8 il problema dell&#8217;accesso al cibo ma occorre contrastare il paradosso del sistema globale che ha declassato il cibo a merce. Domani al problema dell&#8217;accessibilit\u00e0 al cibo si aggiunger\u00e0 probabilmente anche quello della sua scarsit\u00e0, pertanto occorre un governo globale dei beni comuni come il cibo, l&#8217;acqua e il suolo&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/16\/la-cittadinanza-onoraria-di-campi-salentina-a-saba-anglana\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/16\/la-cittadinanza-onoraria-di-campi-salentina-a-saba-anglana\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>FINETERRA fa tappa a Campi Salentina per uno degli appuntamenti pi\u00f9 significativi dell\u2019edizione 2013 della Rassegna. Nella ricorrenza dei 50 anni dalla Fondazione dell\u2019Unione Africana, La Provincia di Lecce, con l\u2019Istituto di Culture Mediterranee e il Comune di Campi hanno voluto celebrare questa importante ricorrenza con un gesto carico di significati politici, umanitari ed affettivi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18736,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18735"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=18735"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18735\/revisions"}],"predecessor-version":[{"id":18738,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18735\/revisions\/18738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/18736"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=18735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=18735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=18735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}