{"id":18840,"date":"2013-07-19T09:39:44","date_gmt":"2013-07-19T09:39:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=18840"},"modified":"2013-07-19T09:39:44","modified_gmt":"2013-07-19T09:39:44","slug":"riconoscimento-dop-per-la-patata-novella-di-galatina","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/19\/riconoscimento-dop-per-la-patata-novella-di-galatina\/","title":{"rendered":"RICONOSCIMENTO DOP PER LA PATATA NOVELLA DI GALATINA"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Novella03.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Novella03-300x180.jpg\" alt=\"\" width=\"300\" height=\"180\" class=\"alignleft size-medium wp-image-18841\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Novella03-300x180.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Novella03.jpg 460w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Nella giornata di mercoled\u00ec 17 Luglio u.s. si \u00e8 tenuto presso la sala San Sebastiano del Municipio di Racale una importantissima riunione di pubblico accertamento finalizzata all\u2019ottenimento definitivo della DOP \u2013 Denominazione di Origine Protetta della \u201cPatata novella di Galatina\u201d.<\/p>\n<p style=\"text-align: justify\">\u201cUn primo fondamentale passo \u2013 secondo il Direttore della Coldiretti di Lecce Benedetto De Serio \u2013 che precede la decisione definitiva della Commissione Europea\u201d. Questo primo momento pubblico, peraltro estremamente partecipato, ha conseguito la condivisione da parte di tutti i portatori di interesse, del disciplinare predisposto dal Comitato promotore ed approvato dalla Regione. La riunione si \u00e8 svolta alla presenza dei funzionari ministeriali responsabili per la regolarizzazione della procedura autorizzativa che porter\u00e0, nei prossimi giorni, alla pubblicazione in Gazzetta Ufficiale del disciplinare. Trascorsi trenta giorni, il Comitato promotore potr\u00e0 richiedere l\u2019autorizzazione transitoria che potr\u00e0 essere rilasciata appena sar\u00e0 predisposto il relativo piano di controllo. L\u2019autorizzazione transitoria garantisce la produzione nazionale in attesa della pubblicazione sulla Gazzetta Ufficiale dell\u2019Unione Europea. Con l\u2019ottenimento dell\u2019autorizzazione transitoria non sar\u00e0 pi\u00f9 possibile utilizzare sul territorio nazionale il marchio e la denominazione \u201cPatata novella di Galatina\u201d se non conforme a quanto previsto dal disciplinare. Attraverso la DOP il mondo agricolo salentino potr\u00e0 rilanciare un prodotto che in passato ha rappresentato oltre il 60% delle esportazioni pugliesi di patate con l\u2019impiego di oltre 2000 vagoni ferroviari. Oggi le produzioni si sono ridotte anche a causa della marcata presenza di prodotto indifferenziato che giunge sui mercati del centro Europa. Il rilascio passa quindi attraverso una pi\u00f9 efficiente riorganizzazione economica che sappia coniugare qualit\u00e0 e distintivit\u00e0 del prodotto.<\/p>\n<p style=\"text-align: justify\">Non \u00e8 pi\u00f9 rinviabile la costituzione di una OP \u2013 Organizzazione di Produttori, che attraverso piani operativi cofinanziati da Bruxelles, consenta ai produttori associati di accedere a strumenti economici, tecnici, finanziari che ne aumentino la competitivit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/19\/riconoscimento-dop-per-la-patata-novella-di-galatina\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/19\/riconoscimento-dop-per-la-patata-novella-di-galatina\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nella giornata di mercoled\u00ec 17 Luglio u.s. si \u00e8 tenuto presso la sala San Sebastiano del Municipio di Racale una importantissima riunione di pubblico accertamento finalizzata all\u2019ottenimento definitivo della DOP \u2013 Denominazione di Origine Protetta della \u201cPatata novella di Galatina\u201d. \u201cUn primo fondamentale passo \u2013 secondo il Direttore della Coldiretti di Lecce Benedetto De Serio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18841,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18840"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=18840"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18840\/revisions"}],"predecessor-version":[{"id":18843,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18840\/revisions\/18843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/18841"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=18840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=18840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=18840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}