{"id":18850,"date":"2013-07-19T15:06:30","date_gmt":"2013-07-19T15:06:30","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=18850"},"modified":"2013-07-19T15:06:30","modified_gmt":"2013-07-19T15:06:30","slug":"navigabile-2013-domenica-a-san-foca-ed-otranto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/19\/navigabile-2013-domenica-a-san-foca-ed-otranto\/","title":{"rendered":"\u201cNAVIGABILE 2013\u201d: DOMENICA A SAN FOCA ED OTRANTO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/image1.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/image1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" class=\"alignleft size-medium wp-image-18851\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/image1-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/image1.jpeg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Continua a solcare il mare del Salento \u201cNavigabile 2013\u201d, il progetto realizzato dall\u2019assessorato alle Politiche sociali e Pari opportunit\u00e0 della Provincia di Lecce e dalla Lega Navale Italiana \u2013 Circoscrizione Puglia Sud e Basilicata Jonica, in collaborazione con gli Ambiti territoriali sociali provinciali.<\/p>\n<p>Domenica 21 luglio, alle ore 10 saranno due le imbarcazioni con a bordo ragazzi diversamente abili che salperanno da Otranto e da San Foca. La partenza da quest\u2019ultima marina, infatti, prevista per il 7 luglio scorso, era stata rinviata a causa del maltempo.<\/p>\n<p>Il programma prevede due momenti di saluto dei rappresentanti istituzionali. Il primo a San Foca, alle ore 9.30, presso la sede della Lega navale dove, prima dell\u2019imbarco, interverranno l\u2019assessore provinciale alle Politiche sociali e alle Pari opportunit\u00e0 Filomena D\u2019Antini Solero, il sindaco del Comune di Melendugno Marco Pot\u00ec, il delegato regionale della Lega navale italiana Puglia Sud Basilicata Jonica Andrea Retucci. Saranno presenti, tra gli altri, i sindaci dei Comuni dell\u2019Ambito territoriale sociale provinciale e i rappresentanti delle Forze dell\u2019ordine.<\/p>\n<p>Il secondo appuntamento \u00e8 presso la sede della Lega navale di Otranto, dove alle ore 11.30, al rientro dalla visita in mare, interverranno per un breve saluto l\u2019assessore provinciale alle Politiche sociali e alle Pari opportunit\u00e0 Filomena D\u2019Antini Solero, il sindaco di Otranto Luciano Cariddi, il senatore e consigliere provinciale Francesco Bruni, il delegato regionale della Lega navale italiana Puglia Sud Basilicata Jonica Andrea Retucci, il presidente della Lega navale di Otranto Walter Melissano, il presidente dell\u2019Ambito sociale territoriale di Maglie Francesco De Giorgi. Parteciperanno anche i sindaci dei Comuni dell\u2019Ambito territoriale sociale provinciale di Maglie e i rappresentanti delle forze dell\u2019ordine.<\/p>\n<p>In tutto sono nove le tappe in programma di questa quarta edizione di \u201cNavigabile\u201d, gi\u00e0 approdato domenica scorsa a Casalabate.<\/p>\n<p>Avviato grazie al Protocollo d\u2019intesa siglato nel 2010, il progetto \u00e8 stato fortemente voluto e sostenuto dall\u2019assessore provinciale alle Politiche sociali Filomena D\u2019Antini Solero convinta che \u201cesperienze di contatto diretto con la natura possano avere straordinarie capacit\u00e0 terapeutiche per persone che hanno particolari difficolt\u00e0 e fragilit\u00e0\u201d.<\/p>\n<p>Con \u201cNavigabile 2013\u201d decine di ragazzi e ragazze diversamente abili hanno l\u2019opportunit\u00e0 di salire a bordo di imbarcazioni messe a disposizione dai soci della Lega navale, per conoscere da vicino il mare con le sue meravigliose risorse e vivere l\u2019emozione di solcarlo, guidati da esperti in navigazione. Il tutto con il coinvolgimento delle rispettive famiglie.<\/p>\n<p>I prossimi appuntamenti lungo la costa ionica ed adriatica sono: il 28 luglio a Frigole, il 4 agosto a Porto Cesareo, il 17 e il 18 agosto a Torre San Giovanni, il 25 agosto a Tricase, l\u20191 settembre a Santa Maria di Leuca e l\u20198 settembre a Gallipoli.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/19\/navigabile-2013-domenica-a-san-foca-ed-otranto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/19\/navigabile-2013-domenica-a-san-foca-ed-otranto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Continua a solcare il mare del Salento \u201cNavigabile 2013\u201d, il progetto realizzato dall\u2019assessorato alle Politiche sociali e Pari opportunit\u00e0 della Provincia di Lecce e dalla Lega Navale Italiana \u2013 Circoscrizione Puglia Sud e Basilicata Jonica, in collaborazione con gli Ambiti territoriali sociali provinciali. Domenica 21 luglio, alle ore 10 saranno due le imbarcazioni con a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18851,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18850"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=18850"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18850\/revisions"}],"predecessor-version":[{"id":18853,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18850\/revisions\/18853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/18851"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=18850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=18850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=18850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}