{"id":18854,"date":"2013-07-19T15:13:11","date_gmt":"2013-07-19T15:13:11","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=18854"},"modified":"2013-07-19T15:13:11","modified_gmt":"2013-07-19T15:13:11","slug":"parco-gondar-appuntamento-con-i-boom-da-bash","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/19\/parco-gondar-appuntamento-con-i-boom-da-bash\/","title":{"rendered":"PARCO GONDAR :APPUNTAMENTO CON I BOOM DA BASH"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Boom-Da-Bash-.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Boom-Da-Bash--300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" class=\"alignleft size-medium wp-image-18855\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Boom-Da-Bash--300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Boom-Da-Bash-.jpg 787w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Sabato 20 luglio<\/strong>, per i consueti e acclamati Reggae Saturday, \u00e8 lo scatenato live dei BOOM DA BASH a infiammare la Pineta! Il loro \u201cSuperheroes Tour\u201d tocca il PARCO GONDAR per presentare live &#8220;SuperHeroeS&#8221;, il terzo album uscito a giugno che nel titolo fa tributo ai veri eroi di questa Italia, precari e famiglie che faticano per arrivare a fine mese in un periodo storico dove sorridere non \u00e8 facile e \u201cReality Show\u201d, ultimo singolo estratto e nuovissimo video con la partecipazione dei Sud Sound System. &#8220;SuperHeroes&#8221; \u00e8 un album multiforme e imprevedibile come tutta la produzione della band salentina, un disco eterogeneo che sa sapientemente dosare le radici reggae con il soul, la drum&#8217;n&#8217;bass, l&#8217;Hip Hop, il tutto orchestrato da sintetizzatori, suoni elettronici, chitarre in levare e ritmi one drop, elementi che fanno dei BOOM DA BASH una delle voci pi\u00f9 interessanti ed innovative del panorama italiano. Le tredici tracce spaziano dalle classiche reggae love song, a canzoni dal mood estivo e ballabile fino ad arrivare a brani pi\u00f9 impegnati supportati da liriche pungenti, furbe e ironiche. Molte e varie le collaborazioni all&#8217;interno del disco, che spaziano dai corregionali e amici Sud Sound System, a due nomi storici dell&#8217;Hip Hop italiano come Clementino e Dj Double S, fino ad arrivare a Bobby Chin dei BlackChiney (storico sound system di cinesi giamaicani con base a Miami, Florida) e i Ward 21, famoso collettivo giamaicano di musicisti e producer dancehall e reggae.<\/p>\n<p>Ad aprire e chiudere la serata, saranno i dj salentini, amici storici del Gondar: Heart on fire sound, Kooloometoo Sound Bwoys, Paparina Sound. Il trio di dj far\u00e0 ballare il Parco Gondar con un ritmo travolgente che si protrarr\u00e0 fino all\u2019alba.<\/p>\n<p>Ingresso a 5 \u20ac.\u00a0Apertura cancelli ore 20:00, inizio concerti ore 22:30.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/19\/parco-gondar-appuntamento-con-i-boom-da-bash\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/19\/parco-gondar-appuntamento-con-i-boom-da-bash\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Sabato 20 luglio, per i consueti e acclamati Reggae Saturday, \u00e8 lo scatenato live dei BOOM DA BASH a infiammare la Pineta! Il loro \u201cSuperheroes Tour\u201d tocca il PARCO GONDAR per presentare live &#8220;SuperHeroeS&#8221;, il terzo album uscito a giugno che nel titolo fa tributo ai veri eroi di questa Italia, precari e famiglie che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18855,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18854"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=18854"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18854\/revisions"}],"predecessor-version":[{"id":18857,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18854\/revisions\/18857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/18855"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=18854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=18854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=18854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}