{"id":18873,"date":"2013-07-20T08:15:41","date_gmt":"2013-07-20T08:15:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=18873"},"modified":"2013-07-20T08:15:41","modified_gmt":"2013-07-20T08:15:41","slug":"arrestato-napolitano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/20\/arrestato-napolitano\/","title":{"rendered":"ARRESTATO NAPOLITANO"},"content":{"rendered":"<div><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/carabinieri-auto.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/carabinieri-auto-300x164.jpg\" alt=\"\" width=\"300\" height=\"164\" class=\"alignleft size-medium wp-image-14032\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/carabinieri-auto-300x164.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/carabinieri-auto.jpg 621w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u00a0<span style=\"color: #000000;font-family: Arial;font-size: x-small\">I militari della Stazione di Squinzano, questo pomeriggio,\u00a0hanno proceduto all&#8217;arresto di NAPOLETANO Roberto, nato a San Pietro Vernotico il 19.11.1986, residente a Squinzano, coniugato, pastore, pluripregiudicato, in esecuzione di una ordinanza di custodia cautelare in carcere emessa dal GIP di Lecce dott. Brancato su richiesta del PM dott. Gagliotta, in data odierna. Napoletano, il giorno 19.06.2013, mentre era agli arresti domiciliari, per sottrarsi alla perquisizione domiciliare eseguita dai militari della Stazione di Squinzano, colp\u00ec con calci, pugni e strattoni uno di essi, per poi correre tra i campi circostanti la sua abitazione.\u00a0Nell&#8217;occasione fu raggiunto dopo un lungo indseguimento da uno degli altri militari presenti. Il militare che sub\u00ec i reati di resistenza a pubblico ufficiale e lesioni personali, risult\u00f2 affetto da escoriazioni e contusioni guaribili in sette giorni.<\/span><\/div>\n<div><span style=\"color: #000000;font-family: Arial;font-size: x-small\">Napoletano, dopo le formalit\u00e0 di rito, \u00e8 stato condotto presso il carcere di Lecce.<\/span><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/20\/arrestato-napolitano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/20\/arrestato-napolitano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00a0I militari della Stazione di Squinzano, questo pomeriggio,\u00a0hanno proceduto all&#8217;arresto di NAPOLETANO Roberto, nato a San Pietro Vernotico il 19.11.1986, residente a Squinzano, coniugato, pastore, pluripregiudicato, in esecuzione di una ordinanza di custodia cautelare in carcere emessa dal GIP di Lecce dott. Brancato su richiesta del PM dott. Gagliotta, in data odierna. Napoletano, il giorno [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18873"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=18873"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18873\/revisions"}],"predecessor-version":[{"id":18874,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/18873\/revisions\/18874"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=18873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=18873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=18873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}