{"id":189396,"date":"2021-10-09T14:09:27","date_gmt":"2021-10-09T12:09:27","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=189396"},"modified":"2021-10-09T20:32:11","modified_gmt":"2021-10-09T18:32:11","slug":"un-bene-confiscato-alla-mafia-diviene-casa-della-salute-il-ministro-lamorgese-a-carmiano-per-la-consegna-dellimmobile-a-lilt-e-avis","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/10\/09\/un-bene-confiscato-alla-mafia-diviene-casa-della-salute-il-ministro-lamorgese-a-carmiano-per-la-consegna-dellimmobile-a-lilt-e-avis\/","title":{"rendered":"UN BENE CONFISCATO ALLA MAFIA DIVIENE &#8220;CASA DELLA SALUTE&#8221;. IL MINISTRO LUCIANA LAMORGESE A CARMIANO PER LA CONSEGNA DELL&#8217;IMMOBILE A LILT E AVIS"},"content":{"rendered":"<p><strong>\u00a0<img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-189402\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/10\/0dfaf79a-a99d-4e27-9a2c-09edcc0ceeca.jpg\" alt=\"\" width=\"1837\" height=\"1080\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/10\/0dfaf79a-a99d-4e27-9a2c-09edcc0ceeca.jpg 1837w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/10\/0dfaf79a-a99d-4e27-9a2c-09edcc0ceeca-300x176.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/10\/0dfaf79a-a99d-4e27-9a2c-09edcc0ceeca-1024x602.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/10\/0dfaf79a-a99d-4e27-9a2c-09edcc0ceeca-768x452.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/10\/0dfaf79a-a99d-4e27-9a2c-09edcc0ceeca-1536x903.jpg 1536w\" sizes=\"(max-width: 1837px) 100vw, 1837px\" \/>di Carmen Leo\u00a0\u00a0<\/strong><strong>______<em>\u201cQuesto luogo, dove un tempo regnava l\u2019illegalit\u00e0, sar\u00e0 da domani dedicato alle necessit\u00e0 delle persone fragili e voi sarete coloro i quali potranno offrire i servizi necessari a chi ne ha pi\u00f9 bisogno, in uno spazio fisico completamente riqualificato. La nostra presenza qui oggi in rappresentanza dello Stato che vigila attentamente a che la legalit\u00e0 venga sempre rispettata\u201d.<\/em><\/strong><\/p>\n<p>Cos\u00ec il Ministro dell\u2019Interno <strong>Luciana Lamorgese<\/strong> (al centro nella foto) alla cittadinanza di Carmiano, durante la cerimonia tenutasi ieri nel comune dell\u2019alto Salento, la cui Commissione Straordinaria, alla presenza anche del prefetto di Lecce, Maria Rosa Tria (a destra nella foto), ha consegnato alle gi\u00e0 note associazioni LILT \u2013 sezione provinciale di Lecce \u2013 e AVIS Carmiano, un immobile appartenuto ad un esponente di spicco della locale criminalit\u00e0 organizzata.<\/p>\n<p>Il bene, sequestrato nel 2015, era stato assegnato al Comune dall\u2019agenzia dei beni confiscati, ma sono trascorsi ben cinque anni, con l\u2019intervento della Commissione Prefettizia, prima che chi ne usufruiva indebitamente lo liberasse.<\/p>\n<p><em><strong>\u201cLe procedure di questo tipo sono lunghe, non sempre tutto dipende dall\u2019agenzia dei beni confiscati, poich\u00e9 esistono varie amministrazioni che si inseriscono nel procedimento, per\u00f2 lavoreremo insieme agli altri, la sinergia porta sempre ad aspetti che certamente si rivolgeranno in positivo anche sulle procedure\u201d<\/strong><\/em>&#8211;\u00a0 ha aggiunto il ministro dell&#8217;Interno per spiegare la lungaggine dei tempi di riassegnazione dell\u2019immobile.<\/p>\n<p>Opportunamente ristrutturato a seguito di procedura ad evidenza pubblica, il caseggiato sar\u00e0 ora trasformato in <em><strong>\u201cCasa della Salute\u201d<\/strong><\/em>, che fornir\u00e0 servizi sanitari utili alla comunit\u00e0.<\/p>\n<p>La presenza della Lamorgese attesta un evento di grande rilevanza in un paese la cui giunta comunale \u00e8 stata sciolta nel dicembre 2019 per infiltrazioni mafiose.<\/p>\n<p>Ministro dell\u2019Interno, Prefetto di Lecce e Commissario straordinario attestano, con il loro intervento a Carmiano, un forte e significativo impegno dello Stato italiano nella lotta alla criminalit\u00e0 organizzata, sottraendo ad essa, proprio con la confisca di questi beni acquisiti illegalmente, potere e importanza sul territorio.<\/p>\n<p><strong>La Legge accanto e a protezione dei cittadini onesti.\u00a0<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/10\/09\/un-bene-confiscato-alla-mafia-diviene-casa-della-salute-il-ministro-lamorgese-a-carmiano-per-la-consegna-dellimmobile-a-lilt-e-avis\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/10\/09\/un-bene-confiscato-alla-mafia-diviene-casa-della-salute-il-ministro-lamorgese-a-carmiano-per-la-consegna-dellimmobile-a-lilt-e-avis\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00a0di Carmen Leo\u00a0\u00a0______\u201cQuesto luogo, dove un tempo regnava l\u2019illegalit\u00e0, sar\u00e0 da domani dedicato alle necessit\u00e0 delle persone fragili e voi sarete coloro i quali potranno offrire i servizi necessari a chi ne ha pi\u00f9 bisogno, in uno spazio fisico completamente riqualificato. La nostra presenza qui oggi in rappresentanza dello Stato che vigila attentamente a che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":189402,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/189396"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=189396"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/189396\/revisions"}],"predecessor-version":[{"id":189415,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/189396\/revisions\/189415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/189402"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=189396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=189396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=189396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}