{"id":189426,"date":"2021-10-10T13:47:41","date_gmt":"2021-10-10T11:47:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=189426"},"modified":"2021-10-10T19:30:40","modified_gmt":"2021-10-10T17:30:40","slug":"giovane-presunto-spacciatore-finisce-ai-domiciliari","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/10\/10\/giovane-presunto-spacciatore-finisce-ai-domiciliari\/","title":{"rendered":"GIOVANE PRESUNTO SPACCIATORE FINISCE AI DOMICILIARI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-189427\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/10\/ARRESTO-TRICASE.jpg\" alt=\"\" width=\"960\" height=\"445\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/10\/ARRESTO-TRICASE.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/10\/ARRESTO-TRICASE-300x139.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/10\/ARRESTO-TRICASE-768x356.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/10\/ARRESTO-TRICASE-315x145.jpg 315w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>(m.a)______Un giovane di 22 anni di Tricase, del quale non sono state rese note le generalit\u00e0, si trova da ieri agli arresti domiciliari, come disposto dal pm di turno presso la Procura della Repubblica di Lecce, dopo che i Carabinieri del Comando Stazione di Gagliano del Capo,\u00a0 nel corso di una perquisizione, lo hanno trovato in possesso, in totale, divisi in diverse confezioni, di circa otto grammi di cocaina\u00a0 e sessantasette di hashish, oltre a materiali utili al confezionamento delle dosi\u00a0(nella foto).. L&#8217;accusa \u00e8 appunto di detenzione ai fini di spaccio di sostanze stupefacenti.<\/p>\n<p>Il giovane dovr\u00e0 inoltre rispondere del possesso di una pistola scacciacani e di diversi proiettili, trovati durante la perquisizione in casa sua insieme alla droga.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/10\/10\/giovane-presunto-spacciatore-finisce-ai-domiciliari\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/10\/10\/giovane-presunto-spacciatore-finisce-ai-domiciliari\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(m.a)______Un giovane di 22 anni di Tricase, del quale non sono state rese note le generalit\u00e0, si trova da ieri agli arresti domiciliari, come disposto dal pm di turno presso la Procura della Repubblica di Lecce, dopo che i Carabinieri del Comando Stazione di Gagliano del Capo,\u00a0 nel corso di una perquisizione, lo hanno trovato [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":189427,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/189426"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=189426"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/189426\/revisions"}],"predecessor-version":[{"id":189434,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/189426\/revisions\/189434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/189427"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=189426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=189426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=189426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}