{"id":19114,"date":"2013-07-27T14:54:37","date_gmt":"2013-07-27T14:54:37","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19114"},"modified":"2013-07-27T14:54:37","modified_gmt":"2013-07-27T14:54:37","slug":"me-ne-vado-a-passeggio-arrestato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/27\/me-ne-vado-a-passeggio-arrestato\/","title":{"rendered":"&#8220;ME NE VADO A PASSEGGIO&#8221; ARRESTATO"},"content":{"rendered":"<p>Ieri sera, a Salice Salentino, i Carabinieri della Stazione di Guagnano, coadiuvati dai colleghi del posto, hanno arrestato, in flagranza di reato, Massimiliano Perrone quarantunenne di Guagnano, gi\u00e0 noto.<\/p>\n<p>Il provvedimento restrittivo pre-cautelare \u00e8 stato adottato perch\u00e9 l\u2019uomo \u00e8 ritenuto responsabile della violazione dell\u2019obbligo di soggiorno cui \u00e8 sottoposto in quanto sorvegliato speciale di pubblica sicurezza. Lo stesso, infatti, \u00e8 stato sorpreso in Salice Salentino, comune diverso da Guagnano, quello in cui \u00e8 obbligato\u00a0<em>soggiornare<\/em>.<\/p>\n<p>Completate le formalit\u00e0 di rito, Perrone \u00e8 stato accompagnato in carcere a disposizione dell\u2019Autorit\u00e0 Giudiziaria.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/27\/me-ne-vado-a-passeggio-arrestato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/27\/me-ne-vado-a-passeggio-arrestato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Ieri sera, a Salice Salentino, i Carabinieri della Stazione di Guagnano, coadiuvati dai colleghi del posto, hanno arrestato, in flagranza di reato, Massimiliano Perrone quarantunenne di Guagnano, gi\u00e0 noto. Il provvedimento restrittivo pre-cautelare \u00e8 stato adottato perch\u00e9 l\u2019uomo \u00e8 ritenuto responsabile della violazione dell\u2019obbligo di soggiorno cui \u00e8 sottoposto in quanto sorvegliato speciale di pubblica [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19114"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19114"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19114\/revisions"}],"predecessor-version":[{"id":19115,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19114\/revisions\/19115"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}