{"id":191192,"date":"2021-11-17T10:13:49","date_gmt":"2021-11-17T09:13:49","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=191192"},"modified":"2021-11-17T10:17:57","modified_gmt":"2021-11-17T09:17:57","slug":"un-richiamo-a-non-abbandoinare-o-peggio-bruciare-i-rifiuti-in-campagna-arriva-dalle-guardie-ecologiche-del-rauccio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/17\/un-richiamo-a-non-abbandoinare-o-peggio-bruciare-i-rifiuti-in-campagna-arriva-dalle-guardie-ecologiche-del-rauccio\/","title":{"rendered":"UN FORTE RICHIAMO A NON ABBANDONARE, O, PEGGIO, BRUCIARE I RIFIUTI IN CAMPAGNA ARRIVA DALLE GUARDIE ECOLOGICHE DEL PARCO DEL RAUCCIO. GUARDATE QUA&#8230;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-191193\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-16-at-13.40.34.jpeg\" alt=\"\" width=\"2048\" height=\"1539\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-16-at-13.40.34.jpeg 2048w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-16-at-13.40.34-300x225.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-16-at-13.40.34-1024x770.jpeg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-16-at-13.40.34-768x577.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-16-at-13.40.34-1536x1154.jpeg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-16-at-13.40.34-400x300.jpeg 400w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>Riceviamo e volentieri pubblichiamo. Primula Meo, per conto delle Guardie Ecologiche Endas, ci manda il seguente comunicato\u00a0______<\/p>\n<p>Parco di Rauccio. Non si placa il fenomeno dell\u2019abbandono di rifiuti<\/p>\n<p>Rifiuti di ogni genere continuano ad \u201carredare\u201d strade e campagne del Parco Naturale Regionale \u201cBosco e Paludi di Rauccio\u201d. Questo \u00e8 lo scenario che, negli ultimi giorni, si sta presentando dinanzi agli occhi delle GEV ENDAS durante i loro servizi di vigilanza ambientale ma, purtroppo, la continua attivit\u00e0 di controllo da parte delle Guardie Ecologiche e le azioni di contrasto e bonifica messe in atto dagli Uffici Parco e Ambiente sembrano non essere sufficienti a frenare tali gesti di incivilt\u00e0.<\/p>\n<p>Il fenomeno non pu\u00f2 pi\u00f9 essere ignorato: vengono abbandonati rifiuti ovunque e qualcuno osa anche bruciarli liberando diossina nell&#8217;aria; inoltre, non dimentichiamo che con l&#8217;abbandono di rifiuti si rischia l&#8217;inquinamento delle falde acquifere e la contaminazione del terreno con il conseguente pericolo per la salute umana oltre all\u2019aggravio di spese per lo smaltimento che ricadono su tutta la comunit\u00e0.<\/p>\n<p>Quello dell\u2019abbandono dei rifiuti \u00e8 un problema che riguarda tutti ed \u00e8 necessario che tutti facciano la loro parte: l\u2019Amministrazione ha gi\u00e0 in programma l\u2019installazione di video camere che immortaleranno i colpevoli, le GEV intensificheranno i controlli e i cittadini potranno segnalare eventuali illeciti, perch\u00e9 solo condividendo le azioni di contrasto, prevenzione e diffusione di una corretta cultura ambientale si potr\u00e0 ridare dignit\u00e0 ad un territorio martoriato e deturpato da troppo tempo e da scriteriati gesti di tanti irresponsabili.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/17\/un-richiamo-a-non-abbandoinare-o-peggio-bruciare-i-rifiuti-in-campagna-arriva-dalle-guardie-ecologiche-del-rauccio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/17\/un-richiamo-a-non-abbandoinare-o-peggio-bruciare-i-rifiuti-in-campagna-arriva-dalle-guardie-ecologiche-del-rauccio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Primula Meo, per conto delle Guardie Ecologiche Endas, ci manda il seguente comunicato\u00a0______ Parco di Rauccio. Non si placa il fenomeno dell\u2019abbandono di rifiuti Rifiuti di ogni genere continuano ad \u201carredare\u201d strade e campagne del Parco Naturale Regionale \u201cBosco e Paludi di Rauccio\u201d. Questo \u00e8 lo scenario che, negli ultimi giorni, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":191193,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/191192"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=191192"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/191192\/revisions"}],"predecessor-version":[{"id":191198,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/191192\/revisions\/191198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/191193"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=191192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=191192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=191192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}