{"id":191489,"date":"2021-11-23T14:04:37","date_gmt":"2021-11-23T13:04:37","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=191489"},"modified":"2021-11-23T14:05:34","modified_gmt":"2021-11-23T13:05:34","slug":"diritto-di-replica-avip-sulla-concessione-comunale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/23\/diritto-di-replica-avip-sulla-concessione-comunale\/","title":{"rendered":"DIRITTO DI REPLICA \/ AVIP SULLA CONCESSIONE COMUNALE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-191490\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/11\/IMG-20211122-WA0007.jpg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/11\/IMG-20211122-WA0007.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/11\/IMG-20211122-WA0007-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/11\/IMG-20211122-WA0007-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>In relazione al nostro articolo &#8216;IL CONSIGLIERE COMUNALE GIORGIO PALA \u201cinorridito\u201d PER QUELLO CHE HA SCOPERTO SULLA GESTIONE DELLA PUBBLICITA\u2019 STRADALE DEL COMUNE DI LECCE&#8217; dell&#8217; 11 novembre scorso, da Torino l&#8217;avvocato Francesco Fusco, per conto della AVIP ITALIA s.r.l. ci scrive quanto segue, che doverosamente pubblichiamo per loro diritto di replica______<\/p>\n<p>&nbsp;<\/p>\n<p>oggetto: AVIP ITALIA \/ CITTA\u2019 DI LECCE<\/p>\n<p>&nbsp;<\/p>\n<p>La AVIP ITALIA S.r.l. mi ha incaricato di tutelare i suoi diritti e interessi nel rapporto in oggetto. Al fine la mia assistita mi ha esposto di essere venuta a conoscenza di un articolo apparso sulla Vostra testata di informazione avente a oggetto le dichiarazioni rese dal Consigliere di opposizione della Citt\u00e0 di Lecce sig. Giorgio Pala, rispetto alla quale si riserva di tutelare i suoi diritti, per significare quanto segue.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019articolo ha destato un certo stupore, soprattutto in considerazione del fatto che con lo stesso pare attuarsi una lesione dell\u2019immagine commerciale della mia assistita, senza che la stessa sia stata contattata preventivamente per esprimersi sui fantasiosi dati riportati.<\/p>\n<p>&nbsp;<\/p>\n<p>La AVIP ITALIA S.r.l. opera nel territorio comunale in forza di regolare convenzione e non merita che se ne metta in dubbio l\u2019affidabilit\u00e0.<\/p>\n<p>In forza della convenzione la mia assistita ha fornito, a costo ZERO per l\u2019Amministrazione, impianti di arredo urbano quali pensiline, paline autobus e transenne parapedonali che al termine della convenzione rimarranno di propriet\u00e0 del Comune stesso.<\/p>\n<p>Si aggiungano gli oneri tributari e la gestione della manutenzione degli impianti di arredo urbano. Trattasi di investimento che supera gli Euro 200.000,00.<\/p>\n<p>E\u2019 poi inverosimile che si possa anche solo pensare che uno spazio pubblicitario nel centro di Lecce possa essere rinvenuto a circa 1.000,00 euro al mese. Trattasi di dato che non trova alcuna evidenza.<\/p>\n<p>&nbsp;<\/p>\n<p>Per quanto poi concerne la sostituzione di alcune delle transenne, la stessa \u00e8 stata determinata non gi\u00e0 dalla mancanza si manutenzione da parte di AVIP ITALIA S.r.l. (regolarmente fornite) bens\u00ec \u00e8 la conseguenza di un intervento urbanistico di pi\u00f9 ampio raggio unilateralmente voluto ed eseguito dall\u2019Amministrazione Comunale, all\u2019insaputa di AVIP ITALIA, che prescinde dalla convenzione in essere con la stessa.<\/p>\n<p>&nbsp;<\/p>\n<p>La AVIP ITALIA S.r.l. si \u00e8 sempre messa a disposizione dell\u2019Amministrazione per risolvere ogni problema del Comune di Lecce, nonostante gli interlocutori siano mutati negli anni.<\/p>\n<p>&nbsp;<\/p>\n<p>La mia assistita ha sempre operato con assoluto spirito di collaborazione, buona fede e diligenza contrattuale. Per tale ragione la AVIP ITALIA S.r.l. non pu\u00f2 accettare che se ne metta in dubbio la correttezza e seriet\u00e0 professionale.<\/p>\n<p>&nbsp;<\/p>\n<p>La mia assistita, mio tramite, invita quindi codesta redazione a rettificare in termini consoni l\u2019articolo e a desistere dal diffondere ulteriori note, prive di verifica, dal contenuto lesivo dell\u2019immagine della AVIP ITALIA S.r.l., precisando che in difetto sar\u00e0 cura della stessa tutelare i suoi diritti e interessi innanzi alle competenti sedi giudiziarie, con ogni pi\u00f9 ampia richiesta.<\/p>\n<p>Distinti saluti<\/p>\n<p>Avv. Francesco FUSCO<\/p>\n<p>AVIP ITALIA S.r.l.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/23\/diritto-di-replica-avip-sulla-concessione-comunale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/23\/diritto-di-replica-avip-sulla-concessione-comunale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>In relazione al nostro articolo &#8216;IL CONSIGLIERE COMUNALE GIORGIO PALA \u201cinorridito\u201d PER QUELLO CHE HA SCOPERTO SULLA GESTIONE DELLA PUBBLICITA\u2019 STRADALE DEL COMUNE DI LECCE&#8217; dell&#8217; 11 novembre scorso, da Torino l&#8217;avvocato Francesco Fusco, per conto della AVIP ITALIA s.r.l. ci scrive quanto segue, che doverosamente pubblichiamo per loro diritto di replica______ &nbsp; oggetto: AVIP [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":191490,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/191489"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=191489"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/191489\/revisions"}],"predecessor-version":[{"id":191492,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/191489\/revisions\/191492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/191490"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=191489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=191489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=191489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}